{"id":651005,"date":"2025-04-16T19:34:00","date_gmt":"2025-04-16T17:34:00","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/die-atemberaubendsten-mittelalterlichen-heiligen-ruinen-von-budapest-fotos\/"},"modified":"2025-05-19T20:30:34","modified_gmt":"2025-05-19T18:30:34","slug":"die-atemberaubendsten-mittelalterlichen-heiligen-ruinen-von-budapest-fotos","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/die-atemberaubendsten-mittelalterlichen-heiligen-ruinen-von-budapest-fotos\/","title":{"rendered":"Die atemberaubendsten mittelalterlichen heiligen Ruinen von Budapest \u2013 FOTOS"},"content":{"rendered":"<p><strong>Wir besuchten mehrere noch bestehende heilige St\u00e4tten im heutigen Budapest, die weiterhin die Gr\u00f6\u00dfe einer einst zutiefst christlichen Welt ehren. Diese mittelalterlichen Kirchen, Kapellen und Kl\u00f6ster fesseln nicht, weil sie wieder aufgebaut oder neu erfunden wurden, sondern weil ihre br\u00f6ckelnde Einfachheit nach wie vor atemberaubend ist Einige sind in ruhigen Ecken versteckt, da ihre Umgebung bekannt und beliebt geworden ist. Hier sind ein paar Highlights.<\/strong><\/p>\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1066\" height=\"800\" src=\"https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2025\/04\/Margaret-Island-Franciscan-Monastery.jpg\" alt=\"Franziskanerkloster Margaret Island\" class=\"wp-image-651535\" srcset=\"https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2025\/04\/Margaret-Island-Franciscan-Monastery.jpg 1066w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2025\/04\/Margaret-Island-Franciscan-Monastery-768x576.jpg 768w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2025\/04\/Margaret-Island-Franciscan-Monastery-267x200.jpg 267w\" sizes=\"auto, (max-width: 1066px) 100vw, 1066px\"><figcaption class=\"wp-element-caption\">Das Franziskanerkloster auf der Margareteninsel, Foto: J\u00e1cint Mayer\/HelloMagyar<\/figcaption><\/figure>\n<h2 class=\"wp-block-heading\">Heilige R\u00e4ume der Budaer Burg<\/h2>\n<h3 class=\"wp-block-heading\">Kapelle des K\u00f6nigspalastes<\/h3>\n<p>Die erste Kapelle der <a href=\"https:\/\/varlexikon.hu\/budavar\" target=\"_blank\" rel=\"noopener\">Burg Buda<\/a> Errichtet wurde im 14. Jahrhundert w\u00e4hrend der Herrschaft K\u00f6nig Ludwigs des Gro\u00dfen, unter K\u00f6nig Sigismund wurde Anfang der 1400 er Jahre der alte Anjou-Palast umfassend umgebaut, an der Stelle der ehemaligen Kapelle eine zweist\u00f6ckige gotische Kirche errichtet, die Oberkirche wurde 1686 bei der R\u00fcckeroberung Budas zerst\u00f6rt, der untere Teil wurde 1963 rekonstruiert und 1990 neu geweiht, heute ist sie innerhalb der untergebracht <a href=\"https:\/\/btm.hu\/\" target=\"_blank\" rel=\"noopener\">Budapester Geschichtsmuseum<\/a>.<\/p>\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1065\" height=\"800\" src=\"https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2025\/04\/Royal-Chapel-14th-Century.jpg\" alt=\"K\u00f6nigliche Kapelle 14. Jahrhundert\" class=\"wp-image-651536\" srcset=\"https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2025\/04\/Royal-Chapel-14th-Century.jpg 1065w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2025\/04\/Royal-Chapel-14th-Century-768x577.jpg 768w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2025\/04\/Royal-Chapel-14th-Century-266x200.jpg 266w\" sizes=\"auto, (max-width: 1065px) 100vw, 1065px\"><figcaption class=\"wp-element-caption\">K\u00f6nigliche Kapelle 14. Jahrhundert, Foto: J\u00e1cint Mayer\/HelloMagyar<\/figcaption><\/figure>\n<h3 class=\"wp-block-heading\">Dominikanerkloster im Hilton Courtyard<\/h3>\n<p>Der Sockel der dem Heiligen Nikolaus geweihten Dominikanerkirche und des Klosters, der sich im Budaer Schloss befindet, begann als quadratische Kapelle, die 1254 erweitert wurde. Damals hielt der Orden seine h\u00f6chste Versammlung ab, die&nbsp;<em>Capitulum generale<\/em>, das auch seine ungarischen Operationen \u00fcberwachte.<\/p>\n<p>Das Kloster beherbergte die regionale Hochschule des Ordens, der noch sichtbare Sankt-Nikolaus-Turm entstand im fr\u00fchen 15. Jahrhundert, bei der Belagerung von Buda 1530 wurde das Kloster besch\u00e4digt und schlie\u00dflich aufgegeben, die Ruinen blieben w\u00e4hrend der osmanischen Besatzung erhalten, wurden aber vor der R\u00fcckeroberung Budas abgebaut, wobei ihre Fundamente und Keller zugesch\u00fcttet wurden, heute liegen die mittelalterlichen Ruinen unter dem Hilton Hotel, das aufgrund des starken Fu\u00dfg\u00e4ngerverkehrs nur noch selten Besuchern den Zugang erm\u00f6glicht.<\/p>\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" src=\"https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2025\/04\/Dominican-Sanctuary-13th-Century-Parliament.jpg\" alt=\"Parlament des Dominikanischen Heiligtums aus dem 13. Jahrhundert\" class=\"wp-image-651537\"><figcaption class=\"wp-element-caption\">Das Dominikanerheiligtum (13. Jahrhundert) und das Parlament, Foto: J\u00e1cint Mayer\/HelloMagyar<\/figcaption><\/figure>\n<h3 class=\"wp-block-heading\">Kirche Maria Magdalena<\/h3>\n<p>Im n\u00f6rdlichen Teil der Burg Buda gelegen, ist die Kirche Maria Magdalena eine der \u00e4ltesten Kirchen der Gegend, die im gotischen Stil w\u00e4hrend des 13. Jahrhunderts erbaut wurde, um 1400 zu einem dreischiffigen Bauwerk erweitert wurde, bei der Belagerung 194445 schwer besch\u00e4digt, durch Bomben der Turm zerbrach und zum teilweisen Einsturz f\u00fchrte Obwohl er h\u00e4tte restauriert werden k\u00f6nnen, f\u00fchrten politische Entscheidungen zu seinem Abbau, so dass nur teilweise Grundmauern und der Turm \u00fcbrig blieben Er steht heute auf dem Kapisztr\u00e1n-Platz, in der N\u00e4he des Nationalarchivs von Ungarn.<\/p>\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1267\" height=\"800\" src=\"https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2025\/04\/Mary-Magdalene-Church.jpg\" alt=\"Maria-Magdalena-Kirche\" class=\"wp-image-651538\" srcset=\"https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2025\/04\/Mary-Magdalene-Church.jpg 1267w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2025\/04\/Mary-Magdalene-Church-768x485.jpg 768w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2025\/04\/Mary-Magdalene-Church-282x178.jpg 282w\" sizes=\"auto, (max-width: 1267px) 100vw, 1267px\"><figcaption class=\"wp-element-caption\">Maria-Magdalena-Kirche<\/figcaption><\/figure>\n<h1 class=\"wp-block-heading\">Margareteninsel<\/h1>\n<h3 class=\"wp-block-heading\">Dominikanisches Nonnenkloster<\/h3>\n<p>Der der Jungfrau Maria geweihte Konvent war im Mittelalter die prominenteste und wohlhabendste religi\u00f6se Institution der Insel, er wurde von K\u00f6nig B\u00e9la IV. zu Ehren der Jungfrau Maria gegr\u00fcndet und ist stark mit seiner dort lebenden Tochter, der Heiligen Margarete, verbunden, dem Konvent schlossen sich auch mehrere andere Adlige und Prinzessinnen an, die f\u00fcr den Verkehr gesperrt sind, bilden die Ruinen einen friedlichen und gesch\u00e4tzten Teil der Insellandschaft.<\/p>\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1066\" height=\"800\" src=\"https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2025\/04\/Nuns-Church-from-13th-Century.jpg\" alt=\"Nonnenkirche aus dem 13. Jahrhundert\" class=\"wp-image-651539\" srcset=\"https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2025\/04\/Nuns-Church-from-13th-Century.jpg 1066w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2025\/04\/Nuns-Church-from-13th-Century-768x576.jpg 768w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2025\/04\/Nuns-Church-from-13th-Century-267x200.jpg 267w\" sizes=\"auto, (max-width: 1066px) 100vw, 1066px\"><figcaption class=\"wp-element-caption\">Die Nonnenkirche aus dem 13. Jahrhundert, Foto: J\u00e1cint Mayer\/HelloMagyar<\/figcaption><\/figure>\n<h3 class=\"wp-block-heading\">Franziskanerkloster<\/h3>\n<p>Die beeindruckenden Ruinen dieses Klosters, unweit der Dominikanerst\u00e4tte, spiegeln die Anmut der gotischen Architektur des 13. Jahrhunderts wider, wie andere religi\u00f6se Gruppen verlie\u00dfen die Franziskaner w\u00e4hrend der osmanischen \u00c4ra, obwohl ihre Kirchenmauern noch standen, nachdem Buda 1686 zur\u00fcckerobert wurde, im Gegensatz zu den Pr\u00e4monstratensern wurde ihr Kloster hier nicht wiederhergestellt, sie bauten im 18. Jahrhundert einen in Buda und Pest.<\/p>\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1066\" height=\"800\" src=\"https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2025\/04\/Franciscans-Carved-Window-13th-Century.jpg\" alt=\"Franziskaner geschnitztes Fenster aus dem 13. Jahrhundert\" class=\"wp-image-651540\" srcset=\"https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2025\/04\/Franciscans-Carved-Window-13th-Century.jpg 1066w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2025\/04\/Franciscans-Carved-Window-13th-Century-768x576.jpg 768w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2025\/04\/Franciscans-Carved-Window-13th-Century-267x200.jpg 267w\" sizes=\"auto, (max-width: 1066px) 100vw, 1066px\"><figcaption class=\"wp-element-caption\">Das geschnitzte Fenster der Franziskaner (13. Jahrhundert), Foto: J\u00e1cint Mayer\/HelloMagyar<\/figcaption><\/figure>\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1066\" height=\"800\" src=\"https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2025\/04\/Premonstratensian-Church.jpg\" alt=\"Pr\u00e4monstratenserkirche\" class=\"wp-image-651541\" srcset=\"https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2025\/04\/Premonstratensian-Church.jpg 1066w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2025\/04\/Premonstratensian-Church-768x576.jpg 768w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2025\/04\/Premonstratensian-Church-267x200.jpg 267w\" sizes=\"auto, (max-width: 1066px) 100vw, 1066px\"><figcaption class=\"wp-element-caption\">Die Pr\u00e4monstratenserkirche, Foto: J\u00e1cint Mayer\/HelloMagyar<\/figcaption><\/figure>\n<h2 class=\"wp-block-heading\">Heilige St\u00e4tten in den W\u00e4ldern des 2. Bezirks<\/h2>\n<h3 class=\"wp-block-heading\">Paulinerkloster Budaszentl Budrinc<\/h3>\n<p>Diese Anlage entstand um die Wende vom 13. zum 14. Jahrhundert im Sattel zwischen J\u00e1nos-H\u00fcgel und H\u00e1rs-H\u00fcgel, am Ostfl\u00fcgel war eine einschiffige Kirche und n\u00f6rdlich ein Kreuzgang von 10 x 15 Metern mit einem 2 Meter breiten Gang angebaut, an den sich eine kleine Priorkapelle anschloss, das Kloster beherbergte einst die mumifizierten Reliquien des Heiligen Paulus des Einsiedlers, denen viele Wunderheilungen zugeschrieben werden. W\u00e4hrend der T\u00fcrkenzeit zerst\u00f6rt, sind seine bedeutenden Grundmauern heute im Wald von Sz\u00e9pjuh\u00e1sze verborgen. Das Kirchenschiff bleibt ein beliebter Ort f\u00fcr Touristen und Pilger gleicherma\u00dfen.<\/p>\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"714\" src=\"https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2025\/04\/Budaszentlrinc-13th-14th-Century.jpg\" alt=\"Budaszentl rinc 13. 14. Jahrhundert\" class=\"wp-image-651542\" srcset=\"https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2025\/04\/Budaszentlrinc-13th-14th-Century.jpg 1280w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2025\/04\/Budaszentlrinc-13th-14th-Century-768x428.jpg 768w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2025\/04\/Budaszentlrinc-13th-14th-Century-282x157.jpg 282w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\"><figcaption class=\"wp-element-caption\">Budaszentl,rinc, Foto: J\u00e1cint Mayer\/HelloMagyar<\/figcaption><\/figure>\n<h3 class=\"wp-block-heading\">Gercse<\/h3>\n<p>Einst ein Dorf, heute Teil des Budapester Bezirks II bei Pesthidegk\u00fat, beherbergt Gercse eine romanische Kirche mit Mauern aus dem 12. 13. Jahrhundert, ihre hufeisenf\u00f6rmige Apsis ist in Ungarn selten, mit \u00e4hnlichen Entw\u00fcrfen findet man sie vor allem in der heutigen Slowakei, vor 800 Jahren erbaut, hat die Kirche mehrere Br\u00e4nde, einen teilweisen Einsturz, und den Verlust ihres umliegenden Dorfes vor vier Jahrhunderten \u00fcberstanden, heute steht sie allein da und bewacht die ihr anvertraute Stille.<\/p>\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1067\" height=\"800\" src=\"https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2025\/04\/Church-of-Gercse.jpg\" alt=\"Kirche von Gercse\" class=\"wp-image-651543\" srcset=\"https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2025\/04\/Church-of-Gercse.jpg 1067w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2025\/04\/Church-of-Gercse-768x576.jpg 768w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2025\/04\/Church-of-Gercse-267x200.jpg 267w\" sizes=\"auto, (max-width: 1067px) 100vw, 1067px\"><figcaption class=\"wp-element-caption\">Kirche von Gercse, Foto: J\u00e1cint Mayer\/HelloMagyar<\/figcaption><\/figure>\n<h3 class=\"wp-block-heading\">Cella Trichora im Bezirk III<\/h3>\n<p>Aus dem 4. Jahrhundert stammend, die <a href=\"https:\/\/kozepkoritemplom.hu\/obuda-cella-trichora-okereszteny-templom-romja\/\" target=\"_blank\" rel=\"noopener\">Cella Trichora<\/a> Ist eines der \u00e4ltesten bekannten christlichen Bauwerke in Budapest. Die \u00dcberreste der Kapelle zeigen die typische dreilappige Gestaltung der fr\u00fchchristlichen Architektur und symbolisieren die Heilige Dreifaltigkeit: den Vater, den Sohn und den Heiligen Geist. Die Ruinen sind an der Kreuzung der Stra\u00dfen K\u00f6rte und Rakt\u00e1r zug\u00e4nglich.<\/p>\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1066\" height=\"800\" src=\"https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2025\/04\/Early-Christian-Chapel-4th-Century.jpg\" alt=\"Fr\u00fchchristliche Kapelle 4. Jahrhundert\" class=\"wp-image-651544\" srcset=\"https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2025\/04\/Early-Christian-Chapel-4th-Century.jpg 1066w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2025\/04\/Early-Christian-Chapel-4th-Century-768x576.jpg 768w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2025\/04\/Early-Christian-Chapel-4th-Century-267x200.jpg 267w\" sizes=\"auto, (max-width: 1066px) 100vw, 1066px\"><figcaption class=\"wp-element-caption\">Fr\u00fchchristliche Kapelle aus dem 4. Jahrhundert, Foto: J\u00e1cint Mayer\/HelloMagyar<\/figcaption><\/figure>\n<p>Um diesen Artikel auf Ungarisch zu lesen oder zu teilen, klicken Sie hier: <a href=\"https:\/\/hellomagyar.hu\/2025\/04\/16\/budapest-szakralis-hagyateka\/\" target=\"_blank\" rel=\"noopener\">Hell\u00f3 Magyar<\/a><\/p>\n<p><strong>Lesen Sie auch:<\/strong><\/p>\n<ul class=\"wp-block-list\">\n<li>Arch\u00e4ologen entdecken gro\u00dfen, 1.400-1.500 Jahre alten Friedhof auf dem Gel\u00e4nde der BYD-Fabrik in der N\u00e4he von Szeged. Einzelheiten und Fotos <strong><a href=\"https:\/\/dailynewshungary.com\/de\/fotos-archaologen-decken-grosen-1-400-1-500-jahre-alten-friedhof-auf-dem-gelande-der-byd-fabrik-in-der-nahe-von-szeged-auf\/\">HIER<\/a><\/strong><\/li>\n<li>Sensationelle Artefakte <strong><a href=\"https:\/\/dailynewshungary.com\/de\/fotos-sensationelle-artefakte-aus-dem-hauskeller-aus-dem-14-15-jahrhundert-unter-dem-budapester-konigspalast-geborgen\/\">Gesichert <\/a><\/strong>Hauskeller aus dem 14-15. Jahrhundert unter dem Budapester K\u00f6nigspalast<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Wir besuchten mehrere noch bestehende heilige St\u00e4tten im heutigen Budapest, die weiterhin die Gr\u00f6\u00dfe einer einst zutiefst christlichen Welt ehren. Diese mittelalterlichen Kirchen, Kapellen und Kl\u00f6ster fesseln nicht, weil sie wieder aufgebaut oder neu erfunden wurden, sondern weil ihre br\u00f6ckelnde Einfachheit nach wie vor atemberaubend ist Einige sind in ruhigen Ecken versteckt, da ihre Umgebung [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":651006,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"yes","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[3552],"tags":[1306,1196,1124,1342,1079,1126,1076],"class_list":["post-651005","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-spezialungarisch","tag-archaologie","tag-fotogalerie","tag-hellomagyar","tag-hungrige-nachrichten","tag-tourismus","tag-ungarische-geschichte","tag-ungarn"],"blocksy_meta":[],"acf":[],"author_username":"ugyelet","telegram_post":"","public_post_metadata":{"breaking_news":"no","important":"no","csempe":"no","center_tile":"no","disable_thumbnail":"no","target_lang":"","_featured_image_style":"hidden","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"Wir besuchten mehrere noch bestehende heilige St\u00e4tten im heutigen Budapest, die weiterhin die Gr\u00f6\u00dfe einer einst zutiefst christlichen Welt w\u00fcrdigen.","focus_keyword":"Heilig","canonical_url":"","robots":"","primary_category":"1412","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"79","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/651005","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=651005"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/651005\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/651006"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=651005"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=651005"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=651005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}