{"id":651577,"date":"2025-03-31T19:04:00","date_gmt":"2025-03-31T17:04:00","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/von-amerika-nach-ungarn-die-reise-der-seltenen-fotografie-von-lajos-kossuth\/"},"modified":"2025-03-31T19:04:00","modified_gmt":"2025-03-31T17:04:00","slug":"von-amerika-nach-ungarn-die-reise-der-seltenen-fotografie-von-lajos-kossuth","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/von-amerika-nach-ungarn-die-reise-der-seltenen-fotografie-von-lajos-kossuth\/","title":{"rendered":"Von Amerika nach Ungarn: Die Reise der seltenen Fotografie von Lajos Kossuth"},"content":{"rendered":"<p><strong>Lajos Kossuth, eine der einflussreichsten Figuren der ungarischen Revolution und des Unabh\u00e4ngigkeitskrieges von 1848-49, hat nur wenige erhaltene Darstellungen, obwohl seine Stimme f\u00fcr die Nachwelt erhalten geblieben ist, ist die visuelle Dokumentation begrenzt.<\/strong><\/p>\n<p>Zu seinen wertvollsten und \u00e4ltesten erhaltenen Fotografien geh\u00f6rt eine Daguerreotypie, die aus den Vereinigten Staaten nach Ungarn zur\u00fcckgebracht wurde, so die <a href=\"https:\/\/www.youtube.com\/watch?v=Ark_vXVD86c\" data-type=\"link\" data-id=\"https:\/\/www.youtube.com\/watch?v=Ark_vXVD86c\" target=\"_blank\" rel=\"noopener\">Youtube-Kanal der Ungarischen Nationalbank<\/a>Dieses einzigartige Portr\u00e4t zeigt nicht nur eine ikonische historische Figur, sondern tr\u00e4gt auch den Abdruck einer wichtigen Epoche der Geschichte.<\/p>\n<h2 class=\"wp-block-heading\">Was ist eine Daguerreotypie?<\/h2>\n<p>Eine Daguerreotypie ist eine der fr\u00fchesten Formen der Fotografie, entwickelt in den sp\u00e4ten 1830 er Jahren, das Verfahren verwendet eine versilberte Kupferplatte, um das Bild aufzunehmen, was zu einer hochdetaillierten, aber einzigartigen und nicht reproduzierbaren Fotografie f\u00fchrt Mitte des 19. Jahrhunderts galt diese Technologie als die modernste fotografische Technik, und die damit hergestellten Bilder sind besonders wertvoll.<\/p>\n<p>1852, als Lajos Kossuth in den Vereinigten Staaten weilte, entstand in Boston eine Daguerreotypie von ihm, die Fotografie wurde von Albert Sands Southworth und Josiah Johnson Hawes, einem der renommiertesten Fotografenpaare der Zeit, aufgenommen, das Portr\u00e4t ist von herausragender Bedeutung, da es sich um eine der fr\u00fchesten erhaltenen Fotografien Kossuths handelt, dargestellt wird er mit ernstem Ausdruck und in schwarzer Kleidung, was zum historischen und \u00e4sthetischen Wert des Bildes beitr\u00e4gt.<\/p>\n<figure class=\"wp-block-embed aligncenter is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\">\n<div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"MNB \u00c9rt\u00e9kt\u00e1r - Kossuth Lajos dagerrot\u00edpia portr\u00e9ja\" width=\"1480\" height=\"833\" src=\"https:\/\/www.youtube.com\/embed\/Ark_vXVD86c?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen=\"\"><\/iframe>\n<\/div>\n<\/figure>\n<h2 class=\"wp-block-heading\">Die amerikanische Wahrnehmung von Kossuth<\/h2>\n<p>In den fr\u00fchen 1850 er Jahren erfreute sich Lajos Kossuth in den Vereinigten Staaten enormer Beliebtheit, als er im Dezember 1851 in New York ankam, wurde er im Hafen von Zehntausenden Menschen und 31 Kanonensch\u00fcssen begr\u00fc\u00dft, ein Bef\u00fcrworter der Freiheit, machte gro\u00dfen Eindruck in der amerikanischen \u00d6ffentlichkeit und wurde in vielen St\u00e4dten als Ehrengast empfangen, so die&nbsp;<a href=\"https:\/\/index.hu\/tudomany\/til\/2021\/08\/17\/1848-szabadsagharc-kossuth-lajos-egyesult-allamok-amerikai-utja-orulet\/\" data-type=\"link\" data-id=\"https:\/\/index.hu\/tudomany\/til\/2021\/08\/17\/1848-szabadsagharc-kossuth-lajos-egyesult-allamok-amerikai-utja-orulet\/\" target=\"_blank\" rel=\"noopener\">Index<\/a><em>,<\/em>\u2018Kossuth-H\u00fcte und ungarische Kleidung kamen in Mode, und tausende Kinder erhielten seinen Namen als zweiten Vornamen, obwohl er sich letztlich keine politische Unterst\u00fctzung der US-Regierung sichern konnte, trug sein Besuch zur internationalen Sichtbarkeit der ungarischen Sache bei.<\/p>\n<h2 class=\"wp-block-heading\">Das Erbe der Kossuth-Daguerreotypie<\/h2>\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"676\" src=\"https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2020\/01\/1024px-Kossuth_\u00e9s_t\u00e1bornokai.jpg\" alt=\"Kossuth Lajos Generalgouverneur Ungarische Geschichte\" class=\"wp-image-299141\" srcset=\"https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2020\/01\/1024px-Kossuth_\u00e9s_t\u00e1bornokai.jpg 1024w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2020\/01\/1024px-Kossuth_\u00e9s_t\u00e1bornokai-300x198.jpg 300w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2020\/01\/1024px-Kossuth_\u00e9s_t\u00e1bornokai-768x507.jpg 768w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2020\/01\/1024px-Kossuth_\u00e9s_t\u00e1bornokai-800x528.jpg 800w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"><figcaption class=\"wp-element-caption\">Kossuth und seine Gener\u00e4le<\/figcaption><\/figure>\n<p>Die Daguerreotypie war lange Zeit in Privatsammlungen im Ausland versteckt, sie ruhte jahrzehntelang, bis sie bei einer amerikanischen Auktion wieder auftauchte, bei der Auktion erkannte das Treasury Program der Ungarischen Nationalbank ihre Bedeutung und erwarb das Artefakt, nach dem Erwerb wurde das Foto nach Ungarn gebracht, wo es restauriert und der \u00d6ffentlichkeit ausgestellt wurde Dieser Schritt bedeutete nicht nur, ein wertvolles Kunstwerk nach Hause zu bringen, sondern auch ein wichtiges historisches Erbe zu bewahren.<\/p>\n<p>Die Daguerreotypie von Kossuth nimmt unter den ungarischen historischen Denkm\u00e4lern einen besonderen Platz ein, sie ist nicht nur das Portr\u00e4t eines ber\u00fchmten Staatsmannes sondern auch ein Symbol des ungarischen Kampfes f\u00fcr Freiheit und Unabh\u00e4ngigkeit Das Bild erinnert an eine Zeit, als Kossuth versuchte, die Unabh\u00e4ngigkeit Ungarns auf der internationalen diplomatischen Arena zu sichern.<\/p>\n<p>Die Daguerreotypie von Kossuth ist nicht nur ein historisches Relikt sondern auch ein wichtiger Teil der ungarischen nationalen Identit\u00e4t, ihre Heimkehr und Restaurierung waren ein weiterer Schritt im Prozess der Erhaltung der ungarischen historischen Denkm\u00e4ler Das Portr\u00e4t nimmt heute einen w\u00fcrdigen Platz im ungarischen Kulturerbe ein und bietet k\u00fcnftigen Generationen die M\u00f6glichkeit, etwas \u00fcber die Figur und das Erbe von Lajos Kossuth zu erfahren.<\/p>\n<p><strong>Lesen Sie auch:<\/strong><\/p>\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/dailynewshungary.com\/de\/seltsame-skulptur-des-ungarischen-freiheitskampfers-lajos-kossuth-mit-husarenhalstattoo-in-kuba-wirft-fragen-auf-fotos\/\">Seltsame Skulptur des ungarischen Freiheitsk\u00e4mpfers Lajos Kossuth mit Husarenhalstattoo in Kuba wirft Fragen auf. \u2013 FOTOS<\/a><\/li>\n<li><a href=\"https:\/\/dailynewshungary.com\/de\/ist-das-county-in-den-usa-nach-lajos-kossuth-benannt-ein-schandfleck-fur-die-menschen\/\">Ist das County in den USA nach Lajos Kossuth benannt, ein Schandfleck f\u00fcr die Menschen?<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Lajos Kossuth, eine der einflussreichsten Figuren der ungarischen Revolution und des Unabh\u00e4ngigkeitskrieges von 1848-49, hat nur wenige erhaltene Darstellungen, obwohl seine Stimme f\u00fcr die Nachwelt erhalten geblieben ist, ist die visuelle Dokumentation begrenzt. Zu seinen wertvollsten und \u00e4ltesten erhaltenen Fotografien geh\u00f6rt eine Daguerreotypie, die aus den Vereinigten Staaten nach Ungarn zur\u00fcckgebracht wurde, so die Youtube-Kanal [&hellip;]<\/p>\n","protected":false},"author":80,"featured_media":651578,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"yes","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1151],"tags":[1482,1125,1342,1126,1076,1157,1192],"class_list":["post-651577","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kulturen","tag-fotografie","tag-geschichte","tag-hungrige-nachrichten","tag-ungarische-geschichte","tag-ungarn","tag-vereinigte-staaten","tag-video"],"blocksy_meta":[],"acf":[],"author_username":"nemethmartin","telegram_post":"","public_post_metadata":{"breaking_news":"yes","important":"no","csempe":"yes","center_tile":"no","disable_thumbnail":"no","target_lang":"","_featured_image_style":"hidden","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"","focus_keyword":"Lajos Kossuth","canonical_url":"","robots":"","primary_category":"1151","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"82","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/651577","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/80"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=651577"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/651577\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/651578"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=651577"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=651577"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=651577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}