{"id":659779,"date":"2024-07-17T09:34:32","date_gmt":"2024-07-17T07:34:32","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/ungarischer-ausenminister-wer-uber-frieden-spricht-ist-kein-spion-kein-trojanisches-pferd\/"},"modified":"2024-07-17T09:34:32","modified_gmt":"2024-07-17T07:34:32","slug":"ungarischer-ausenminister-wer-uber-frieden-spricht-ist-kein-spion-kein-trojanisches-pferd","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/ungarischer-ausenminister-wer-uber-frieden-spricht-ist-kein-spion-kein-trojanisches-pferd\/","title":{"rendered":"Ungarischer Au\u00dfenminister: Wer \u00fcber Frieden spricht, ist kein Spion, kein Trojanisches Pferd"},"content":{"rendered":"<p><strong>Ungarn und China sind sich einig, dass die diplomatischen Bem\u00fchungen, die auf die Schaffung von Frieden abzielen, vervielfacht werden m\u00fcssen, sagte Au\u00dfenminister P\u00e9ter Szijj\u00e1rt\u00f3 am Dienstag in New York nach einem Telefonat mit Wang Yi, seinem chinesischen Amtskollegen, und f\u00fcgte hinzu, dass die UN dabei eine besondere Verantwortung trage Angriffe kriegsbef\u00fcrwortender europ\u00e4ischer Politiker w\u00fcrden die ungarische Regierung weiter ermutigen, ihre Friedensmission fortzusetzen, weil Ungarn Frieden statt Krieg wolle und nur Frieden Europa wieder gro\u00df machen k\u00f6nne, sagte Szijj\u00e1rt\u00f3r in New York.<\/strong><\/p>\n<h2>Die UNO kann sich nicht verstecken<\/h2>\n<p>\u201cDie UNO muss sich endlich zu Wort melden und endlich eine Rolle \u00fcbernehmen,\u201d <a href=\"https:\/\/www.facebook.com\/szijjarto.peter.official\" target=\"_blank\" rel=\"noopener\"><strong>Szijj\u00e1rt\u00f3<\/strong> <\/a>Sagte, so eine Erkl\u00e4rung des Ministeriums. \u201c<a href=\"https:\/\/www.facebook.com\/szijjarto.peter.official\/posts\/pfbid021xymMz4aSd5qcbqkK1QkmvJZism3qVN3c5ejBGrHetNUNfhnby73Yq4z3GR2GmtMl?__cft__[0]=AZXgKaMVdY6imkSMuU5xGpSYwNdq3RKcrpxL_iifdaQ8_VrpbhZ_DQbGNqQ8GYvi3Bu2Wwv7P8Il75pz72PQmgcGNqllR5NI01vhaO-Hfbc9GTPyiec516O_QAgdQallPtCLNXM9-okSAo81TGp59joSdZg-OI67baq1SmgceqUiGeIOTV9Kg8ztNGsh1zIW8Jm7sRVOg-tkAJ6P2B81kp-2cJOSVyAaojC-pF3wv1dKYg&amp;__tn__=%2CO%2CP-R\" target=\"_blank\" rel=\"noopener\"><strong>Die UNO kann sich nicht verstecken<\/strong><\/a> In den komfortablen B\u00fcros in New York, muss aber f\u00fcr die Wiederer\u00f6ffnung diplomatischer Kommunikationswege Stellung beziehen\u201d.<\/p>\n<p>Er wies darauf hin, dass die Vereinten Nationen gegr\u00fcndet worden seien, um einen Dialog zwischen den Konfliktparteien zu erm\u00f6glichen.<\/p>\n<p>Szijj\u00e1rt\u00f3 sagte, die ungarische Regierung sei k\u00fcrzlich von \u201callen europ\u00e4ischen Kriegspolitikern\u201d \u201cangegriffen\u201d worden, aber das \u201cwird uns nicht davon abhalten, die Friedensmission fortzusetzen\u201d.<\/p>\n<p><strong>Herr Szijj\u00e1rt\u00f3 telefoniert mit seinem chinesischen Amtskollegen Wang Yi:<\/strong><\/p>\n<p><iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2Fszijjarto.peter.official%2Fposts%2Fpfbid0rXWTvmwGgtow4AmdmLBVjV59VdNJkiEzMLQuXLPHb5uPFsmi9zhSPYcDDE1QwRKPl&amp;show_text=false&amp;width=500\" width=\"500\" height=\"333\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Er sagte, der liberale Mainstream treibe \u201cdie Pro-Kriegspropaganda in der transatlantischen Blase so stark voran\u201d, dass er den Menschen in Europa und Amerika den Eindruck vermittelt habe, dass \u201cdies die Meinung der ganzen Welt ist, wenn sie es nicht ist\u201d.<\/p>\n<h2>Mehrheit will Frieden<\/h2>\n<p>\u201cDie globale Mehrheit will Frieden und versteht \u00fcberhaupt nicht, warum Europa keine Friedensstrategie hat. warum es die amerikanische Strategie kopiert\u201d Szijj\u00e1rt\u00f3 sagte \u201cUnd die globale Mehrheit beobachtet die Bem\u00fchungen der ungarischen Friedensmission mit gro\u00dfer Sympathie, Interesse und Wertsch\u00e4tzung\u201d<\/p>\n<p>Szijj\u00e1rt\u00f3 sagte, er werde seinen russischen Amtskollegen, den UN-Untergeneralsekret\u00e4r f\u00fcr Friedenseins\u00e4tze und den Pr\u00e4sidenten des Internationalen Komitees vom Roten Kreuz, treffen.<\/p>\n<figure id=\"attachment_486579\" aria-describedby=\"caption-attachment-486579\" style=\"width: 600px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-486579\" src=\"https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2022\/04\/Peter-Szijjarto-United-Nations-gas-transit.webp\" alt=\"P\u00e9ter Szijj\u00e1rt\u00f3 Gastransit der Vereinten Nationen\" width=\"600\" height=\"400\" srcset=\"https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2022\/04\/Peter-Szijjarto-United-Nations-gas-transit.webp 2048w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2022\/04\/Peter-Szijjarto-United-Nations-gas-transit-768x512.webp 768w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2022\/04\/Peter-Szijjarto-United-Nations-gas-transit-1536x1023.webp 1536w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2022\/04\/Peter-Szijjarto-United-Nations-gas-transit-350x233.webp 350w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2022\/04\/Peter-Szijjarto-United-Nations-gas-transit-248x165.webp 248w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2022\/04\/Peter-Szijjarto-United-Nations-gas-transit-1030x686.webp 1030w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2022\/04\/Peter-Szijjarto-United-Nations-gas-transit-219x146.webp 219w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2022\/04\/Peter-Szijjarto-United-Nations-gas-transit-50x33.webp 50w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2022\/04\/Peter-Szijjarto-United-Nations-gas-transit-113x75.webp 113w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\"><figcaption id=\"caption-attachment-486579\" class=\"wp-caption-text\">Foto: FB<\/figcaption><\/figure>\n<p>\u201cDieser Krieg, der in der Ukraine stattfindet, hat eine enorme humanit\u00e4re Katastrophe verursacht; das k\u00f6nnen wir Ungarn auch sehen\u201d, sagte er \u201cWir haben mehr als eine Million Fl\u00fcchtlinge aufgenommen, wir sehen die getrennten Familien, wir sehen die erzwungenen, inakzeptablen Wehrpflichtoperationen, die alle Menschenrechte verletzen\u201d<\/p>\n<p>Szijj\u00e1rt\u00f3 warnte vor der Gefahr, dass \u201cdie westliche Welt bei Entscheidungen \u00fcber Waffenlieferungen die Gefahr einer Eskalation ignoriert\u201d.<\/p>\n<p>Unterdessen sagte der Minister, er werde am Dienstag auch Gespr\u00e4che mit F\u00fchrungskr\u00e4ften amerikanischer Unternehmen wie Kyndryl und Johnson and Johnson \u00fcber eine m\u00f6gliche Verst\u00e4rkung ihrer Pr\u00e4senz in Ungarn f\u00fchren.<\/p>\n<h2>Neue Stipendien<\/h2>\n<p>Er sagte, er werde auch Gespr\u00e4che mit seinen bahrainischen, iranischen und kapverdischen Amtskollegen f\u00fchren.<\/p>\n<p>Er sagte, Ungarn und Bahrain w\u00fcrden ein Investitionsschutzabkommen abschlie\u00dfen und sagte, es sei \u201eeine gute Nachricht\u201cdass ein ungarisches Unternehmen beim letzten Formel-Eins-Grand-Prix von Bahrain die M\u00f6glichkeit f\u00fcr bargeldlose Zahlungen geboten habe.<\/p>\n<p>Ungarn und Kap Verde werden unterdessen eine Vereinbarung unterzeichnen, wonach Ungarn weiterhin jedes Jahr Stipendien f\u00fcr 20 Universit\u00e4tsstudenten aus Kap Verde anbieten wird, sagte erAu\u00dferdem werden ungarische Unternehmen im Rahmen einer 42-Millionen-Euro-Bindung-Hilfe-Regelung Investitionen im Hinblick auf eine Verbesserung der Wasserversorgung durchf\u00fchrenf\u00fcgte er hinzu.<\/p>\n<p>Szijj\u00e1rt\u00f3 sagte, er werde sich auch mit seinem treffen<a href=\"https:\/\/www.facebook.com\/szijjarto.peter.official\/posts\/pfbid026fTZTe8GjAE88R6EteifWY14xPGLt2Z4jigzf4wdgPksT6ZrMDkXE2AZesbdZ5DVl?__cft__[0]=AZX6Jp50InEXiETBGUT_S8qwZ0EbrcAM8BNv4NNRkBhO7SEoOjHikRuA-fEqie2_dFVmgRXPa5mDB56C6h1GhH0HGn_Xui2olCYl--kBlX_LGqhciXiY6VLHXm7JQVhwnoi_odvUD1YsBgLMjIfo4PQYH8NrcU9pIKkYGe363EG7KyZSuKdRdDRFT4KGYScc6I02Lx1SZSayapmwOR8T-8kzBZ6GCPg4xJ-PVpSN1s1LdQ&amp;__tn__=%2CO%2CP-R\" target=\"_blank\" rel=\"noopener\"><strong> Iranisches Pendant<\/strong><\/a> und sagen Sie ihm, dass Ungarns Interessen in einer m\u00f6glichst schnellen L\u00f6sung der Nahostkrise liegen.<\/p>\n<h2>Szijj\u00e1rt\u00f3: Politische Angriffe ermutigen die weitere Friedensmission der Regierung nur noch mehr<\/h2>\n<p>Angriffe von kriegsbef\u00fcrwortenden europ\u00e4ischen Politikern werden die ungarische Regierung weiter ermutigen, ihre Friedensmission fortzusetzen, weil Ungarn Frieden statt Krieg will und nur Frieden Europa wieder gro\u00df machen kann, sagte Szijj\u00e1rt\u00f3 in New York.<\/p>\n<p>Das Ministerium zitierte Szijj\u00e1rt\u00f3, der in einer offenen Debatte im UN-Sicherheitsrat sagte, Ungarn lebe seit zweieinhalb Jahren im Schatten des Krieges und sei mit den direkten Folgen des Krieges konfrontiert worden, habe mehr als eine Million Fl\u00fcchtlinge aufgenommen und sei damit konfrontiert Kriegsinflation und die Zahlung enorm hoher Energiepreise.<\/p>\n<p>\u201cDer Krieg sieht v\u00f6llig anders aus als der Nachbar im Vergleich zu einem Meer entfernt\u201d, sagte er.<\/p>\n<p>Tausende Menschen starben, ein Land wurde zerst\u00f6rt und es gab langfristige Risiken, wie zum Beispiel die erneute Spaltung der Welt in Bl\u00f6cke. Ungarn wei\u00df, dass wir \u201eda keine Chance auf eine zivilisierte Zusammenarbeit zwischen Ost und West haben, wenn es keine Chance gibt\u201cdran verlieren\u201d, f\u00fcgte er hinzu.<\/p>\n<p>Er sagte, dass er in den letzten zehn Jahren an mehreren Treffen in der EU teilgenommen habe, bei denen die Frage bewaffneter Konflikte und Kriege fernab von Europa er\u00f6rtert worden sei, und dass die europ\u00e4ische Position immer darin bestanden habe, die Parteien des jeweiligen Krieges dazu zu dr\u00e4ngen die Schlachtfeldl\u00f6sung aufzugeben, am Verhandlungstisch zu sitzen und nach einer diplomatischen L\u00f6sung zu suchen.<\/p>\n<h2>Redner \u00fcber Peade sind keine Spione oder trojanischen Pferde<\/h2>\n<p>Wenn nun in Europa ein Krieg im Gange ist, ist nicht nur die Lage v\u00f6llig anders, sondern wenn jemand das Wort \u201eFrieden\u201cund das Wort \u201eVerhandlung\u201d verwendet, wird er sofort stigmatisiert und als \u201eSpion oder trojanisches Pferd\u201d bezeichnet, sagte er.<\/p>\n<p>Szijj\u00e1rt\u00f3 sagte, es sei \u201cein sehr schlechter Ansatz\u201d, dass \u00fcber die Legitimit\u00e4t der Diplomatie debattiert worden sei. Er sagte, Diplomatie spreche nicht nur mit denen, \u201cmit denen man zu 100 Prozent \u00fcbereinstimmt\u201d.<\/p>\n<p>Bei der Diplomatie gehe es darum, mit allen zu sprechen, auch mit denen, mit denen man sich in wichtigen Fragen nicht einig sei.<\/p>\n<p>Die letzten zweieinhalb Jahre h\u00e4tten deutlich bewiesen, dass es keine Schlachtfeldl\u00f6sung f\u00fcr den Krieg in der Ukraine gebe, daher sei es notwendig, die Legitimit\u00e4t der Diplomatie zur\u00fcckzugeben, sagte der Minister.<\/p>\n<p>\u201eEs ist nicht nur inakzeptabel, sondern auch skandal\u00f6s, dass ein Land im 21. Jahrhundert stigmatisiert wird, nur weil es f\u00fcr eine diplomatische L\u00f6sung pl\u00e4diert, nur weil es Kommunikationskan\u00e4le nutzt, um mit denen zu sprechen, mit denen es m\u00f6glicherweise an gemeinsamem Verst\u00e4ndnis mangelt.\u201czu wichtigen Themen\u201d, sagte er.<\/p>\n<h2>Eine \u00dcberpolitisierung der UNO sei \u201cinakzeptabel\u201d<\/h2>\n<p>Die UN seien gegr\u00fcndet worden, um denjenigen, die nicht miteinander einverstanden sind, die in einer feindseligen Beziehung stehen, die miteinander Krieg f\u00fchren, eine Plattform zu bieten, miteinander zu sprechen, f\u00fcgte er hinzu.<\/p>\n<p>Szijj\u00e1rt\u00f3 sagte, die \u00dcberpolitisierung der Vereinten Nationen sei \u201einakzeptabel\u201cund es sei ebenso inakzeptabel, L\u00e4nder daran zu hindern, mit wem sie wollen, zu verhandeln.<\/p>\n<p>Angriffe europ\u00e4ischer Politiker, die eine Kriegsbef\u00fcrworterposition vertraten, w\u00fcrden die ungarische Regierung nur noch mehr ermutigen, ihre Friedensmission fortzusetzen, sagte er.<\/p>\n<p>\u201cWir wollen Frieden statt Krieg Und nur Frieden wird Europa wieder gro\u00df machen\u201d, f\u00fcgte er hinzu.<\/p>\n<p><strong>Lesen Sie auch:<\/strong><\/p>\n<ul>\n<li>Trump <a href=\"https:\/\/dailynewshungary.com\/de\/trump-wahlt-den-senator-von-orban-fan-ohio-zum-vizeprasidenten\/\"><strong>W\u00e4hlt<\/strong> <\/a>Senator von Orb\u00e1n-Fan Ohio als Vizepr\u00e4sident<\/li>\n<li>POLITICO: <a href=\"https:\/\/dailynewshungary.com\/de\/politico-eu-boykottiert-ungarns-ausengipfel\/\"><strong>EU zum Boykott<\/strong> <\/a>Ungarns Au\u00dfengipfel<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Ungarn und China sind sich einig, dass die diplomatischen Bem\u00fchungen, die auf die Schaffung von Frieden abzielen, vervielfacht werden m\u00fcssen, sagte Au\u00dfenminister P\u00e9ter Szijj\u00e1rt\u00f3 am Dienstag in New York nach einem Telefonat mit Wang Yi, seinem chinesischen Amtskollegen, und f\u00fcgte hinzu, dass die UN dabei eine besondere Verantwortung trage Angriffe kriegsbef\u00fcrwortender europ\u00e4ischer Politiker w\u00fcrden die [&hellip;]<\/p>\n","protected":false},"author":50,"featured_media":659780,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1081],"tags":[1169,1162,1084,1102,1076,1638],"class_list":["post-659779","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politik","tag-aussenministerium-von-ungarn","tag-china","tag-krieg-in-der-ukraine","tag-ungarische-regierung","tag-ungarn","tag-vereinigte-nationen"],"blocksy_meta":[],"acf":[],"author_username":"dnh","telegram_post":"","public_post_metadata":{"breaking_news":"yes","important":"no","csempe":"no","center_tile":"no","disable_thumbnail":"no","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"\"Wir wollen Frieden statt Krieg Und nur Frieden wird Europa wieder gro\u00df machen\", stellte der ungarische Au\u00dfenminister in New York klar.","focus_keyword":"Frieden","canonical_url":"","robots":"","primary_category":"1081","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"84","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/659779","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/50"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=659779"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/659779\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/659780"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=659779"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=659779"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=659779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}