{"id":663378,"date":"2024-04-02T14:34:28","date_gmt":"2024-04-02T12:34:28","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/ungarns-botschaft-in-zypern-wird-wiedereroffnet\/"},"modified":"2024-04-02T14:34:28","modified_gmt":"2024-04-02T12:34:28","slug":"ungarns-botschaft-in-zypern-wird-wiedereroffnet","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/ungarns-botschaft-in-zypern-wird-wiedereroffnet\/","title":{"rendered":"Ungarns Botschaft in Zypern wird wiederer\u00f6ffnet"},"content":{"rendered":"<p><strong>Ungarn und Zypern \u201cwerden niemals akzeptieren, dass die Europ\u00e4ische Union bis zu Mitgliedstaaten erster und zweiter Klasse aufgeteilt werden sollte\u201d, sagte Au\u00dfenminister P\u00e9ter Szijj\u00e1rt\u00f3 am Dienstag in Nikosia und f\u00fcgte hinzu, dass die beiden L\u00e4nder \u201csich entschieden gegen die Abschaffung der einstimmigen Entscheidungsfindung\u201d in der EU aussprechen.<\/strong><\/p>\n<p>Auf einer gemeinsam mit seinem zyprischen Amtskollegen Constantinos Kombos abgehaltenen Pressekonferenz sagte Szijj\u00e1rt\u00f3, die Wirtschaft und Sicherheit der Gemeinschaft seien \u201cschlimmer als nach der Coronavirus-Pandemie\u201d, insbesondere im Hinblick auf die abnehmende Wettbewerbsf\u00e4higkeit der EU, den Krieg in der Ukraine und die Gefahr ihrer Eskalation sowie die Schwierigkeiten durch illegale Migration. Er hoffte, dass die bevorstehenden Wahlen zum Europ\u00e4ischen Parlament Ver\u00e4nderungen bringen k\u00f6nnten, \u201cwobei der Block in die richtige Richtung tendiert und das Friedenslager an St\u00e4rke gewinnt\u201d.<\/p>\n<p>Die ungarische Regierung mahnt zum baldigen Frieden, sagte Szijj\u00e1rt\u00f3, r\u00e4umte aber ein, dass ihre Position \u201cnicht im Mainstream ist und nicht von einer Mehrheit unterst\u00fctzt wird\u201d Ungarn sende keine Waffen in die Ukraine und \u201clehne sich Erkl\u00e4rungen bez\u00fcglich der M\u00f6glichkeit der Entsendung westlicher Truppen scharf ab\u201d, sagte er.<\/p>\n<p>Er sagte, dass diejenigen, die \u201edie Position des Friedenslagers f\u00f6rdern, stigmatisiert werden\u201cund \u201ees gibt einen winzigen Raum f\u00fcr einen n\u00fcchternen Dialog\u201d zu diesem Thema gibt, und f\u00fcgte hinzu, dass \u201e\u00e4hnlich, es gab keine Gelegenheit f\u00fcr eine sinnvolle Debatte \u00fcber eine Art Entsch\u00e4digung f\u00fcr Mitgliedstaaten, die ernsthaft betroffen sind.\u201cvon den Sanktionen gegen Russland betroffen\u201d<\/p>\n<p>Bez\u00fcglich der vorgeschlagenen Abschaffung einstimmiger Entscheidungen in der EU sagte Szijj\u00e1rt\u00f3<\/p>\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201cWir werden niemals eine Situation akzeptieren, in der die gro\u00dfen L\u00e4nder Entscheidungen \u00fcber Themen treffen k\u00f6nnten, die auch uns betreffen, und uns die einzige M\u00f6glichkeit lassen, &#8216;Ja, Sir&#8217; zu sagen\u201d<\/p>\n<\/blockquote>\n<p>Die ungarische EU-Pr\u00e4sidentschaft in der zweiten Jahresh\u00e4lfte werde darauf abzielen, \u201ceine weitere Schw\u00e4chung der Gemeinschaft zu stoppen\u201d, sagte er und f\u00fcgte hinzu, dass \u201cein starkes Europa starke Mitglieder erfordert\u201d Die EU brauche \u201cneuen Schwung und Energie, die nur von au\u00dfen kommen k\u00f6nne; die (ungarische) Regierung werde daher die F\u00f6rderung der Integration des Westbalkans ganz oben auf ihrer Agenda haben\u201d, sagte erEr f\u00fcgte jedoch hinzu, dass einigen L\u00e4ndern aus politischen Gr\u00fcnden kein \u201cFast-Track\u201d &#8211; Verfahren gew\u00e4hrt werden d\u00fcrfe; \u201cjeder Kandidat m\u00fcsse nach seinen tats\u00e4chlichen Verdiensten beurteilt werden\u201d Die Westbalkanstaaten h\u00e4tten \u201ceine faire und positive Haltung verdient\u201d, sagte er Ungarn und Zypern werden ihre Kr\u00e4fte b\u00fcndeln, um das Thema voranzutreiben, f\u00fcgte er hinzu.<\/p>\n<p>Die ungarische Pr\u00e4sidentschaft wird den Kampf gegen illegale Drogen st\u00e4rker in den Mittelpunkt stellen&nbsp;<a href=\"https:\/\/dailynewshungary.com\/de\/der-grose-britische-zuguberfall-wie-eine-15-kopfige-bande-1963-26-millionen-pfund-stahl\/\">Migration<\/a>Szijj\u00e1rt\u00f3 sagte \u201eDie Regierung betrachtet Migration eher als Gefahr denn als Chance\u201csagte er und f\u00fcgte hinzu, dass \u201eMigration einged\u00e4mmt und nicht gesteuert werden muss\u201d.<\/p>\n<p>Szijj\u00e1rt\u00f3 begr\u00fc\u00dfte, dass \u201cZypern \u00e4hnlich wie Ungarn stets seine nationalen Interessen in der EU vertritt\u201d, und stellte eine regelm\u00e4\u00dfige politische Koordinierung zwischen den beiden L\u00e4ndern fest.<\/p>\n<p>Bez\u00fcglich der Wirtschaft verwies Szijj\u00e1rt\u00f3 auf den Tourismus als einen sich schnell entwickelnden Sektor und sagte<\/p>\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Im Jahr 2023 hatten \u00fcber 66.000 Ungarn Zypern besucht, 31 Prozent mehr als im Vorjahr.<\/p>\n<\/blockquote>\n<p>Der Umsatz des bilateralen Handels liege bei \u00fcber 100 Millionen Euro, sagte Szijj\u00e1rt\u00f3 und f\u00fcgte hinzu, dass Energie weitere M\u00f6glichkeiten der Zusammenarbeit biete, insbesondere im Hinblick auf neue Ressourcen in Zypern.<\/p>\n<p>Szijj\u00e1rt\u00f3 erw\u00e4hnte auch, dass Ungarn Truppen zur Friedensmission der Vereinten Nationen (UNFICYP) geschickt habe, \u201eund damit zu Frieden und Stabilit\u00e4t beigetragen hat\u201c\u201d.<\/p>\n<h2 class=\"wp-block-heading\">Ungarische Botschaft wird in Zypern er\u00f6ffnet<\/h2>\n<p>Angesichts der Wirtschaftsbeziehungen, der k\u00fcnftigen Energiekooperation, der gro\u00dfen ungarischen Gemeinschaft und der vielen Touristen und Soldaten beschloss die Regierung, die Botschaft in Nikosia wieder zu er\u00f6ffnen und die Dienstleistungen zu verbessern.<\/p>\n<p>Er&nbsp;<a href=\"https:\/\/hirado.hu\/kulfold\/cikk\/2024\/04\/02\/szijjarto-peter-ujranyilt-magyarorszag-ciprusi-nagykovetsege\" target=\"_blank\" rel=\"noopener\">Sagte<\/a>&nbsp;Dass es wichtig ist, den ungarischen B\u00fcrgern, die zu Besuch sind oder sogar&nbsp;<strong><a href=\"https:\/\/gk-lawfirm.com\/practice-areas\/immigration-law\/cyprus-permanent-residency\/\" target=\"_blank\" rel=\"noopener\">Dauerhaft in Zypern leben<\/a><\/strong>(dass aber auch eine pers\u00f6nliche diplomatische Pr\u00e4senz ein Mittel sein kann, um die bilateralen Beziehungen weiter zu verbessern.<\/p>\n<p>\u201cIch hoffe, dass die Anwesenheit der Botschaft deutlich zeigen wird, welche Bedeutung die ungarische Seite dieser Beziehung beimisst\u201d, sagte er und dankte den lokalen Beh\u00f6rden f\u00fcr ihre Hilfe bei der schnellen Bew\u00e4ltigung der Angelegenheit.<\/p>\n<div class=\"lazyblock-dnh-insert-embed-post-Z1MYzfm wp-block-lazyblock-dnh-insert-embed-post\">\n<div class=\"custom-link-block dnh-embed-container\">\n<h3 class=\"dnh-embed-post-label\">Lesen Sie auch<\/h3>\n<p>        <a href=\"https:\/\/dailynewshungary.com\/de\/chaos-wizz-air-fluge-mit-brutalen-verspatungen-viele-passagiere-haben-zypern-flugzeug-verpasst\/\" class=\"dnh-embed-post-url\"><br \/>\n            Chaos: Wizz Air-Fl\u00fcge mit brutalen Versp\u00e4tungen, viele Passagiere haben Zypern-Flugzeug verpasst!        <\/a>\n    <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ungarn und Zypern \u201cwerden niemals akzeptieren, dass die Europ\u00e4ische Union bis zu Mitgliedstaaten erster und zweiter Klasse aufgeteilt werden sollte\u201d, sagte Au\u00dfenminister P\u00e9ter Szijj\u00e1rt\u00f3 am Dienstag in Nikosia und f\u00fcgte hinzu, dass die beiden L\u00e4nder \u201csich entschieden gegen die Abschaffung der einstimmigen Entscheidungsfindung\u201d in der EU aussprechen. Auf einer gemeinsam mit seinem zyprischen Amtskollegen Constantinos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":663379,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"yes","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1081],"tags":[1169,1160,1132,1082,1445,1076,1638],"class_list":["post-663378","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politik","tag-aussenministerium-von-ungarn","tag-besuch","tag-diplomatie","tag-europaische-union","tag-migration","tag-ungarn","tag-vereinigte-nationen"],"blocksy_meta":[],"acf":[],"author_username":"alk","telegram_post":"","public_post_metadata":{"breaking_news":"no","important":"no","csempe":"no","center_tile":"no","disable_thumbnail":"no","target_lang":"","_featured_image_style":"hidden","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"","focus_keyword":"Zypern","canonical_url":"","robots":"","primary_category":"1081","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"80","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/663378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=663378"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/663378\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/663379"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=663378"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=663378"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=663378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}