{"id":670208,"date":"2023-10-06T11:34:37","date_gmt":"2023-10-06T09:34:37","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/ungarische-regierung-zur-verscharfung-der-arbeitsgesetze\/"},"modified":"2023-10-06T11:34:37","modified_gmt":"2023-10-06T09:34:37","slug":"ungarische-regierung-zur-verscharfung-der-arbeitsgesetze","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/ungarische-regierung-zur-verscharfung-der-arbeitsgesetze\/","title":{"rendered":"Ungarische Regierung zur Versch\u00e4rfung der Arbeitsgesetze"},"content":{"rendered":"<p><strong>Die Regierung entwirft Gesetze, um die Vorschriften zur Einwanderung und Arbeit von Drittstaatsb\u00fcrgern weiter zu versch\u00e4rfen, teilte das Wirtschaftsentwicklungsministerium am Donnerstag mit.<\/strong><\/p>\n<p>Die Regierung werde die geltenden Vorschriften mit dem Ziel einer \u201cvollst\u00e4ndigen \u00dcberarbeitung und Versch\u00e4rfung der Vorschriften \u00fcber Einwanderung und Arbeit\u201d rigoros \u00fcberpr\u00fcfen \u201cUmfassende Ma\u00dfnahmen sind erforderlich, was den Aufenthalt und die Besch\u00e4ftigung von Drittstaatsb\u00fcrgern betrifft, um die ungarischen Arbeitskr\u00e4fte und B\u00fcrger zu sch\u00fctzen\u201d, hei\u00dft es in der Erkl\u00e4rung.<\/p>\n<p>\u201cDer neue Gesetzentwurf wird deutlich machen, dass Drittstaatsangeh\u00f6rige nur aus den von Ungarn festgelegten Gr\u00fcnden, durch die Erf\u00fcllung der Anforderungen des Staates und durch seine Zustimmung in Ungarn leben und arbeiten k\u00f6nnen\u201d, hei\u00dft es in der Erkl\u00e4rung.<\/p>\n<p>Unternehmen m\u00fcssten zun\u00e4chst versuchen, alle Arbeitspl\u00e4tze mit Ungarn zu besetzen, und d\u00fcrften Ausl\u00e4nder nur dann besch\u00e4ftigen, wenn das nicht m\u00f6glich sei, hie\u00df es.<\/p>\n<p>Die Umsetzung des Gesetzes \u00fcber die Besch\u00e4ftigung von Gastarbeitern werde auf Eis gelegt, bis die umfassende Gesetzgebung in Kraft sei, hei\u00dft es in der Erkl\u00e4rung.<\/p>\n<p><strong>Lesen Sie auch:<\/strong><\/p>\n<ul>\n<li><a href=\"https:\/\/dailynewshungary.com\/de\/die-mit-spannung-erwartete-innovation-kommt-bei-den-budapester-u-bahnlinien\/\">Die mit Spannung erwartete Innovation kommt bei den Budapester U-Bahnlinien<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Die Regierung entwirft Gesetze, um die Vorschriften zur Einwanderung und Arbeit von Drittstaatsb\u00fcrgern weiter zu versch\u00e4rfen, teilte das Wirtschaftsentwicklungsministerium am Donnerstag mit. Die Regierung werde die geltenden Vorschriften mit dem Ziel einer \u201cvollst\u00e4ndigen \u00dcberarbeitung und Versch\u00e4rfung der Vorschriften \u00fcber Einwanderung und Arbeit\u201d rigoros \u00fcberpr\u00fcfen \u201cUmfassende Ma\u00dfnahmen sind erforderlich, was den Aufenthalt und die Besch\u00e4ftigung von [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":670209,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"yes","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1081],"tags":[1096,1217,1423,1102,1076],"class_list":["post-670208","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politik","tag-arbeitsmarkt","tag-expats-in-ungarn","tag-recht","tag-ungarische-regierung","tag-ungarn"],"blocksy_meta":[],"acf":[],"author_username":"ugyelet","telegram_post":"","public_post_metadata":{"breaking_news":"yes","important":"no","csempe":"no","center_tile":"no","disable_thumbnail":"no","target_lang":"","_featured_image_style":"hidden","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"Die ungarische Regierung entwirft Gesetze zur weiteren Versch\u00e4rfung der Arbeitsvorschriften, teilte das Wirtschaftsentwicklungsministerium am Donnerstag mit.","focus_keyword":"Ungarische Regierung","canonical_url":"","robots":"","primary_category":"1081","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"53","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/670208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=670208"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/670208\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/670209"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=670208"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=670208"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=670208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}