{"id":670724,"date":"2023-09-21T17:41:09","date_gmt":"2023-09-21T15:41:09","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/ungarisches-fm-die-globale-zusammenarbeit-im-gesundheitswesen-muss-vollig-entpolitisiert-werden\/"},"modified":"2023-09-21T17:41:09","modified_gmt":"2023-09-21T15:41:09","slug":"ungarisches-fm-die-globale-zusammenarbeit-im-gesundheitswesen-muss-vollig-entpolitisiert-werden","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/ungarisches-fm-die-globale-zusammenarbeit-im-gesundheitswesen-muss-vollig-entpolitisiert-werden\/","title":{"rendered":"Ungarisches FM: Die globale Zusammenarbeit im Gesundheitswesen muss v\u00f6llig entpolitisiert werden"},"content":{"rendered":"<p><strong>Die globale Zusammenarbeit im Gesundheitswesen m\u00fcsse v\u00f6llig entpolitisiert werden, damit die Welt besser auf eine m\u00f6gliche zuk\u00fcnftige Pandemie vorbereitet sei, sagte der ungarische Au\u00dfenminister am Mittwoch auf einer Generalversammlung der Vereinten Nationen in New York.<\/strong><\/p>\n<p>Das Ministerium zitierte P\u00e9ter Szijj\u00e1rt\u00f3 und sagte auf einem hochrangigen Treffen zur Pandemiepr\u00e4vention, -vorsorge und -reaktion, dass die Coronavirus-Pandemie gezeigt habe, \u201ewie schutzlos wir sind, unabh\u00e4ngig von all unseren superhochentwickelten Technologien und der k\u00fcnstlichen Intelligenz, die uns zur Verf\u00fcgung stehen.\u201c\u201d.<\/p>\n<p>\u201cLeider k\u00f6nnen wir das Leben der Hunderttausenden Verstorbenen nicht zur\u00fcckgeben&#8230; aber wir m\u00fcssen die Schlussfolgerungen ziehen und verstehen, um in Zukunft besser gesch\u00fctzt zu sein\u201d, f\u00fcgte er hinzu.<\/p>\n<p>\u201eEine dieser Lektionen, die wir lernen m\u00fcssen, ist, dass all diese strategischen Kapazit\u00e4ten unter normalen Umst\u00e4nden wie nutzlos aussehen k\u00f6nnten, aber unter Notfallbedingungen Leben retten k\u00f6nnen,\u201csagte Szijj\u00e1rt\u00f3\u201d.<\/p>\n<p><a href=\"https:\/\/dailynewshungary.com\/de\/der-grose-britische-zuguberfall-wie-eine-15-kopfige-bande-1963-26-millionen-pfund-stahl\/\" target=\"_blank\" rel=\"noopener\">Ungarn<\/a> Er baute eine eigene Impfstofffabrik, ist nun auch in der Lage, Masken, Handschuhe und Beatmungsger\u00e4te herzustellen und verf\u00fcgt \u00fcber eigene Luftfrachtlieferkapazit\u00e4ten, f\u00fcgte er hinzu.<\/p>\n<p>Er \u00e4u\u00dferte die Hoffnung, dass dies eine Folge davon sei <a href=\"https:\/\/dailynewshungary.com\/de\/der-grose-britische-zuguberfall-wie-eine-15-kopfige-bande-1963-26-millionen-pfund-stahl\/\" target=\"_blank\" rel=\"noopener\">COVID<\/a>\u201eAlle verstehen, dass \u201edie menschliche Gesundheit nichts mit Geopolitik zu tun hat.\u201cVirus kennt keine Grenzen, keine Ideologien, keine politische Zugeh\u00f6rigkeit\u201d.<\/p>\n<p>Um besser gesch\u00fctzt zu werden, m\u00fcsse die Welt in eine \u00c4ra echter globaler Zusammenarbeit kommen, die nicht durch globale Politik eingeschr\u00e4nkt, eingeschr\u00e4nkt oder beeinflusst werde, sagte er.<\/p>\n<p>\u201cDiejenigen, die zulassen <a href=\"https:\/\/dailynewshungary.com\/de\/der-grose-britische-zuguberfall-wie-eine-15-kopfige-bande-1963-26-millionen-pfund-stahl\/\" target=\"_blank\" rel=\"noopener\">Gesundheit<\/a> Sorge mit der globalen Politik zu verwechseln, wird daf\u00fcr verantwortlich sein, dass wir nicht das Leben retten k\u00f6nnen, wir k\u00f6nnen nicht so viele Menschen sch\u00fctzen, wie viele mit einer echten Zusammenarbeit h\u00e4tten gesch\u00fctzt werden k\u00f6nnen\u201d, sagte der Au\u00dfenminister.<\/p>\n<p>Ungarn sei \u201eeinesfalls\u201cAngriffen ausgesetzt gewesen, weil es Impfstoffe gekauft habe, die in \u00f6stlichen L\u00e4ndern hergestellt wurden, und diese Kritik und Angriffe h\u00e4tten keinerlei berufliche Aspekte gehabt, sagte er. Szijj\u00e1rt\u00f3 sagte, Ungarn habe die erfolgreichste Impfkampagne in der Region abgeschlossen<a href=\"https:\/\/dailynewshungary.com\/de\/der-grose-britische-zuguberfall-wie-eine-15-kopfige-bande-1963-26-millionen-pfund-stahl\/\" target=\"_blank\" rel=\"noopener\"> Europ\u00e4ische Union<\/a> Weil die Regierung gleichzeitig Impfstoffe aus Ost und West kaufteDie Regierung betrachtete Impfstoffe als Instrumente zur Rettung von Leben und nicht als politisches Statementf\u00fcgte er hinzu.<\/p>\n<p>\u201cDas Jahrzehnt der Gefahren steht an und wir k\u00f6nnen nicht ausschlie\u00dfen, dass neue Viren Herausforderungen vor uns stellen werden\u201d, sagte <a href=\"https:\/\/dailynewshungary.com\/de\/der-grose-britische-zuguberfall-wie-eine-15-kopfige-bande-1963-26-millionen-pfund-stahl\/\">Szijj\u00e1rt\u00f3<\/a>, es als globale Verantwortung bezeichnen, besser vorbereitet zu sein.<\/p>\n<p>\u201cWenn wir dieses Thema politisch angehen, werden wir scheitern\u201d, f\u00fcgte er hinzu.<\/p>\n<p>Die globale Zusammenarbeit im Gesundheitswesen muss v\u00f6llig entpolitisiert werden <a href=\"https:\/\/dailynewshungary.com\/de\/der-grose-britische-zuguberfall-wie-eine-15-kopfige-bande-1963-26-millionen-pfund-stahl\/\" target=\"_blank\" rel=\"noopener\">UN<\/a> Mitgliedstaaten m\u00fcssen ihr Bestes geben, um \u201czu machen <a href=\"https:\/\/dailynewshungary.com\/de\/der-grose-britische-zuguberfall-wie-eine-15-kopfige-bande-1963-26-millionen-pfund-stahl\/\" target=\"_blank\" rel=\"noopener\">WER<\/a> Die professionellste und entpolitisierteste Machtorganisation einer nationalen politischen Region\u201d, sagte der Au\u00dfenminister zum Abschluss seiner Ansprache.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die globale Zusammenarbeit im Gesundheitswesen m\u00fcsse v\u00f6llig entpolitisiert werden, damit die Welt besser auf eine m\u00f6gliche zuk\u00fcnftige Pandemie vorbereitet sei, sagte der ungarische Au\u00dfenminister am Mittwoch auf einer Generalversammlung der Vereinten Nationen in New York. Das Ministerium zitierte P\u00e9ter Szijj\u00e1rt\u00f3 und sagte auf einem hochrangigen Treffen zur Pandemiepr\u00e4vention, -vorsorge und -reaktion, dass die Coronavirus-Pandemie gezeigt [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"yes","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1098],"tags":[3497,2243,1082,1107,1076,1638,1721],"class_list":["post-670724","post","type-post","status-publish","format-standard","hentry","category-gesellschaft","tag-auslanderangelegenheiten-ungarnministerium","tag-coronavirus","tag-europaische-union","tag-gesundheit","tag-ungarn","tag-vereinigte-nationen","tag-wer"],"blocksy_meta":[],"acf":[],"author_username":"ugyelet","telegram_post":"","public_post_metadata":{"breaking_news":"yes","important":"no","csempe":"no","center_tile":"no","disable_thumbnail":"no","target_lang":"","_featured_image_style":"hidden","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"Die globale Zusammenarbeit im Gesundheitswesen muss v\u00f6llig entpolitisiert werden, damit die Welt besser auf eine m\u00f6gliche zuk\u00fcnftige Pandemie vorbereitet ist","focus_keyword":"Gesundheit","canonical_url":"","robots":"","primary_category":"1098","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"57","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/670724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=670724"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/670724\/revisions"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=670724"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=670724"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=670724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}