{"id":689918,"date":"2022-03-29T16:00:00","date_gmt":"2022-03-29T14:00:00","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/v4-kooperation-zum-einfrieren-tschechen-polen-bleiben-zu-hause-ungarn-sagt-verteidigungstreffen-ab\/"},"modified":"2022-03-29T16:00:00","modified_gmt":"2022-03-29T14:00:00","slug":"v4-kooperation-zum-einfrieren-tschechen-polen-bleiben-zu-hause-ungarn-sagt-verteidigungstreffen-ab","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/v4-kooperation-zum-einfrieren-tschechen-polen-bleiben-zu-hause-ungarn-sagt-verteidigungstreffen-ab\/","title":{"rendered":"V4-Kooperation zum Einfrieren? Tschechen, Polen bleiben zu Hause, Ungarn sagt Verteidigungstreffen ab"},"content":{"rendered":"<p><strong><span data-preserver-spaces=\"true\">Ungarn h\u00e4tte das n\u00e4chste Verteidigungstreffen der Zusammenarbeit Visegr\u00e1d Four aus Ungarn, der Slowakei, der Tschechischen Republik und Polen ausgerichtet. Die Polen und Tschechen haben jedoch bereits gekl\u00e4rt, dass sie wegen der Ukraine-Politik der ungarischen Regierung nicht kommen w\u00fcrden. Wie bekannt ist, geh\u00f6ren Warschau und Prag zu den Hardlinern in Bezug auf Putins Krieg gegen Russland.<\/span><\/strong><\/p>\n<h2>Anti-Russland, pro-Russland?<\/h2>\n<p><span data-preserver-spaces=\"true\">Polen bot der Ukraine sogar seine MIG-29-Kampfflugzeuge an, aber die Vereinigten Staaten haben diesen Plan schnell zunichte gemacht. Zwei Tage zuvor sagte der ukrainische Au\u00dfenminister Dmytro Kuleba, Washington unterst\u00fctze die Idee. Daher liegt es jetzt an Warschau, ob sie diese Flugzeuge schicken werden oder nicht. Die Tschechische Republik geh\u00f6rt auch zu den Hardlinern, wenn es um Sanktionen gegen Russland geht. Sie m\u00f6chten beispielsweise Sanktionen gegen russische Energie verh\u00e4ngen. Dar\u00fcber hinaus unterst\u00fctzen beide Nationen Waffentransporte in Richtung Ukraine, obwohl die Tschechen keine gemeinsame Grenze mit dem vom Krieg betroffenen Land haben.<\/span><\/p>\n<p><span data-preserver-spaces=\"true\">Unterdessen erkl\u00e4rte die ungarische Regierung, sie werde die Ausweitung der Sanktionen gegen russische Energie nicht unterst\u00fctzen, weil das steigende Heizpreise und den industriellen Zusammenbruch Ungarns bedeuten w\u00fcrde Insofern folgt Budapest dem Standpunkt Berlins Dar\u00fcber hinaus erlaubt die Regierung Orb\u00e1n nicht, dass t\u00f6dliche milit\u00e4rische Ausr\u00fcstung die ungarisch-ukrainische Grenze passiertSie sagen, solche Lieferungen w\u00fcrden die ungarische Minderheit gef\u00e4hrden, die auf ukrainischer Seite lebt.<\/span><\/p>\n<ul>\n<li><span data-preserver-spaces=\"true\">Lesen Sie auch:&nbsp;<\/span><a class=\"editor-rtfLink\" href=\"https:\/\/dailynewshungary.com\/de\/ist-orban-wirklich-putins-schoshund-hier-ist-was-ungarn-fur-die-ukraine-tut-und-was-nicht\/\" target=\"_blank\" rel=\"noopener\"><span data-preserver-spaces=\"true\">Ist Orb\u00e1n wirklich Putins Scho\u00dfhund? Hier ist, was Ungarn f\u00fcr die Ukraine tut und was nicht<\/span><\/a><\/li>\n<\/ul>\n<h2>Verteidigungstreffen verschoben<\/h2>\n<p><span data-preserver-spaces=\"true\">Wir&nbsp;<\/span><a class=\"editor-rtfLink\" href=\"https:\/\/dailynewshungary.com\/de\/ungarischer-prasident-besucht-polen-am-tag-der-polnisch-ungarischen-freundschaft-nicht\/\" target=\"_blank\" rel=\"noopener\"><span data-preserver-spaces=\"true\">Geschrieben<\/span><\/a><span data-preserver-spaces=\"true\"> Zuvor sollte J\u00e1nos \u00c1der am 23. M\u00e4rz anl\u00e4sslich des Tages der polnisch-ungarischen Freundschaft die Stadt Bochnia in Polen besuchen. Der ungarische Pr\u00e4sident ging jedoch nicht, weil der polnische Pr\u00e4sident sich wegen der Haltung Ungarns zum russischen Einmarsch nicht mit ihm treffen wollte.<\/span><\/p>\n<p><a class=\"editor-rtfLink\" href=\"https:\/\/www.blikk.hu\/aktualis\/politika\/v4-magyarorszag-lemondas-lengyelek-csehek\/6qws1kk\" target=\"_blank\" rel=\"noopener\"><span data-preserver-spaces=\"true\">Blikk.hu<\/span><\/a><span data-preserver-spaces=\"true\">&nbsp;Heute schrieb, Ungarn werde das f\u00fcr diesen Mittwoch in Budapest geplante Verteidigungstreffen der Visegr\u00e1d Four-L\u00e4nder absagen. Sowohl die tschechische als auch die polnische Regierung haben zugestimmt, dass sie nicht kommen w\u00fcrden, da sie mit der Ukraine-Politik des Orb\u00e1n-Kabinetts nicht einverstanden sind.<\/span><\/p>\n<ul>\n<li><span data-preserver-spaces=\"true\">Lesen Sie auch: <a href=\"https:\/\/dailynewshungary.com\/de\/orban-selenskyj-will-so-viele-staaten-wie-moglich-in-den-krieg-ziehen-darunter-auch-ungarn\/\">Orb\u00e1n: Selenskyj will so viele Staaten wie m\u00f6glich in den Krieg ziehen, darunter auch Ungarn<\/a><\/span><\/li>\n<\/ul>\n<p><span data-preserver-spaces=\"true\">Nach Angaben des slowakischen Verteidigungsministeriums wurde Ungarn von Polen und der Tschechischen Republik scharf kritisiert. Wojciech Skurkiewicz, der stellvertretende polnische Verteidigungsminister, sagte, dass die Beobachtung der V4-Kooperation keinen Grund zum Optimismus gebe.&nbsp;<\/span><\/p>\n<p><span data-preserver-spaces=\"true\">Die tschechische Verteidigungsministerin Jana cozernochov\u00e1 sagte am vergangenen Freitag das Verteidigungstreffen in Budapest ab. Ihr polnischer Kollege Mariusz Blusszczak tat dasselbe am Montagabend. \u201c<\/span><em><span data-preserver-spaces=\"true\">Es tut mir sehr leid, dass billiges russisches \u00d6l f\u00fcr ungarische Politiker wichtiger ist als ukrainisches Blut<\/span><\/em><span data-preserver-spaces=\"true\">\u201d \u2013 sagte Cernochov\u00e1.<\/span><\/p>\n<p><span data-preserver-spaces=\"true\">Der polnische Pr\u00e4sident Andrzej Duda sagte, es sei schwer, die Haltung von Premierminister Orb\u00e1n gegen\u00fcber der Ukraine zu verstehen. Der polnische Au\u00dfenminister f\u00fcgte hinzu, Orb\u00e1n habe einen Fehler in Bezug auf seine Russland- und Ukraine-Politik gemacht.&nbsp;<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ungarn h\u00e4tte das n\u00e4chste Verteidigungstreffen der Zusammenarbeit Visegr\u00e1d Four aus Ungarn, der Slowakei, der Tschechischen Republik und Polen ausgerichtet. Die Polen und Tschechen haben jedoch bereits gekl\u00e4rt, dass sie wegen der Ukraine-Politik der ungarischen Regierung nicht kommen w\u00fcrden. Wie bekannt ist, geh\u00f6ren Warschau und Prag zu den Hardlinern in Bezug auf Putins Krieg gegen Russland. [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":689919,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"yes","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1081],"tags":[1360,1084,1197,1209,1173,1366,1128,1923],"class_list":["post-689918","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politik","tag-hungern","tag-krieg-in-der-ukraine","tag-polen","tag-russland","tag-slowakei","tag-tschechische-republik","tag-viktor-orban","tag-visegrad-vier"],"blocksy_meta":[],"acf":[],"author_username":"johnwoods","telegram_post":"","public_post_metadata":{"breaking_news":"yes","important":"no","csempe":"no","center_tile":"no","disable_thumbnail":"no","target_lang":"","_featured_image_style":"hidden","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"Ungarn w\u00e4re Gastgeber des n\u00e4chsten Verteidigungstreffens der V4-Zusammenarbeit gewesen, an dem die Slowakei, die Tschechische Republik und Polen beteiligt gewesen w\u00e4ren.","focus_keyword":"Verteidigungssitzung","canonical_url":"","robots":"","primary_category":"1081","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"69","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/689918","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=689918"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/689918\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/689919"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=689918"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=689918"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=689918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}