{"id":690643,"date":"2022-03-09T09:45:45","date_gmt":"2022-03-09T08:45:45","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/premierminister-orban-teilte-johnson-mit-ob-ungarn-truppen-und-waffen-an-die-ukraine-weiterleiten-werde\/"},"modified":"2022-03-09T09:45:45","modified_gmt":"2022-03-09T08:45:45","slug":"premierminister-orban-teilte-johnson-mit-ob-ungarn-truppen-und-waffen-an-die-ukraine-weiterleiten-werde","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/premierminister-orban-teilte-johnson-mit-ob-ungarn-truppen-und-waffen-an-die-ukraine-weiterleiten-werde\/","title":{"rendered":"Premierminister Orb\u00e1n teilte Johnson mit, ob Ungarn Truppen und Waffen an die Ukraine weiterleiten werde"},"content":{"rendered":"<p><strong>Premierminister Viktor Orb\u00e1n machte in London deutlich, dass Ungarn weder Truppen oder Waffen in die Ukraine schicken werde, noch Waffentransporte \u201cdirekt in den von Russland angegriffenen Staat\u201d \u00fcber sein Territorium zulassen werde, sagte Au\u00dfenminister P\u00e9ter Szijj\u00e1rt\u00f3 am sp\u00e4ten Dienstag nach der Teilnahme an Gespr\u00e4chen an der Seite von Orb\u00e1n mit Visegr\u00e1d-F\u00fchrern und Premierminister Boris Johnson.<\/strong><\/p>\n<p>Bei seiner R\u00fcckkehr nach Budapest sagte er, die Gespr\u00e4che, einschlie\u00dflich eines bilateralen Treffens zwischen Orb\u00e1n und Johnson, h\u00e4tten sich \u201eausschlie\u00dflich auf Fragen rund um den Ukraine-Krieg und die Sicherheitsherausforderungen infolge des Konflikts\u201ckonzentriert und \u201eFake News\u201d-Berichte \u00fcber die Gespr\u00e4che zur\u00fcckgewiesen.<\/p>\n<blockquote>\n<p>Ungarn, die Tschechische Republik, die Slowakei und Polen sind alle daran interessiert, Frieden zu schaffen und der Ukraine Hilfe zu leisten, aber \u201ejeder tut dies auf seine eigene Weise\u201c\u201d,<\/p>\n<\/blockquote>\n<p>Szijj\u00e1rt\u00f3 sagte. Die anderen drei Visegrad-L\u00e4nder haben beschlossen, den Transit t\u00f6dlicher Hilfe zuzulassen, w\u00e4hrend die ungarische Regierung der Ukraine \u201edurch&#8221; hilft<\/p>\n<blockquote>\n<p>Die gr\u00f6\u00dfte humanit\u00e4re Operation ihrer Geschichte\u201d, die<\/p>\n<\/blockquote>\n<p>Der Minister sagte und f\u00fcgte hinzu, dass diese Hilfe ausschlie\u00dflich humanit\u00e4rer Natur sei Ungarn d\u00fcrfe sich nicht in den Konflikt verwickeln, sagte er und f\u00fcgte hinzu, dass die erste Pflicht der Regierung darin bestehe, das ungarische Volk zu sch\u00fctzen.<\/p>\n<ul>\n<li>Lesen Sie auch: <a href=\"https:\/\/dailynewshungary.com\/de\/der-ungarische-forint-ist-hier-zusammengebrochen\/\">Der ungarische Forint ist hier zusammengebrochen<\/a><\/li>\n<\/ul>\n<p>Auch die ungarische Regierung<\/p>\n<blockquote>\n<p>\u201ckann Sanktionen nicht unterst\u00fctzen, die die Energieversorgung des Landes gef\u00e4hrden k\u00f6nnten\u201d,<\/p>\n<\/blockquote>\n<p>Szijj\u00e1rt\u00f3 sagte, \u201eOhne Gas aus Russland wird es \u201ekeine Heizung geben\u201cund die Industrie st\u00fcnde vor ernsthaften Schwierigkeiten, sagte er. \u201eWenn das Atomaufr\u00fcstungsprojekt Paks gestoppt w\u00fcrde, w\u00fcrden sich die Rechnungen der \u00f6ffentlichen Versorgungsunternehmen weiter vervierfachen\u201d, sagte er.<\/p>\n<p>Vertreter der Regierung sollen am Mittwoch Gespr\u00e4che in Serbien f\u00fchren, sagte er.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Premierminister Viktor Orb\u00e1n machte in London deutlich, dass Ungarn weder Truppen oder Waffen in die Ukraine schicken werde, noch Waffentransporte \u201cdirekt in den von Russland angegriffenen Staat\u201d \u00fcber sein Territorium zulassen werde, sagte Au\u00dfenminister P\u00e9ter Szijj\u00e1rt\u00f3 am sp\u00e4ten Dienstag nach der Teilnahme an Gespr\u00e4chen an der Seite von Orb\u00e1n mit Visegr\u00e1d-F\u00fchrern und Premierminister Boris Johnson. [&hellip;]<\/p>\n","protected":false},"author":50,"featured_media":690644,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"yes","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1081],"tags":[1160,1066,1184,1361,1092,1128,1923],"class_list":["post-690643","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politik","tag-besuch","tag-hungary","tag-krieg","tag-uk","tag-ukraine","tag-viktor-orban","tag-visegrad-vier"],"blocksy_meta":[],"acf":[],"author_username":"dnh","telegram_post":"","public_post_metadata":{"breaking_news":"yes","important":"no","csempe":"no","center_tile":"no","disable_thumbnail":"no","target_lang":"","_featured_image_style":"hidden","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"Premierminister Viktor Orb\u00e1n machte bei seinem Besuch beim britischen Premierminister Boris Johnson die ungarische Position in dieser Frage noch einmal deutlich.","focus_keyword":"Ukraine","canonical_url":"","robots":"","primary_category":"1081","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"59","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/690643","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/50"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=690643"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/690643\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/690644"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=690643"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=690643"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=690643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}