{"id":690904,"date":"2022-03-01T17:00:00","date_gmt":"2022-03-01T16:00:00","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/ungarn-geht-aus-der-coronavirus-krise-als-sieger-hervor-sagt-minister\/"},"modified":"2022-03-01T17:00:00","modified_gmt":"2022-03-01T16:00:00","slug":"ungarn-geht-aus-der-coronavirus-krise-als-sieger-hervor-sagt-minister","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/ungarn-geht-aus-der-coronavirus-krise-als-sieger-hervor-sagt-minister\/","title":{"rendered":"Ungarn geht aus der Coronavirus-Krise als Sieger hervor, sagt Minister"},"content":{"rendered":"<p><strong>Die vergangenen 12 Jahre h\u00e4tten \u201cdeutlich gemacht, welchen Wettbewerbsvorteil ein Land durch eine schnelle, von politischer Stabilit\u00e4t getragene Entscheidungsfindung erlangen wird\u201d, sagte P\u00e9ter Szijj\u00e1rt\u00f3, der Minister f\u00fcr ausw\u00e4rtige Angelegenheiten und Handel, am Dienstag auf einer Veranstaltung der ungarischen Industrie &#8211; und Handelskammer.<\/strong><\/p>\n<p>In einer Erkl\u00e4rung zitierte das Au\u00dfenministerium Szijj\u00e1rt\u00f3 mit den Worten, Ungarn sei aus der Coronavirus-Krise als Sieger hervorgegangen \u201eEs ist klar geworden, dass zwei Dinge notwendig sind, um wirtschaftlich erfolgreich zu sein: so viele Investitionen wie m\u00f6glich anzuziehen und Marktchancen zu ergattern\u201csagte der Minister.<\/p>\n<p>Szijj\u00e1rt\u00f3 sagte<\/p>\n<blockquote>\n<p>Die ungarische Wirtschaft sei seit 2013 \u201cum das Doppelte des europ\u00e4ischen Durchschnitts pro Jahr\u201d gewachsen, wobei staatliche Steuersenkungen eine entscheidende Rolle spielten, insbesondere die Einf\u00fchrung der einheitlichen Steuer.<\/p>\n<\/blockquote>\n<p>Unter Berufung auf Eurostat-Zahlen sagte der Minister, dass Ungarn in den letzten zehn Jahren die gr\u00f6\u00dften Lohnsteuersenkungen vorgenommen habe, was dem Land seit 2014 jedes Jahr dabei geholfen habe, Investitionsrekorde zu brechen.<\/p>\n<blockquote>\n<p>Die Regierung unterst\u00fctzte 1.380 Unternehmen w\u00e4hrend der Coronavirus-Krise mit Entwicklungsprojekten im Gesamtwert von 900 Milliarden Forint (2,4 Mrd. EUR)<\/p>\n<\/blockquote>\n<p>Szijj\u00e1rt\u00f3 sagte. Die Regierung habe insgesamt 375 Milliarden Forint zu diesen Projekten beigetragen, die ma\u00dfgeblich zur Rettung von rund 290.000 Arbeitspl\u00e4tzen beigetragen h\u00e4tten, sagte er.<\/p>\n<p>Zum Ukraine-Krieg sagte Szijj\u00e1rt\u00f3, er werde erhebliche wirtschaftliche Auswirkungen haben und \u201cden Status quo der Weltwirtschaft zum zweiten Mal in zwei Jahren scheitern lassen\u201d.<\/p>\n<p>Es m\u00fcssten alle Anstrengungen unternommen werden, um Frieden zu schaffen, aber es m\u00fcssten auch Anstrengungen unternommen werden, um sicherzustellen, dass auch Ungarn gest\u00e4rkt aus dieser Krise herauskommt, sagte er.<\/p>\n<p>Wie wir heute bereits geschrieben haben <a href=\"https:\/\/dailynewshungary.com\/de\/ungarn-covid-19-todesopferzahl-uber-44-000\/\">Ungarn COVID-19-Todesopferzahl \u00fcber 44.000<\/a>.<\/p>\n<ul>\n<li>Lesen Sie mehr News \u00fcber <a href=\"https:\/\/dailynewshungary.com\/de\/der-grose-britische-zuguberfall-wie-eine-15-kopfige-bande-1963-26-millionen-pfund-stahl\/\">Coronavirus in Ungarn<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Die vergangenen 12 Jahre h\u00e4tten \u201cdeutlich gemacht, welchen Wettbewerbsvorteil ein Land durch eine schnelle, von politischer Stabilit\u00e4t getragene Entscheidungsfindung erlangen wird\u201d, sagte P\u00e9ter Szijj\u00e1rt\u00f3, der Minister f\u00fcr ausw\u00e4rtige Angelegenheiten und Handel, am Dienstag auf einer Veranstaltung der ungarischen Industrie &#8211; und Handelskammer. In einer Erkl\u00e4rung zitierte das Au\u00dfenministerium Szijj\u00e1rt\u00f3 mit den Worten, Ungarn sei aus [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":690905,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"no","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1281],"tags":[1096,2243,1778,1137,1076,1104],"class_list":["post-690904","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geschaft","tag-arbeitsmarkt","tag-coronavirus","tag-coronavirus-in-ungarn","tag-ungarische-wirtschaft","tag-ungarn","tag-wirtschaft"],"blocksy_meta":[],"acf":[],"author_username":"alk","telegram_post":"","public_post_metadata":{"breaking_news":"yes","important":"no","csempe":"no","center_tile":"no","disable_thumbnail":"no","target_lang":"","_featured_image_style":"hidden","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"","focus_keyword":"","canonical_url":"","robots":"","primary_category":"1281","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/690904","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=690904"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/690904\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/690905"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=690904"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=690904"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=690904"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}