{"id":691655,"date":"2022-02-06T19:00:00","date_gmt":"2022-02-06T18:00:00","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/die-ungarische-regierung-kaufte-chinesische-beatmungsgerate-die-als-gefahrlich-galten\/"},"modified":"2022-02-06T19:00:00","modified_gmt":"2022-02-06T18:00:00","slug":"die-ungarische-regierung-kaufte-chinesische-beatmungsgerate-die-als-gefahrlich-galten","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/die-ungarische-regierung-kaufte-chinesische-beatmungsgerate-die-als-gefahrlich-galten\/","title":{"rendered":"Die ungarische Regierung kaufte chinesische Beatmungsger\u00e4te, die als gef\u00e4hrlich galten"},"content":{"rendered":"<p><strong>Im Fr\u00fchjahr 2020 war zum Zeitpunkt der Transaktion bereits bekannt, dass ein Beatmungsger\u00e4ttyp nicht den Anforderungen einer sicheren Anwendung entspricht und seine St\u00f6rungen sogar das Leben von Patienten gef\u00e4hrden k\u00f6nnen.<\/strong><\/p>\n<p>Wie in der <a href=\"https:\/\/24.hu\/kulfold\/2022\/02\/05\/kinai-lelegeztetogep-eletveszelyes-magyar-kormany-malaysianow\/\" target=\"_blank\" rel=\"noopener\">Artikel<\/a> Von 24,hu kaufte die ungarische Regierung w\u00e4hrend der ersten Welle des Coronavirus chinesische Beatmungsger\u00e4te vom malaysischen Gesch\u00e4ftsmann Vinod Sekhar f\u00fcr insgesamt 178 Mrd. HUF (501 Mio. EUR).Die Lieferung von 6.258 Maschinen gelangte \u00fcber GR Technologies, ein Unternehmen von Sekhar, nach Ungarn.<\/p>\n<p>Nach den <a href=\"https:\/\/www.malaysianow.com\/news\/2022\/02\/04\/revealed-warning-by-medical-experts-over-ventilators-sold-to-hungary-by-malaysian-businessman\/\" target=\"_blank\" rel=\"noopener\">MalaysiaJetzt<\/a> Nachrichtenportal,<\/p>\n<blockquote>\n<p>Bereits zum Zeitpunkt des riesigen Kaufs durch Ungarn war bekannt, dass eines der von Sekhar vertriebenen Modelle nicht den Anforderungen an eine sichere Verwendung entsprach und seine M\u00e4ngel sogar das Leben von Patienten gef\u00e4hrden k\u00f6nnten.<\/p>\n<\/blockquote>\n<figure id=\"attachment_465662\" aria-describedby=\"caption-attachment-465662\" style=\"width: 1280px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-465662\" src=\"https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2022\/02\/rsz_chinese_ventilator.jpg\" alt=\"Chinesisches Beatmungsger\u00e4t gef\u00e4hrliche Wizz-Luft\" width=\"1280\" height=\"853\" srcset=\"https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2022\/02\/rsz_chinese_ventilator.jpg 1280w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2022\/02\/rsz_chinese_ventilator-768x512.jpg 768w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2022\/02\/rsz_chinese_ventilator-350x233.jpg 350w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2022\/02\/rsz_chinese_ventilator-248x165.jpg 248w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2022\/02\/rsz_chinese_ventilator-1030x686.jpg 1030w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2022\/02\/rsz_chinese_ventilator-219x146.jpg 219w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2022\/02\/rsz_chinese_ventilator-50x33.jpg 50w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2022\/02\/rsz_chinese_ventilator-113x75.jpg 113w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\"><figcaption id=\"caption-attachment-465662\" class=\"wp-caption-text\">Eine Lieferung von Beatmungsger\u00e4ten, die im Mai 2020 in Ungarn entladen wird und von Ungarn auf dem H\u00f6hepunkt der ersten Welle der Covid-19-Pandemie kontrovers gekauft wurde. Quelle: kormany.hu<\/figcaption><\/figure>\n<ul>\n<li>Lesen Sie auch: <a href=\"https:\/\/dailynewshungary.com\/de\/schauen-sie-sich-an-wie-ungarische-kleidung-zur-ewigen-mode-wird\/\">Schauen Sie sich an, wie ungarische Kleidung zur ewigen Mode wird<\/a><\/li>\n<\/ul>\n<p>Das vorgenannte Modell ist die Shangrila 510 S. Im Vereinigten K\u00f6nigreich wurde ein 60-seitiger Bericht \u00fcber die Untersuchung der Maschine ver\u00f6ffentlicht, aufgrund von Bedenken, die im Bericht ge\u00e4u\u00dfert wurden, nahm das Gesundheitsministerium 750 Beatmungsger\u00e4te aus dem Einsatz.<\/p>\n<p>Laut dem Artikel von MalaysiaNow wurde das ebenfalls in der ungarischen Lieferung enthaltene SH300-Modell in Kolumbien wegen schwerwiegender Probleme gemeldet. Berichten im Land zufolge<\/p>\n<blockquote>\n<p>Mindestens sechs Menschen kamen durch das Modell ums Leben, da die Maschinen mehrfach unerwartet anhielten und falsche Daten \u00fcbermittelten.<\/p>\n<\/blockquote>\n<p>24.hu sagt, dass nicht genau bekannt ist, wie viel Sekhar schlie\u00dflich mit dem ungarischen Deal verdiente, aber kurz nachdem er die Beatmungsger\u00e4te geliefert hatte, kaufte er eine Luxusyacht und einen Bombardier BD-700-1A10-Privatjet.<\/p>\n<ul>\n<li>Lesen Sie auch: <a href=\"https:\/\/dailynewshungary.com\/de\/einzigartiger-kabinenlift-und-erneuerter-aussichtspunkt-in-der-tokajer-weinregion-fotos\/\">Einzigartiger Kabinenlift und erneuerter Aussichtspunkt in der Tokajer Weinregion \u2013 FOTOS<\/a><\/li>\n<\/ul>\n<p>Ebenfalls im November letzten Jahres berichtete MalaysiaNow, dass malaysische Beh\u00f6rden die B\u00fcros von Sekhars Hauptsitz in Kuala Lumpur durchsucht h\u00e4tten, gegen den milliardenschweren Gesch\u00e4ftsmann wurde laut dem Papier wegen des Verdachts der Geldw\u00e4sche ermittelt.<\/p>\n<p>Wie in mfor.hus berichtet <a href=\"https:\/\/mfor.hu\/cikkek\/makro\/betegeket-veszelyezteto-lelegeztetogepet-is-vasarolt-a-magyar-kormany.html\" target=\"_blank\" rel=\"noopener\">Artikel<\/a>(In Ungarn befindet sich der Gro\u00dfteil der 16.000 w\u00e4hrend der Epidemie gekauften Beatmungsger\u00e4te in Lagereinrichtungen, und das Au\u00dfenministerium hat damit begonnen, den \u00dcberschuss zu verkaufen und zu verschenken.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Im Fr\u00fchjahr 2020 war zum Zeitpunkt der Transaktion bereits bekannt, dass ein Beatmungsger\u00e4ttyp nicht den Anforderungen einer sicheren Anwendung entspricht und seine St\u00f6rungen sogar das Leben von Patienten gef\u00e4hrden k\u00f6nnen. Wie in der Artikel Von 24,hu kaufte die ungarische Regierung w\u00e4hrend der ersten Welle des Coronavirus chinesische Beatmungsger\u00e4te vom malaysischen Gesch\u00e4ftsmann Vinod Sekhar f\u00fcr insgesamt [&hellip;]<\/p>\n","protected":false},"author":62,"featured_media":691656,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"yes","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1281],"tags":[1470,1778,1102,1137,1109,1076],"class_list":["post-691655","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geschaft","tag-ausenministerium-fur-ungarn","tag-coronavirus-in-ungarn","tag-ungarische-regierung","tag-ungarische-wirtschaft","tag-ungarisches-gesundheitssystem","tag-ungarn"],"blocksy_meta":[],"acf":[],"author_username":"hmercedesz","telegram_post":"","public_post_metadata":{"breaking_news":"yes","important":"no","csempe":"no","center_tile":"no","disable_thumbnail":"no","target_lang":"","_featured_image_style":"hidden","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"","focus_keyword":"","canonical_url":"","robots":"","primary_category":"1281","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/691655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=691655"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/691655\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/691656"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=691655"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=691655"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=691655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}