{"id":692458,"date":"2022-01-13T14:30:00","date_gmt":"2022-01-13T13:30:00","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/bruch-der-regierungskurzungen-quarantanezeit\/"},"modified":"2022-01-13T14:30:00","modified_gmt":"2022-01-13T13:30:00","slug":"bruch-der-regierungskurzungen-quarantanezeit","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/bruch-der-regierungskurzungen-quarantanezeit\/","title":{"rendered":"Bruch der Regierungsk\u00fcrzungen Quarant\u00e4nezeit!"},"content":{"rendered":"<div class=\"leadNews\"><strong><span id=\"ctl00_ContentPlaceHolder1_ctrlNewsControl_lbLead\">Ungarns Regierung habe beschlossen, die Quarant\u00e4nezeiten f\u00fcr positiv auf Covid getestete Personen zu verk\u00fcrzen, sagte der Stabschef des Premierministers am Donnerstag.<\/span><\/strong><\/div>\n<div>&nbsp;<\/div>\n<div class=\"leadNews\"><span id=\"ctl00_ContentPlaceHolder1_ctrlNewsControl_lbBody\">Erwachsene m\u00fcssen sich sieben Tage lang selbst isolieren und d\u00fcrfen die Quarant\u00e4ne nach f\u00fcnf Tagen verlassen, wenn sie beschwerdefrei sind und einen negativen Covid-Test vorlegen, sagte Gergely Gulyas in einer regelm\u00e4\u00dfigen Pressekonferenz.<\/span><\/div>\n<div>&nbsp;<\/div>\n<blockquote>\n<div class=\"leadNews\"><span id=\"ctl00_ContentPlaceHolder1_ctrlNewsControl_lbBody\">Ungeimpfte Grundschulkinder der Klassen 1-4 m\u00fcssen f\u00fcnf Tage lang unter Quarant\u00e4ne gestellt werden, wenn sich in ihrer Klasse ein positiver Fall best\u00e4tigt <\/span><\/div>\n<\/blockquote>\n<div>&nbsp;<\/div>\n<div class=\"leadNews\"><span id=\"ctl00_ContentPlaceHolder1_ctrlNewsControl_lbBody\">Er sagte und f\u00fcgte hinzu, dass sie in Isolation online am Unterricht teilnehmen d\u00fcrften. Oth<\/span><span id=\"ctl00_ContentPlaceHolder1_ctrlNewsControl_lbBody\">\u201eWahrscheinlich muss die Pr\u00e4senzbildung ununterbrochen erfolgen, sagte er.<br \/><\/span><\/div>\n<div>&nbsp;<\/div>\n<ul>\n<li>Lesen Sie auch:<a href=\"https:\/\/dailynewshungary.com\/de\/omicron-tobt-fast-10-tausend-neuinfektionen-in-nur-24-stunden\/\"> Omicron tobt: fast 10 Tausend Neuinfektionen in nur 24 Stunden<\/a><\/li>\n<\/ul>\n<div>&nbsp;<\/div>\n<div>Zum Referendum und zur Wahl sagte Guly\u00e1s, dass t<span style=\"color: initial;\">Er Regierung begr\u00fc\u00dft die Entscheidung, die Parlamentswahlen und ein Referendum \u00fcber den Schutz von Kindern am selben Tag abzuhaltenDas liegt daran, dass dadurch 7 Milliarden Forint (19,6 Mio. EUR) eingespart werden, sagte der Stabschef des Premierministers am Donnerstag.<\/span><\/div>\n<div>&nbsp;<\/div>\n<div><span style=\"color: initial;\">Gergely Guly\u00e1s sagte in einer regelm\u00e4\u00dfigen Pressekonferenz, dass es eine seltene Gelegenheit sei, in einer Frage einen Konsens aller politischen Parteien zu erzielen. Er dankte dem oppositionellen p\u00e1rbesz\u00e9d-Abgeordneten T\u00edmea Szab\u00f3, der urspr\u00fcnglich vorgeschlagen hatte, die Wahl und das Referendum am selben Tag abzuhalten.<\/span><\/div>\n<div>&nbsp;<\/div>\n<blockquote>\n<div><span style=\"color: initial;\">Guly\u00e1s sagte, dass in beiden Wahlg\u00e4ngen \u00e4u\u00dferst wichtige Themen auf dem Spiel st\u00fcnden, und die Regierung bittet alle, ihre Meinung nicht nur bei den Parlamentswahlen, sondern auch beim Referendum zu \u00e4u\u00dfern.<\/span><\/div>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Ungarns Regierung habe beschlossen, die Quarant\u00e4nezeiten f\u00fcr positiv auf Covid getestete Personen zu verk\u00fcrzen, sagte der Stabschef des Premierministers am Donnerstag. &nbsp; Erwachsene m\u00fcssen sich sieben Tage lang selbst isolieren und d\u00fcrfen die Quarant\u00e4ne nach f\u00fcnf Tagen verlassen, wenn sie beschwerdefrei sind und einen negativen Covid-Test vorlegen, sagte Gergely Gulyas in einer regelm\u00e4\u00dfigen Pressekonferenz. &nbsp; [&hellip;]<\/p>\n","protected":false},"author":50,"featured_media":692459,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"yes","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1098],"tags":[2243,1778,1107,1467,1102,1076],"class_list":["post-692458","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gesellschaft","tag-coronavirus","tag-coronavirus-in-ungarn","tag-gesundheit","tag-nutzliches-dnh","tag-ungarische-regierung","tag-ungarn"],"blocksy_meta":[],"acf":[],"author_username":"dnh","telegram_post":"","public_post_metadata":{"breaking_news":"yes","important":"no","csempe":"no","center_tile":"no","disable_thumbnail":"no","target_lang":"","_featured_image_style":"hidden","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"Die ungarische Regierung habe beschlossen, die Quarant\u00e4nezeiten f\u00fcr Menschen zu verk\u00fcrzen, die positiv auf Covid getestet wurden, sagte Gergely Guly\u00e1s heute.","focus_keyword":"Regierungsquarant\u00e4ne","canonical_url":"","robots":"","primary_category":"1098","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"11","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/692458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/50"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=692458"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/692458\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/692459"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=692458"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=692458"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=692458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}