{"id":694139,"date":"2025-05-02T18:34:00","date_gmt":"2025-05-02T16:34:00","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/gute-nachrichten-aus-dem-ungarischen-tourismussektor\/"},"modified":"2025-05-02T18:34:00","modified_gmt":"2025-05-02T16:34:00","slug":"gute-nachrichten-aus-dem-ungarischen-tourismussektor","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/gute-nachrichten-aus-dem-ungarischen-tourismussektor\/","title":{"rendered":"Gute Nachrichten aus dem ungarischen Tourismussektor"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong>W\u00e4hrend der Schulferien vom 17. bis 27. April wurden 664.000 Besucher in den touristischen Beherbergungsbetrieben gez\u00e4hlt, 36 Prozent mehr als in den Fr\u00fchjahrsferien des Vorjahres, teilte Visit Hungary am Mittwoch mit.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Davon entfielen 338.000 auf einheimische Reisende, 27 % mehr als im Vorjahr. Die Zahl der G\u00e4ste\u00fcbernachtungen stieg um 25 % auf rund 1,5 Millionen. Die H\u00e4lfte davon wurde von ausl\u00e4ndischen Touristen verbracht. Die Beherbergungs- und Gastronomiebetriebe erwirtschafteten w\u00e4hrend der Schulferien einen Umsatz von mehr als 100 Milliarden Forint. Die Einnahmen der Beherbergungsbetriebe stiegen um 32 % auf 37,1 Mrd. HUF.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lesen Sie auch:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Spatenstich f\u00fcr das Terminal 3 des Budapester Flughafens im Rahmen einer ehrgeizigen \u00dcberholung des Luftverkehrs &#8211; mehr dazu <strong><a href=\"https:\/\/dailynewshungary.com\/de\/budapest-airports-terminal-3-to-break-ground-this-year-among-ambitious-aviation-overhaul\/\">HIER<\/a><\/strong><\/li>\n\n\n\n<li>Das Ende einer \u00c4ra: Wizz Air erh\u00f6ht die Preise deutlich &#8211; 10-15 EUR-Tickets verschwinden, mehr dazu <strong><a href=\"https:\/\/dailynewshungary.com\/de\/ende-einer-ara-wizz-air-erhoht-deutlich-die-preise-tickets-fur-10-15-eur-verschwinden\/\">HIER <\/a><\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Titelbild: <a href=\"https:\/\/depositphotos.com\/photos\/budapest-tourism.html?filter=all&amp;qview=363499764\" target=\"_blank\" rel=\"noopener\">depositphotos.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>W\u00e4hrend der Schulferien vom 17. bis 27. April wurden 664.000 Besucher in den touristischen Beherbergungsbetrieben gez\u00e4hlt, 36 Prozent mehr als in den Fr\u00fchjahrsferien des Vorjahres, teilte Visit Hungary am Mittwoch mit. Davon entfielen 338.000 auf einheimische Reisende, 27 % mehr als im Vorjahr. Die Zahl der G\u00e4ste\u00fcbernachtungen stieg um 25 % auf rund 1,5 Millionen. [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":694140,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"yes","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1101],"tags":[1138,1079,1076],"class_list":["post-694139","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-flashnews","tag-statistik","tag-tourismus","tag-ungarn"],"blocksy_meta":[],"acf":[],"author_username":"ugyelet","telegram_post":"","public_post_metadata":{"breaking_news":"yes","important":"no","csempe":"no","center_tile":"no","disable_thumbnail":"no","target_lang":"","_featured_image_style":"hidden","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"W\u00e4hrend der Schulferien vom 17. bis 27. April verzeichneten die Tourismusbetriebe 664.000 Besucher, das sind 36 Prozent mehr als in den Fr\u00fchjahrsferien des Vorjahres.","focus_keyword":"tourism","canonical_url":"","robots":"","primary_category":"1101","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"76","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/694139","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=694139"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/694139\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/694140"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=694139"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=694139"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=694139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}