{"id":696635,"date":"2021-11-21T17:00:00","date_gmt":"2021-11-21T16:00:00","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/die-meisten-lander-weltweit-und-in-der-ceeca-region-bestehen-laut-neuem-index-den-drogenpolitiktest-nicht\/"},"modified":"2021-11-21T17:00:00","modified_gmt":"2021-11-21T16:00:00","slug":"die-meisten-lander-weltweit-und-in-der-ceeca-region-bestehen-laut-neuem-index-den-drogenpolitiktest-nicht","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/die-meisten-lander-weltweit-und-in-der-ceeca-region-bestehen-laut-neuem-index-den-drogenpolitiktest-nicht\/","title":{"rendered":"Die meisten L\u00e4nder weltweit und in der CEECA-Region bestehen laut neuem Index den Drogenpolitiktest nicht"},"content":{"rendered":"<p><strong>Das allererste Instrument zur Rechenschaftspflicht bewertet und bewertet die Drogenpolitik der L\u00e4nder anhand wichtiger Empfehlungen des UN-Systems<\/strong><\/p>\n<p>Norwegen, Neuseeland, Portugal, das Vereinigte K\u00f6nigreich und Australien sind laut der ersten Ausgabe des Jahres die f\u00fcnf f\u00fchrenden L\u00e4nder in Bezug auf humane und gesundheitsorientierte Drogenpolitik <a href=\"http:\/\/www.globaldrugpolicyindex.net\/\" target=\"_blank\" rel=\"noopener\">Globaler Index der Drogenpolitik<\/a>&nbsp;Heute vom Harm Reduction Consortium ver\u00f6ffentlicht. Brasilien, Uganda, Indonesien, Kenia und Mexiko sind die f\u00fcnf L\u00e4nder mit dem niedrigsten Rang.<\/p>\n<p>Norwegen schaffte jedoch trotz der Spitze des Index immer noch nur einen Wert von 74\/100. Und der Medianwert \u00fcber alle 30 L\u00e4nder und Dimensionen betr\u00e4gt gerade einmal 48\/100.<\/p>\n<p>\u201c48 von 100 ist ein Versagen der Drogenpolitik in irgendjemandem, sagte \u201e&nbsp;<strong>Ann Fordham<\/strong>Gesch\u00e4ftsf\u00fchrer des&nbsp;<a href=\"https:\/\/idpc.net\/\" target=\"_blank\" rel=\"noopener\">Konsortium f\u00fcr internationale Drogenpolitik<\/a>&nbsp;Dies f\u00fchrte zur Entwicklung des Index mit den Partnern des Harm Reduction Consortium.<\/p>\n<p>\u201cKeines der bewerteten L\u00e4nder sollte sich mit seinem Score in der Drogenpolitik gut f\u00fchlen, denn kein Land hat einen perfekten Score erreicht Oder auch nur ann\u00e4hernd Dieser Index verdeutlicht den riesigen Verbesserungspotential auf breiter Front\u201d<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/globaldrugpolicyindex.net\/map\" target=\"_blank\" rel=\"noopener\"><strong>Die interaktive Karte des Global Drug Policy Index<\/strong><\/a><\/p>\n<p>Seit Jahrzehnten ist es ein schwer fassbares Unterfangen, zu verfolgen, wie gut oder schlecht es den Regierungen in der Drogenpolitik geht. Dies liegt nicht zuletzt daran, dass die Datenerhebungsbem\u00fchungen sowohl der Regierungen als auch der Vereinten Nationen von dem veralteten und sch\u00e4dlichen politischen Ziel angetrieben wurden, eine \u201edrogenfreie Gesellschaft&#8217; zu erreichen<\/p>\n<p>Die meisten Regierungen verfolgen weiterhin einen repressiven Ansatz bei der Drogenkontrolle, der auf diesen verzerrten Daten basiert, was wiederum bedeutet, dass sie nicht f\u00fcr den Schaden verantwortlich gemacht werden k\u00f6nnen, den ihre Politik dem Leben so vieler Menschen zuf\u00fcgt.<\/p>\n<p>Der Erfolg der Drogenpolitik wurde nicht an den Ergebnissen in den Bereichen Gesundheit, Entwicklung und Menschenrechte gemessen, sondern tendierte stattdessen dazu, Indikatoren wie die Zahl der wegen Drogendelikten festgenommenen oder inhaftierten Personen, die Menge der beschlagnahmten Drogen oder die Zahl der Hektar zu priorisieren des Drogenanbaus ausgerottet.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/dailynewshungary.com\/de\/internationale-pharmakonferenz-ddrs-2021-wird-in-budapest-eroffnet\/\"><strong>Internationale Pharmakonferenz DDRS 2021 wird in Budapest er\u00f6ffnet<\/strong><\/a><\/p>\n<p>Der Global Drug Policy Index ist die erste datengesteuerte globale Analyse der Drogenpolitik und ihrer Umsetzung. Er besteht aus 75 Indikatoren, die sich \u00fcber f\u00fcnf gro\u00dfe Dimensionen der Drogenpolitik erstrecken: Strafjustiz, extreme Reaktionen, Gesundheit und Schadensminderung, Zugang zu international kontrollierten Medikamenten und Entwicklung.<\/p>\n<p>\u201cDer Global Drug Policy Index ist nichts weniger als eine radikale Innovation, sagte&nbsp;<strong>Helen Clark<\/strong>, Vorsitzender der Globalen Kommission f\u00fcr Drogenpolitik und ehemaliger Premierminister Neuseelands.<\/p>\n<p>\u201cGute, genaue Daten sind Macht, und sie k\u00f6nnen uns helfen, den 1-War on drugs&#8217; eher fr\u00fcher als sp\u00e4ter zu beenden.\u201d<\/p>\n<p>\u201cAus den Ergebnissen geht klar hervor, dass keine Regierung selbstgef\u00e4llig sein kann\u201d, sagte&nbsp;<strong>Julita Lemgruber<\/strong>\u201cAuch in den h\u00f6chsten L\u00e4ndern ist Fortschritt bitter n\u00f6tig, ehemaliger Direktor des Gef\u00e4ngnissystems des Staates Rio de Janeiro\u201d Regierungen weltweit m\u00fcssen die Idee der Drogenpolitik als Instrumente des \u201cKriegs\u201d aufgeben und sie als Mittel zur F\u00f6rderung der Menschenrechte und der Staatsb\u00fcrgerschaft verstehen.\u201d<\/p>\n<p style=\"text-align: center;\"><strong><a href=\"https:\/\/dailynewshungary.com\/de\/wo-kann-man-die-sauberste-und-schadlichste-luft-der-welt-atmen-karte\/\">Wo kann man die sauberste und sch\u00e4dlichste Luft der Welt atmen? \u2013 KARTE<\/a><\/strong><\/p>\n<p><strong>In der gesamten CEECA-Region<\/strong>(die f\u00fcnf in dieser ersten Fassung des Index untersuchten L\u00e4nder &#8211; Georgien (55\/100), Ungarn (50\/100), Kirgisistan (50\/100), Nordmazedonien (55\/100), die Russische F\u00f6deration (41\/1100) (alle haben niedrig abgeschnitten Das Ziel von 100\/100 ist ein Mindeststandard f\u00fcr eine wirksame gesundheitliche Reaktion auf Drogen.<\/p>\n<p>\u201eDer Index wird in Zukunft auf andere L\u00e4nder der Region ausgeweitet, aber das Bild zeichnet sich bereits eindeutig durch unverh\u00e4ltnism\u00e4\u00dfige strafrechtliche Reaktionen, eine ungleiche Anwendung der Drogengesetze und einen fehlenden Zugang sowohl zu Schadensminderung als auch zu Medikamenten zur Schmerzkontrolle ab.\u201cund Palliativversorgung. Im Vergleich zu den Standards und Empfehlungen der Vereinten Nationen ist dies nicht gut genug\u201d \u201eZusammenfassung der Situation in der Region Prof.&nbsp;<strong>Michel Kazatchkine<\/strong>&nbsp;und&nbsp;<strong>Pavel Bem<\/strong>, Mitglieder der Global Commission on Drug Policy aus der CEECA-Region.<\/p>\n<p>Die erste Iteration des Index bewertet die Leistung von 30 L\u00e4ndern, die alle Regionen der Welt abdecken, und wird durch reale Geschichten, auch von Menschen, die Drogen konsumieren, aus der ganzen Welt veranschaulicht.<\/p>\n<p>Die Ergebnisse des Index spiegeln Folgendes wider:<\/p>\n<ul>\n<li><strong>Der militarisierte und strafrechtliche Ansatz zur Drogenkontrolle setzt sich weiterhin durch:&nbsp;<\/strong>In der H\u00e4lfte der untersuchten L\u00e4nder wurde ein gewisses Ma\u00df an t\u00f6dlicher Gewaltanwendung durch Milit\u00e4r- oder Polizeikr\u00e4fte gemeldet, wobei die F\u00e4lle in Mexiko und Brasilien weit verbreitet waren.<\/li>\n<li><strong>Die unverh\u00e4ltnism\u00e4\u00dfigen Auswirkungen der Drogenkontrolle auf marginalisierte Menschen aufgrund von Geschlecht, ethnischer Zugeh\u00f6rigkeit und sozio\u00f6konomischem Status<\/strong>&nbsp;Wurde in gewissem Umfang \u00fcber alle Dimensionen und \u00fcber alle L\u00e4nder hinweg gemeldet.<\/li>\n<li><strong>Die Drogenbek\u00e4mpfung zielt in erster Linie auf gewaltfreie Straftaten ab, insbesondere auf Menschen, die Drogen konsumieren:&nbsp;<\/strong>Nur 8 der 30 befragten L\u00e4nder haben Drogenkonsum und -besitz entkriminalisiert, und von diesen gelang es nur 3, die Menschen wirklich vom Strafjustizsystem abzulenken.<\/li>\n<li><strong>Die Finanzierungsl\u00fccke zur Schadensminderung ist nach wie vor \u00e4u\u00dferst besorgniserregend:<\/strong>&nbsp;Nur 5 von 30 L\u00e4ndern haben \u201eausreichende&#8217; Mittel zur Schadensminderung bereitgestellt, und von diesen L\u00e4ndern gilt die Finanzierung nur in einem (Norwegen) als sicher.<\/li>\n<li><strong>Es besteht eine gro\u00dfe L\u00fccke zwischen der Regierungspolitik und ihrer Umsetzung zur Gew\u00e4hrleistung des Zugangs zu kontrollierten Arzneimitteln<\/strong>, insbesondere in L\u00e4ndern wie Indien, Indonesien, Mexiko und Senegal, die in der Politik hohe Werte erzielen, aber 0\/100 f\u00fcr die tats\u00e4chliche Verf\u00fcgbarkeit f\u00fcr Bed\u00fcrftige erreichen.<\/li>\n<li><strong>Alternative Entwicklungsprogramme in Gebieten mit illegalem Anbau sind nach wie vor in Verboten und Ausrottung verankert<\/strong>, wobei Kolumbien aufgrund seiner militarisierten Strategie, die sich auf die Zwangsausrottung und den sch\u00e4dlichen Einsatz von Luftspritzen konzentriert, besonders niedrig abschneidet (23\/100).<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Das allererste Instrument zur Rechenschaftspflicht bewertet und bewertet die Drogenpolitik der L\u00e4nder anhand wichtiger Empfehlungen des UN-Systems Norwegen, Neuseeland, Portugal, das Vereinigte K\u00f6nigreich und Australien sind laut der ersten Ausgabe des Jahres die f\u00fcnf f\u00fchrenden L\u00e4nder in Bezug auf humane und gesundheitsorientierte Drogenpolitik Globaler Index der Drogenpolitik&nbsp;Heute vom Harm Reduction Consortium ver\u00f6ffentlicht. Brasilien, Uganda, Indonesien, [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":696636,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"yes","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1154],"tags":[1346,1107,1108,1138],"class_list":["post-696635","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-welt","tag-drogen","tag-gesundheit","tag-gesundheitssystem","tag-statistik"],"blocksy_meta":[],"acf":[],"author_username":"ugyelet","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"hidden","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"Der Global Drug Policy Index ist die erste datengesteuerte globale Analyse der Drogenpolitik und ihrer Umsetzung.","focus_keyword":"Drogenpolitik","canonical_url":"","robots":"","primary_category":"1154","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"75","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/696635","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=696635"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/696635\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/696636"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=696635"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=696635"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=696635"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}