{"id":698391,"date":"2021-09-24T18:30:00","date_gmt":"2021-09-24T16:30:00","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/regierung-balkanstaaten-soll-geholfen-werden-mitglied-der-eu-zu-werden\/"},"modified":"2021-09-24T18:30:00","modified_gmt":"2021-09-24T16:30:00","slug":"regierung-balkanstaaten-soll-geholfen-werden-mitglied-der-eu-zu-werden","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/regierung-balkanstaaten-soll-geholfen-werden-mitglied-der-eu-zu-werden\/","title":{"rendered":"Regierung: Balkanstaaten soll geholfen werden, Mitglied der EU zu werden"},"content":{"rendered":"<p><strong>Der Balkan werde wahrscheinlich \u201cdie n\u00e4chste gro\u00dfe Chance\u201d f\u00fcr die Europ\u00e4ische Union darstellen, und die Region k\u00f6nnte zum n\u00e4chsten Wirtschaftsmotor des Blocks werden, sagte Ministerpr\u00e4sident Viktor Orb\u00e1n am Freitag in einer Ansprache vor der Konferenz der Parlamentspr\u00e4sidenten der Visegr\u00e1d-Gruppe und S\u00fcdosteuropasDie V4 &#8211; und Balkanl\u00e4nder k\u00f6nnten am Ende gemeinsam den bedeutendsten Wirtschaftsraum des gesamten europ\u00e4ischen Kontinents aufbauen, sagte er.<\/strong><\/p>\n<p>\u201cWenn die Balkanstaaten eine Chance bekommen, so wie es die Visegr\u00e1d-L\u00e4nder getan haben, werden sie innerhalb weniger Jahre an Fahrt aufnehmen, ihre Wirtschaft und ihr reales Wachstum st\u00e4rken und der wirtschaftliche Fortschritt wird aus dem Balkan in die EU kommen\u201d, sagte er.<\/p>\n<blockquote>\n<p>Die EU-Mitgliedschaft der Balkanl\u00e4nder liegt noch mehr im Interesse der EU<\/p>\n<\/blockquote>\n<p>Umgekehrt, nicht nur aus Sicherheitsgr\u00fcnden, sondern auch im Hinblick auf westliche Wirtschaftsinteressen, f\u00fcgte er hinzu.<\/p>\n<p>\u201cWenn sie nicht in der Lage sind, die Vitalit\u00e4t und Bem\u00fchungen des Balkans in die EU-Wirtschaft zu lenken, werden sie eine gro\u00dfe Chance verpassen\u201d, sagte er und ermutigte die Balkanl\u00e4nder, ihre Forderungen nach einer EU-Mitgliedschaft mit \u201ch\u00f6chstem Selbstvertrauen\u201d zu pr\u00e4sentieren. Orb\u00e1n sagte, wenn die Vorg\u00e4nger der derzeitigen westlichen Staats- und Regierungschefs den Schritt zur Erweiterung nicht getan h\u00e4tten, w\u00e4re die EU heute viel schw\u00e4cher. Denn, f\u00fcgte er hinzu, dass zus\u00e4tzliches Wachstum und Leistung derzeit aus Mitteleuropa k\u00e4men.<\/p>\n<p>Wenn die mitteleurop\u00e4ischen L\u00e4nder heute nicht Mitglieder der EU w\u00e4ren, w\u00e4re der Lebensstandard im Westen viel niedriger als sie sind, sagte Orb\u00e1nDer kombinierte Handel zwischen den L\u00e4ndern der Visegr\u00e1d-Gruppe und Deutschland ist doppelt so hoch wie der von Frankreich-Deutschland und dreimal der Handel zwischen Italien und Deutschland, f\u00fcgte er hinzu \u201cEs ist keine \u00dcbertreibung zu sagen, dass die deutsche Wirtschaft ohne Mitteleuropa zusammenbrechen w\u00fcrde\u201d, sagte er.<\/p>\n<p>Orb\u00e1n sagte, der Weg in die EU f\u00fcr die V\u00f6lker des Balkans f\u00fchre durch Mitteleuropa.<\/p>\n<blockquote>\n<p>Die L\u00e4nder des Balkans sollten nicht zu einer Pufferzone gemacht, sondern in den Block integriert werden<\/p>\n<\/blockquote>\n<p>Er f\u00fcgte hinzuSo stark der f\u00fcr die Erweiterung zust\u00e4ndige Kommissar auch daran arbeitet, die wirkliche Integration des Balkans erfordert politische und strategische Entscheidungen, die nicht von den Kommissaren getroffen werden, und nicht einmal von der Europ\u00e4ischen Kommission, sondern vom Europ\u00e4ischen Rat, der sich aus den Premierministern und Pr\u00e4sidenten der europ\u00e4ischen L\u00e4nder zusammensetzt, sagte Orb\u00e1n.<\/p>\n<div style=\"text-align: center;\"><a href=\"https:\/\/dailynewshungary.com\/de\/rede-des-ministers-in-der-uno-ungarn-wird-jede-art-von-migrantenquotensystemen-ablehnen\/\">Rede des Ministers in der UNO: Ungarn wird jede Art von Migrantenquotensystemen ablehnen<\/a><\/div>\n<p>\u201cSolange sie sich nicht f\u00fcr eine Integration des Balkans entscheiden, werden wir Teil eines sich kontinuierlich ausweitenden Prozesses sein, in dem wir uns im Detail verlieren, wobei Regulierungsfragen im Fokus stehen statt strategische Angelegenheiten; und eigentlich geht es nur darum, auf Zeit zu spielen\u201d, f\u00fcgte er hinzu.<\/p>\n<blockquote>\n<p>Orb\u00e1n sagte, den westeurop\u00e4ischen Staats- und Regierungschefs fehle derzeit der Wille zur weiteren Erweiterung<\/p>\n<\/blockquote>\n<p>Was, f\u00fcgte er hinzu, ein \u201cschwerer Fehler\u201d sei Gleichzeitig habe Mitteleuropa es kontinuierlich und beharrlich unterst\u00fctzt, stellte er festDer Premierminister schlug vor, dass die V4- und Balkanl\u00e4nder gemeinsam die bedeutendste Wirtschaftsregion Europas als Ganzes entwickeln sollten.<\/p>\n<p>\u201cWir haben eine Chance dazu, und &#8230; es wird der Moment kommen, in dem die Balkanl\u00e4nder f\u00fcr die europ\u00e4ische Wirtschaft genauso entscheidend sein werden, wie es die V4-L\u00e4nder bereits sind\u201d, sagte Orb\u00e1nDiesem Sinne sollten diese Nationen zun\u00e4chst der Europ\u00e4ischen Union beitreten, sich \u00fcber den mitteleurop\u00e4ischen Raum integrieren und sich f\u00fcr die deutsche, italienische und franz\u00f6sische Wirtschaft unverzichtbar machen, sagte er.<\/p>\n<p>Die V4-L\u00e4nder betrachten den Balkan nicht nur als wirtschaftliches Ziel, sondern auch als strategische Chance, die Sicherheit bietet und dazu beitr\u00e4gt, Europas sich am dynamischsten entwickelnde Region zu erweitern, sagte Orb\u00e1n.<\/p>\n<blockquote>\n<p>\u201cWir wollen, dass Eisenbahnen, Br\u00fccken und Stra\u00dfen entstehen, um unsere Energieversorgungsnetze zu verbinden, um<\/p>\n<\/blockquote>\n<p>und sehen Sie, dass die Balkanl\u00e4nder nicht nur ausl\u00e4ndische Investitionen erhalten, sondern auch wettbewerbsf\u00e4hige Produkte herstellen und dann als Investoren zu uns kommen, sagte er.<\/p>\n<p>Parlamentspr\u00e4sident L\u00e1szl\u00f3 K\u00f6v\u00e9r sagte, dass in den letzten drei Jahrzehnten<\/p>\n<blockquote>\n<p>25 Millionen Arbeitnehmer hatten die Region der baltischen Staaten auf dem Balkan verlassen und waren auf dem Weg nach Westeuropa, weitere 20 Millionen sollten bis 2050 folgen.<\/p>\n<\/blockquote>\n<p>Unter Berufung auf Sch\u00e4tzungen sagte er: \u201cAuf diese Weise hat unsere Region das Wohlergehen Westeuropas in H\u00f6he von 1.000 Milliarden Euro finanziert\u201d \u201cDaher haben alle L\u00e4nder in der Region das Recht, selbstbewusst zu sein, wenn sie von Br\u00fcssel erpresst werden, wie es der Fall ist, wenn es um das geht, was die EU als Unterst\u00fctzung bezeichnet, oder um die Post-Pandemie-Wiederaufbaufonds, die Polen und Ungarn zustehen, sagte Kover.<\/p>\n<p>Der f\u00fcr Nachbarschaft und Erweiterung zust\u00e4ndige Kommissar Oliver Varhelyi sagte zu dem Ereignis, dass die L\u00e4nder des westlichen Balkans einen Platz in der EU h\u00e4tten Niemand m\u00fcsse mehr davon \u00fcberzeugt werden, dass der Beitritt des westlichen Balkans eine soziale, wirtschaftliche, geografische und historische Realit\u00e4t und politische Notwendigkeit sei, f\u00fcgte er hinzuDamit dieser Anerkennung Taten folgen m\u00fcssen, sagte erDie EG in ihrer derzeitigen Zusammensetzung unterst\u00fctzt die EU-Erweiterung um den westlichen Balkan und bietet der Region eine echte Integration, f\u00fcgte er hinzu.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Balkan werde wahrscheinlich \u201cdie n\u00e4chste gro\u00dfe Chance\u201d f\u00fcr die Europ\u00e4ische Union darstellen, und die Region k\u00f6nnte zum n\u00e4chsten Wirtschaftsmotor des Blocks werden, sagte Ministerpr\u00e4sident Viktor Orb\u00e1n am Freitag in einer Ansprache vor der Konferenz der Parlamentspr\u00e4sidenten der Visegr\u00e1d-Gruppe und S\u00fcdosteuropasDie V4 &#8211; und Balkanl\u00e4nder k\u00f6nnten am Ende gemeinsam den bedeutendsten Wirtschaftsraum des gesamten europ\u00e4ischen [&hellip;]<\/p>\n","protected":false},"author":50,"featured_media":698392,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"no","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1081],"tags":[1243,1082,1658,1076,1128,1923],"class_list":["post-698391","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politik","tag-balkan","tag-europaische-union","tag-parlament","tag-ungarn","tag-viktor-orban","tag-visegrad-vier"],"blocksy_meta":[],"acf":[],"author_username":"dnh","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"hidden","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"","focus_keyword":"","canonical_url":"","robots":"","primary_category":"1081","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/698391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/50"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=698391"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/698391\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/698392"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=698391"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=698391"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=698391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}