{"id":700386,"date":"2021-07-14T07:25:00","date_gmt":"2021-07-14T05:25:00","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/fidesz-fordert-karacsony-auf-die-ausschreibung-fur-die-beschaffung-von-donaubooten-zu-untersuchen\/"},"modified":"2021-07-14T07:25:00","modified_gmt":"2021-07-14T05:25:00","slug":"fidesz-fordert-karacsony-auf-die-ausschreibung-fur-die-beschaffung-von-donaubooten-zu-untersuchen","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/fidesz-fordert-karacsony-auf-die-ausschreibung-fur-die-beschaffung-von-donaubooten-zu-untersuchen\/","title":{"rendered":"Fidesz fordert Kar\u00e1csony auf, die Ausschreibung f\u00fcr die Beschaffung von Donaubooten zu untersuchen"},"content":{"rendered":"<p><strong>Ungarns regierender Fidesz hat den Budapester B\u00fcrgermeister Gergely Kar\u00e1csony aufgefordert, eine Untersuchung des \u00f6ffentlichen Vergabeverfahrens des Donaubootdienstes der Budapester Verkehrsbetriebe anzuordnen.<\/strong><\/p>\n<p>Zsolt Wintermantel, das Fidesz-delegierte Mitglied in der Budapester Verkehrsbeh\u00f6rde BKK, sagte am Dienstag in einem Facebook-Video, dass die \u00f6ffentliche Vergabeausschreibung f\u00fcr einen Betreiber des Donau-Bootsdienstes \u201c\u00e4hnliche Verdachtsmomente wie um\u201d die Busleasing-Vereinbarungen des Verkehrsunternehmens BKV aufwirft.<\/p>\n<blockquote>\n<p>\u201cNat\u00fcrlich leugnen BKV und B\u00fcrgermeister alles und sagen das Gleiche, was sie vor einem halben Jahr zur Busausschreibung gesagt haben: dass es hier &#8216;nichts zu sehen&#8217; gibt\u201d, sagte Wintermantel.<\/p>\n<\/blockquote>\n<p>Er forderte Kar\u00e1csony auf, eine umfassende Untersuchung der Ausschreibung anzuordnen und BKV die Unterzeichnung etwaiger Vereinbarungen bis zum Abschluss der Untersuchung zu verbieten.<\/p>\n<ul>\n<li><a href=\"https:\/\/dailynewshungary.com\/de\/mit-einem-kreuzer-auf-der-donau-kommt-ihr-ab-diesem-donnerstag-nach-ungarn\/\" target=\"_blank\" rel=\"noopener noreferrer\">Mit einem Kreuzer auf der Donau kann man nach Ungarn kommen<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Ungarns regierender Fidesz hat den Budapester B\u00fcrgermeister Gergely Kar\u00e1csony aufgefordert, eine Untersuchung des \u00f6ffentlichen Vergabeverfahrens des Donaubootdienstes der Budapester Verkehrsbetriebe anzuordnen. Zsolt Wintermantel, das Fidesz-delegierte Mitglied in der Budapester Verkehrsbeh\u00f6rde BKK, sagte am Dienstag in einem Facebook-Video, dass die \u00f6ffentliche Vergabeausschreibung f\u00fcr einen Betreiber des Donau-Bootsdienstes \u201c\u00e4hnliche Verdachtsmomente wie um\u201d die Busleasing-Vereinbarungen des Verkehrsunternehmens BKV [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":700387,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1281],"tags":[1111,1569,1531,1091],"class_list":["post-700386","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geschaft","tag-budapest","tag-budapest-rat","tag-danube","tag-fidesz"],"blocksy_meta":[],"acf":[],"author_username":"alk","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"","focus_keyword":"","canonical_url":"","robots":"","primary_category":"1281","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/700386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=700386"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/700386\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/700387"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=700386"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=700386"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=700386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}