{"id":702089,"date":"2021-05-24T10:30:00","date_gmt":"2021-05-24T08:30:00","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/derby-county-konnte-noch-absteigen\/"},"modified":"2021-05-24T10:30:00","modified_gmt":"2021-05-24T08:30:00","slug":"derby-county-konnte-noch-absteigen","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/derby-county-konnte-noch-absteigen\/","title":{"rendered":"Derby County k\u00f6nnte noch absteigen"},"content":{"rendered":"<p style=\"text-align: center;\"><span style=\"color: #808080;\"><em><strong>Gesponserte Inhalte<\/strong><\/em><\/span><\/p>\n<p><strong>Die Saison der englischen Premier League ist vorbei, die darunter liegenden Profi-Divisionen haben ihre komplette Spielpaarung ebenfalls absolviert Abgesehen von den stets dramatischen Playoffs stehen Auf &#8211; und Abstieg bereits fest Die Championship war die Liga, die man am letzten Spieltag der Saison beobachten konnte, wobei Derby County nach einer schrecklichen Form unter der Leitung des legend\u00e4ren ehemaligen englischen St\u00fcrmers Wayne Rooney in seiner ersten Managerrolle gegen den Abstieg k\u00e4mpfte Zun\u00e4chst schien es, dass der Verein seinen Meisterschaftsstand behalten w\u00fcrde <a href=\"https:\/\/www.mirror.co.uk\/sport\/football\/news\/derby-county-players-toast-championship-24067259\" target=\"_blank\" rel=\"noopener\">Mit einem Unentschieden gegen Sheffield Wednesday<\/a>. Nun ist die Position weitaus weniger klar.<\/strong><\/p>\n<p>Die ganze Saison \u00fcber wurde der Verein von finanziellen Problemen geplagt, vor einigen Monaten sollte eine \u00dcbernahme abgeschlossen werden, die den Rams neuen Besitz und neue finanzielle R\u00fcckendeckung geben w\u00fcrde, zum Zeitpunkt des Verfassens dieses Artikels noch immer nicht alle notwendigen Unterlagen sollen unterschrieben und eingereicht worden sein, doch der Deal wird aus Gr\u00fcnden aufgehalten, denen offenbar niemand auf den Grund gehen kann Inzwischen intensiviert sich die Pr\u00fcfung von Derbys Finanzen Am Montag, den 10<sup>th<\/sup> Mai, nur zwei Tage nach der Flucht des Vereins vor dem drohenden Abstieg, zeichnete sich f\u00fcr Derby-Fans eine erschreckende neue M\u00f6glichkeit ab. Obwohl sie gen\u00fcgend Punkte sammelten, um ihre Ligaposition zu behalten, <a href=\"https:\/\/www.dailymail.co.uk\/sport\/football\/article-9561583\/Derby-RELEGATED-Championship-EFL-won-appeal-against-FFP-rule-break.html\" target=\"_blank\" rel=\"noopener noreferrer\">Sie k\u00f6nnten noch untergehen<\/a> Dank einer potenziellen rechtlichen Anfechtung.<\/p>\n<p>Die Frage h\u00e4ngt von einer rechtlichen Anfechtung ab, die von der englischen Football League selbst angestrengt wurde, die festgestellt hat, dass Derby gegen die Regeln des Financial Fair Play verst\u00f6\u00dft Die Angelegenheit ging in Berufung, aber jetzt wurde ein Urteil zugunsten der EFL gef\u00e4llt Das l\u00e4sst der EFL die Freiheit, Sanktionen gegen Derby zu verh\u00e4ngen, und es wird gedacht, dass diese Sanktionen auf ihr Ansehen in dieser Saison angewendet werden k\u00f6nnten, im Gegensatz zur n\u00e4chsten Saison Die EFL hat hier mehrere Durchsetzungsm\u00f6glichkeiten Sie k\u00f6nnten eine Geldstrafe verh\u00e4ngen, einen Punktabzug verh\u00e4ngen oder beides tun Derby County blieb um einen Punkt oben Selbst der kleinste Punktabzug w\u00fcrde dazu f\u00fchren, dass sie absteigen w\u00fcrden (und das ist ein Interesse der Wycombe Wanderers, die einen Platz unter Derby-Abstieg belegten und auf dem endg\u00fcltigen Platz landeten.<\/p>\n<blockquote>\n<p>Es wurde angenommen, dass die Angelegenheit im vergangenen August gekl\u00e4rt wurde, als die EFL zwei separate Anklagen gegen Derby wegen Versto\u00dfes gegen die FFP-Regeln erhob.<\/p>\n<\/blockquote>\n<p>Die Disziplinarkommission hat sie damals freigesprochen, aber die EFL war mit dem Urteil unzufriedenDie Sache rumpelte monatelang im Hintergrund herum, ist aber nun zum f\u00fcr den Verein und seine Fans zumindest g\u00fcnstigsten Zeitpunkt wieder aufgetauchtEs wird davon ausgegangen, dass die Berufung schlie\u00dflich wegen eines konkreten Versto\u00dfes gegen Regeln zur Spielerbewertung erfolgreich war, wobei sich herausstellte, dass Derbys Eigent\u00fcmer ein Verschulden trifft Der Amerikaner Mel Morris (der bis zum Durchlaufen der \u00dcbernahme Eigent\u00fcmer von Derby County bleibt, hat die Wertminderung des Spielerverm\u00f6gens in den j\u00fcngsten Konten des Vereins nicht ber\u00fccksichtigt. Der Nettoeffekt bestand darin, die Verluste zu verschleiern oder zu beseitigen, die sonst in den letzten drei Jahren etwa drei\u00dfig Millionen Pfund an Verlusten betragen h\u00e4tten.<\/p>\n<blockquote>\n<p>Sollte Derby absteigen, k\u00f6nnte die gesamte \u00dcbernahme gef\u00e4hrdet sein.<\/p>\n<\/blockquote>\n<p>Die vorgeschlagenen K\u00e4ufer des Vereins glauben derzeit, eine Mannschaft in der Championship gekauft zu haben Eine Mannschaft in der League One, zwei Divisionen unterhalb des versprochenen Landes der Premier League, w\u00e4re ein ganz anderes und weitaus weniger attraktives Angebot. Erik Alonso, der spanische Gesch\u00e4ftsmann, der das Amt \u00fcbernehmen wird, k\u00f6nnte die Gelegenheit nutzen, sein Interesse zur\u00fcckzuziehen, wenn sich herausstellt, dass der Abstieg das Ergebnis dieses langwierigen Prozesses ist. Das w\u00fcrde Derby unter enormem finanziellen Druck und einer ungewissen Zukunft zur\u00fccklassen. Das haben wir schon einmal bei ehemaligen englischen Premier-League-Teams erlebt, die nach dem Abstieg Probleme hatten, wobei Portsmouth und Bolton Wanderers die bekanntesten der j\u00fcngsten Beispiele sind.<\/p>\n<p>All dies ist ironisch f\u00fcr ein Unternehmen, das erst vor zwei Jahren die Unterst\u00fctzung eines hochkar\u00e4tigen Online-Slots-Unternehmens hochhob. Tats\u00e4chlich waren es das Gl\u00fccksspiel- und Online-Slots-Geld, das dazu f\u00fchrte, dass Wayne Rooney als Spieler zum Club kam Seine R\u00fcckennummer entsprach dem Namen des betreffenden Online-Slots-Unternehmens, was sich damals als m\u00f6glicher Versto\u00df gegen die Gl\u00fccksspielbestimmungen als umstritten erwies. Eine \u00dcbernahme von Derby mit drohendem Abstieg \u00fcber dem Club abzuschlie\u00dfen, w\u00e4re ein gr\u00f6\u00dferes Gl\u00fccksspiel, als Sie jemals bei Rose Slots NZ finden w\u00fcrden. Jeder Spieler verliert gelegentlich, obwohl \u201eeine Tatsache des Hobbys, dass jeder Online-Slots-Spieler bereits mit \u201eDerby-Inhaber und beide&#8221; vertraut sein k\u00f6nnte.<\/p>\n<p>Die Lage des Landes in seiner jetzigen Form ist derzeit unklar. Die EFL wei\u00df, dass sie auf Fan-Wut sto\u00dfen wird, wenn sie einen Punkteabzug vorschreibt, der Derby absteigen l\u00e4sst, aber gesehen werden muss, um ihre eigenen Regeln durchzusetzen. Das gilt insbesondere, nachdem sie so hart darum gek\u00e4mpft hat, dass ihre Ergebnisse \u00fcberhaupt best\u00e4tigt werden. Die Wycombe Wanderers erw\u00e4gen bereits, eine separate rechtliche Anfechtung einzureichen, in der sie sich auf die Ungerechtigkeit berufen, dass Derby an ihrem Platz bleibt, nachdem er f\u00fcr schuldig befunden wurde, gegen so wichtige Regeln versto\u00dfen zu haben. Nachdem sie das Berufungsverfahren bereits durchlaufen haben, sind sich die meisten Analysten einig, dass Derby nicht in der Lage ist, das Urteil anzufechten. Es ist wahrscheinlich, dass die FIFA \u00fcberhaupt in die Angelegenheit verwickelt wird oder sogar auf die UEFA fallen k\u00f6nnte.<\/p>\n<p>Zwar sollte kein Verein mit Regelverst\u00f6\u00dfen durchkommen, die alle anderen einhalten m\u00fcssen, doch w\u00e4re dies f\u00fcr die Fans von Derby County eine enorme Schande, erst vor zwei Spielzeiten verpassten sie mit Pech den Aufstieg in die Premier League unter der Leitung von Frank Lampard, nun stehen sie unverschuldet am Rande einer Katastrophe, mit einem an der Spitze k\u00e4mpfenden Rookie-Manager und v\u00f6lliger Unbest\u00e4ndigkeit hinter den KulissenWas auch immer die EFL anpacken muss, muss schnell in Angriff genommen werden Sowohl Derby als auch Wycombe m\u00fcssen mit den Vorbereitungen f\u00fcr die n\u00e4chste Saison beginnen, und zu wissen, in welcher Division sie antreten werden, ist ein enormer Teil davon Die finanziellen Kosten des Abstiegs sind auch au\u00dferhalb der Premier League betr\u00e4chtlich, und die Budgets werden entsprechend festgelegt. F\u00fcr Derby kommt vielleicht noch schlimmer.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gesponserte Inhalte Die Saison der englischen Premier League ist vorbei, die darunter liegenden Profi-Divisionen haben ihre komplette Spielpaarung ebenfalls absolviert Abgesehen von den stets dramatischen Playoffs stehen Auf &#8211; und Abstieg bereits fest Die Championship war die Liga, die man am letzten Spieltag der Saison beobachten konnte, wobei Derby County nach einer schrecklichen Form unter [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":702090,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1154],"tags":[1218,1361],"class_list":["post-702089","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-welt","tag-fusball","tag-uk"],"blocksy_meta":[],"acf":[],"author_username":"alk","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"","focus_keyword":"","canonical_url":"","robots":"","primary_category":"1154","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/702089","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=702089"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/702089\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/702090"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=702089"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=702089"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=702089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}