{"id":702469,"date":"2021-05-14T17:32:00","date_gmt":"2021-05-14T15:32:00","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/vollstandig-geimpfte-menschen-konnen-ihre-masken-an-den-meisten-orten-in-den-usa-abwerfen\/"},"modified":"2021-05-14T17:32:00","modified_gmt":"2021-05-14T15:32:00","slug":"vollstandig-geimpfte-menschen-konnen-ihre-masken-an-den-meisten-orten-in-den-usa-abwerfen","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/vollstandig-geimpfte-menschen-konnen-ihre-masken-an-den-meisten-orten-in-den-usa-abwerfen\/","title":{"rendered":"Vollst\u00e4ndig geimpfte Menschen k\u00f6nnen ihre Masken an den meisten Orten in den USA abwerfen."},"content":{"rendered":"<p><strong>Die US-amerikanischen Zentren f\u00fcr die Kontrolle und Pr\u00e4vention von Krankheiten (CDC) haben am Donnerstag darauf hingewiesen, dass vollst\u00e4ndig geimpfte Menschen im Freien keine Masken tragen m\u00fcssen und das Tragen in Innenr\u00e4umen an den meisten Orten vermeiden k\u00f6nnen. Die aktualisierten Leitlinien der Beh\u00f6rde sagten, dass sie es erm\u00f6glichen werden, dass sich das Leben wieder normalisiert.<\/strong><\/p>\n<p>Das CDC, das hofft, dass die Leitlinien mehr Amerikaner dazu verleiten werden, sich impfen zu lassen, sagte au\u00dferdem, dass vollst\u00e4ndig geimpfte Menschen an den meisten Orten keine physische Distanz einhalten m\u00fcssen.<\/p>\n<p>Die Wende kam erst 16 Tage, seit CDC \u00fcberarbeitete Leitlinien herausgab, die viele Beschr\u00e4nkungen f\u00fcr geimpfte Personen vorsahen. Die Beh\u00f6rde geriet im M\u00e4rz in die Kritik, weil sie zun\u00e4chst geimpfte Gro\u00dfeltern davon abgehalten hatte, zu ihren Angeh\u00f6rigen zu fliegen.<\/p>\n<p>CDC-Direktorin Rochelle Walensky sagte, die neuen Leitlinien basierten auf einem starken R\u00fcckgang der F\u00e4lle, einer Ausweitung der Impfstoffe auf j\u00fcngere Menschen und der Wirksamkeit des Impfstoffs gegen Coronavirus-Varianten.<\/p>\n<blockquote>\n<p>\u201cWir sind hier der Wissenschaft gefolgt,\u201d Walensky.<\/p>\n<\/blockquote>\n<p>Pr\u00e4sident Joe Biden kam im Wei\u00dfen Haus zu Bemerkungen ohne Maske \u201cIch denke, es ist ein gro\u00dfer Meilenstein, ein gro\u00dfartiger Tag\u201d, sagte er.<\/p>\n<p>\u201cWenn Sie vollst\u00e4ndig geimpft sind und Ihre Maske abnehmen k\u00f6nnen, haben Sie sich das Recht verdient, etwas zu tun, wof\u00fcr die Amerikaner auf der ganzen Welt bekannt sind: andere mit einem L\u00e4cheln zu begr\u00fc\u00dfen\u201d, sagte er und blinkte selbst ein kurzes L\u00e4cheln.<\/p>\n<p>Biden habe zuvor bei einem Treffen mit Gesetzgebern seine Maske abgelegt, sagte die republikanische Senatorin Shelly Moore Capito gegen\u00fcber Reportern. Einige Journalisten im Wei\u00dfen Haus haben auch ihre Masken abgenommen.<\/p>\n<p>Das CDC wurde selbst von Gesundheitsbeh\u00f6rden kritisiert, dass es in seinen Leitlinien zu vorsichtig gewesen sei. Kritiker sagten, die Menschen m\u00fcssten mehr Nutzen aus der Impfung im Hinblick auf die R\u00fcckkehr zu normalen Aktivit\u00e4ten ziehen.<\/p>\n<p>\u201eIn den letzten Wochen haben wir zus\u00e4tzliche Daten gesehen, die zeigen, dass diese Impfstoffe in der realen Welt wirken, sie halten den Varianten stand und geimpfte Menschen das Virus seltener \u00fcbertragen,\u201csagte die Agentur in einer Pressemitteilung.<\/p>\n<p>Es f\u00fcgte hinzu, \u201cWir mussten uns die Zeit nehmen, die gesamte Beweislage zu \u00fcberpr\u00fcfen, um dies richtig zu machen, und so sind wir zu dieser Entscheidung gekommen\u201d<\/p>\n<h4>&#8216;BRAUCHE EINE BELOHNUNG&#8217;<\/h4>\n<p>Dr. William Schaffner, Arzt f\u00fcr Infektionskrankheiten am Vanderbilt University Medical Center, sagte, er unterst\u00fctze die neuen Leitlinien, die viele gefordert h\u00e4tten.<\/p>\n<p>\u201cLeute in staatlichen Gesundheits\u00e4mtern und \u00c4rzte f\u00fcr Infektionskrankheiten sagen das seit einiger Zeit, weil sie von der Wirksamkeit des Impfstoffs so beeindruckt sind und au\u00dferdem das Gef\u00fchl haben, dass geimpfte Menschen eine Belohnung brauchen\u201d, sagte er.<\/p>\n<p>Die republikanische Senatorin Susan Collins nannte die Leitlinien \u201c\u00fcberf\u00e4llig\u201d.<\/p>\n<blockquote>\n<p>\u201cWenn Menschen feststellen, dass sie nach einem Impfstoff nichts anders machen k\u00f6nnen, werden sie den Nutzen einer Impfung nicht erkennen\u201d, sagte sie.<\/p>\n<\/blockquote>\n<p>Die \u00fcberarbeiteten Leitlinien sind ein wichtiger Schritt auf dem Weg zur R\u00fcckkehr in das Leben vor der Pandemie, aber die Beh\u00f6rde empfiehlt geimpften Menschen dennoch, Masken in Flugzeugen und Z\u00fcgen sowie auf Flugh\u00e4fen, Verkehrsknotenpunkten, im Nahverkehr und an Orten wie Krankenh\u00e4usern und Arztpraxen zu tragen.<\/p>\n<p>Beamte in mehreren Bundesstaaten sagten, sie w\u00fcrden die bestehenden Maskenpflichten sofort \u00fcberpr\u00fcfen.<\/p>\n<p>Die Retail Industry Leaders Association sagte, die Ank\u00fcndigung f\u00fchre zu Unklarheiten, da sie nicht vollst\u00e4ndig mit den staatlichen und lokalen Vorschriften \u00fcbereinstimme.<\/p>\n<p>\u201cEs ist f\u00fcr Kunden von entscheidender Bedeutung, sich daran zu erinnern, dass die CDC-Ank\u00fcndigung eine Orientierungshilfe ist und dass viele staatliche und lokale Gerichtsbarkeiten immer noch Maskenpflichten haben, die Einzelh\u00e4ndler befolgen m\u00fcssen\u201d<\/p>\n<p>Die Supermarktkette Kroger Co sagte, sie werde ihre Maskenpflicht \u201czu diesem Zeitpunkt\u201d beibehalten<\/p>\n<p>Target Corp sagte, es werde weiterhin Sicherheitsma\u00dfnahmen f\u00fcr Coronaviren in allen Gesch\u00e4ften verlangen, einschlie\u00dflich Masken und sozialer Distanzierung, und \u00fcberpr\u00fcfte gleichzeitig die Leitlinien.<\/p>\n<p>Die United Food and Commercial Workers International Union (UFCW), die 1,3 Millionen Einzelhandels- und Lebensmittelarbeiter vertritt, bezeichnete die neuen Richtlinien als \u201everwirrend\u201cund f\u00fcgte hinzu, dass \u201enicht ber\u00fccksichtigt werden kann, welche Auswirkungen sie auf lebenswichtige Arbeitnehmer haben wird, die h\u00e4ufig Personen ausgesetzt sind, die dies nicht tun.\u201cgeimpft werden und das Tragen von Masken verweigern\u201d<\/p>\n<p>Die US-Regierung hat letzten Monat die Maskenpflicht auf alle Verkehrsnetze ausgeweitet bis zum 13. September Die Transportation Security Administration sagte, sie werde \u201ceng mit der CDC zusammenarbeiten, um die Notwendigkeit dieser Richtlinien zu bewerten\u201d Walensky sagte, CDC werde bald aktualisierte Transitleitlinien herausgeben.<\/p>\n<p>Die neuen Leitlinien besagen, dass geimpfte Amerikaner alle Reisen wieder aufnehmen k\u00f6nnen, nach internationalen Reisen nicht unter Quarant\u00e4ne gestellt werden m\u00fcssen und nicht auf COVID-19 getestet werden m\u00fcssen, wenn sie einer Person ausgesetzt werden, die COVID-19-positiv, aber asymptomatisch ist.<\/p>\n<blockquote>\n<p>Allerdings sind Amerikaner immer noch mit einigen internationalen Reisebeschr\u00e4nkungen konfrontiert, darunter nicht unbedingt notwendige Reisen nach Kanada.<\/p>\n<\/blockquote>\n<p>Masken wurden in den Vereinigten Staaten zu einem politischen Thema, da sich der damalige Pr\u00e4sident Donald Trump dagegen wehrte, Gesichtsbedeckungen vorzuschreiben, w\u00e4hrend Pr\u00e4sident Joe Biden Masken umarmte und sie f\u00fcr Verkehrsknotenpunkte vorschrieb. Einige US-Bundesstaaten erlie\u00dfen aggressive Maskenpflichten, w\u00e4hrend andere sie vor Monaten ablehnten oder fallen lie\u00dfen.<\/p>\n<p>Das CDC sagte, dass vollst\u00e4ndig geimpfte Menschen weiterhin Masken tragen sollten, wenn dies durch Bundes-, Landes-, lokale, Stammes- oder Territorialgesetze vorgeschrieben ist, und sich an Regeln und Vorschriften halten sollten, die von lokalen Unternehmen und Arbeitspl\u00e4tzen festgelegt werden.<\/p>\n<p>Ende April erkl\u00e4rte das CDC, dass vollst\u00e4ndig geimpfte Menschen sicher an Outdoor-Aktivit\u00e4ten wie Wandern und Wandern ohne Masken teilnehmen k\u00f6nnen, empfahl jedoch deren weitere Verwendung in \u00f6ffentlichen R\u00e4umen, wo sie ben\u00f6tigt werden.<\/p>\n<p>Immunschwachen Personen sollten vor dem Ablegen von Masken \u00c4rzte konsultieren und diejenigen, die nicht geimpft sind, sollten diese weiterhin tragen, sagte Walensky.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die US-amerikanischen Zentren f\u00fcr die Kontrolle und Pr\u00e4vention von Krankheiten (CDC) haben am Donnerstag darauf hingewiesen, dass vollst\u00e4ndig geimpfte Menschen im Freien keine Masken tragen m\u00fcssen und das Tragen in Innenr\u00e4umen an den meisten Orten vermeiden k\u00f6nnen. Die aktualisierten Leitlinien der Beh\u00f6rde sagten, dass sie es erm\u00f6glichen werden, dass sich das Leben wieder normalisiert. Das [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":702470,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1154],"tags":[2243,1972,1107,1157],"class_list":["post-702469","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-welt","tag-coronavirus","tag-covid-19-impfstoff","tag-gesundheit","tag-vereinigte-staaten"],"blocksy_meta":[],"acf":[],"author_username":"ugyelet","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"","focus_keyword":"","canonical_url":"","robots":"","primary_category":"1154","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/702469","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=702469"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/702469\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/702470"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=702469"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=702469"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=702469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}