{"id":714719,"date":"2020-11-14T23:47:27","date_gmt":"2020-11-14T22:47:27","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/krankenhausbrand-totet-covid-19-patienten-im-nordosten-rumaniens\/"},"modified":"2020-11-14T23:47:27","modified_gmt":"2020-11-14T22:47:27","slug":"krankenhausbrand-totet-covid-19-patienten-im-nordosten-rumaniens","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/krankenhausbrand-totet-covid-19-patienten-im-nordosten-rumaniens\/","title":{"rendered":"Krankenhausbrand t\u00f6tet COVID-19-Patienten im Nordosten Rum\u00e4niens"},"content":{"rendered":"<p><strong>Zehn COVID-19-Patienten in ernstem Zustand kamen bei einem Brand ums Leben, der am sp\u00e4ten Samstag auf der Intensivstation (ICU) des Piatra Neamt County Hospital im Nordosten Rum\u00e4niens ausbrach, best\u00e4tigte Gesundheitsminister Nelu Tataru.<\/strong><\/p>\n<p>\u201cAcht Patienten starben an den Folgen des Brandes, die beiden anderen sp\u00e4ter in der Notaufnahme, an Atemversagen\u201d, erkl\u00e4rte der Minister, der kurz nach dem Vorfall das Krankenhaus in Piatra Neamt, etwa 350 km von der Hauptstadt Bukarest entfernt, besuchte.<\/p>\n<p>Irina Popa, Sprecherin der \u00f6rtlichen Aufsichtsbeh\u00f6rde f\u00fcr Notsituationen, sagte den lokalen Medien nach der L\u00f6schung des Feuers, dass sich 16 Patienten in den beiden COVID-19-Notfallstationen befanden, als das Feuer ausbrach.<\/p>\n<blockquote>\n<p>\u201cSieben Menschen befinden sich in einem kritischen Zustand, darunter auch der diensthabende Arzt\u201d, sagte der Sprecher.<\/p>\n<\/blockquote>\n<p>Nach Angaben der \u00f6rtlichen Beh\u00f6rden werden die geretteten Patienten zur Behandlung in zwei Krankenh\u00e4user im benachbarten Iasi County gebracht.<\/p>\n<p>Dies ist der Krankenhausbrand, der in den letzten Jahren die meisten Opfer im Land gefordert hat Der letzte gro\u00dfe Krankenhausbrand ereignete sich im August 2010, als in der Entbindungsklinik Giulesti in Bukarest sechs Babys get\u00f6tet und mehrere weitere schwer verletzt wurden.<\/p>\n<p>Es ist noch nicht bekannt, wo das Feuer ausbrach, aber zweifellos wurden die Flammen durch die bestehenden Sauerstoffanlagen auf der Intensivstation verst\u00e4rkt, wurde Lucian Micu, der Krankenhausdirektor, von lokalen Medien zitiert.<\/p>\n<blockquote>\n<p>Dieser Unfall ist zweifellos ein Schlag f\u00fcr die rum\u00e4nischen medizinischen Einrichtungen, die von der Ausbreitung der Pandemie \u00fcberfordert waren.<\/p>\n<\/blockquote>\n<p>Rum\u00e4nien hat ab Montag eine 30-t\u00e4gige Ausgangssperre verh\u00e4ngt Die neuesten Statistiken vom Samstag zeigten, dass die Zahl der COVID-19-F\u00e4lle im Land 353.185 erreichte und die Zahl der Todesopfer auf 8.813 stieg.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zehn COVID-19-Patienten in ernstem Zustand kamen bei einem Brand ums Leben, der am sp\u00e4ten Samstag auf der Intensivstation (ICU) des Piatra Neamt County Hospital im Nordosten Rum\u00e4niens ausbrach, best\u00e4tigte Gesundheitsminister Nelu Tataru. \u201cAcht Patienten starben an den Folgen des Brandes, die beiden anderen sp\u00e4ter in der Notaufnahme, an Atemversagen\u201d, erkl\u00e4rte der Minister, der kurz nach [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":714720,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1154],"tags":[2243,1358,1107,1582,1236,1425],"class_list":["post-714719","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-welt","tag-coronavirus","tag-feuerwehrmann","tag-gesundheit","tag-krankenhaus","tag-polizei","tag-rumanien"],"blocksy_meta":[],"acf":[],"author_username":"ugyelet","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"","focus_keyword":"","canonical_url":"","robots":"","primary_category":"1154","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/714719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=714719"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/714719\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/714720"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=714719"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=714719"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=714719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}