{"id":716515,"date":"2020-09-21T20:45:00","date_gmt":"2020-09-21T18:45:00","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/die-britische-covid-19-alarmstufe-wurde-empfohlen-sie-auf-stufe-4-anzuheben\/"},"modified":"2020-09-21T20:45:00","modified_gmt":"2020-09-21T18:45:00","slug":"die-britische-covid-19-alarmstufe-wurde-empfohlen-sie-auf-stufe-4-anzuheben","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/die-britische-covid-19-alarmstufe-wurde-empfohlen-sie-auf-stufe-4-anzuheben\/","title":{"rendered":"Die britische COVID-19-Alarmstufe wurde empfohlen, sie auf Stufe 4 anzuheben"},"content":{"rendered":"<p><strong>Laut einer am Montag von den CMOs ver\u00f6ffentlichten gemeinsamen Erkl\u00e4rung haben die britischen Chief Medical Officers (CMOs) empfohlen, die COVID-19-Alarmstufe des Landes von Stufe 3 auf Stufe 4 zu verschieben.<\/strong><\/p>\n<p>\u201cDie CMOs f\u00fcr England, Schottland, Wales und Nordirland haben die Beweise \u00fcberpr\u00fcft und empfehlen allen 4 Nationen des Vereinigten K\u00f6nigreichs, auf Stufe 4 zu wechseln\u201d, hei\u00dft es in der Erkl\u00e4rung.<\/p>\n<p>Stufe 4 bedeutet, dass die COVID-19-Epidemie im Allgemeinen verbreitet ist, die \u00dcbertragung hoch ist oder exponentiell zunimmt. <\/p>\n<p>Die Empfehlung wurde zu einer Zeit eingebracht, als L\u00e4nder wie Gro\u00dfbritannien, China, Russland und die Vereinigten Staaten gegen die Zeit rennen, um Coronavirus-Impfstoffe zu entwickeln.<\/p>\n<h4>Der britische Premierminister leitet die Dringlichkeitssitzung zur Bek\u00e4mpfung der Coronavirus-Pandemie<\/h4>\n<p>Der britische Premierminister Boris Johnson werde am Dienstag eine COBRA-Notfallsitzung leiten, um die steigenden Coronavirus-F\u00e4lle zu bek\u00e4mpfen, sagte Downing Street am Montag.<\/p>\n<p>Johnson werde die Reaktion auf das Coronavirus sp\u00e4ter am Montag auch mit den ersten Ministern Schottlands, Wales und Nordirlands besprechen, so der Sprecher des Premierministers.<\/p>\n<p>\u201cEine Sache, die er tun wird, ist, (zu) seine Verpflichtung zu bekr\u00e4ftigen, mit den dezentralen Verwaltungen als ein Vereinigtes K\u00f6nigreich zusammenzuarbeiten, als Reaktion auf die steigenden Infektionsraten, die wir im gesamten Vereinigten K\u00f6nigreich sehen\u201d, sagte der Sprecher.<\/p>\n<blockquote>\n<p>\u201cWir stehen vor erheblichen Herausforderungen, wenn wir in die Wintermonate eintreten\u201d, f\u00fcgte der Sprecher hinzu.<\/p>\n<\/blockquote>\n<p>COBRA, benannt nach dem Briefing Room A des britischen Kabinettsb\u00fcros in Whitehall, versammelt Minister, Beamte, die Polizei, Geheimdienstmitarbeiter und andere Personen, die f\u00fcr alles geeignet sind, was sie bei einer Notfallreaktion untersuchen.<\/p>\n<p>\u201cMorgen fr\u00fch ist f\u00fcr COBRA eine Gelegenheit, dar\u00fcber zu diskutieren, welche n\u00e4chsten Schritte bei der Reaktion auf das Coronavirus erforderlich sein k\u00f6nnten\u201d, sagte der Sprecher.<\/p>\n<blockquote>\n<p>Am fr\u00fchen Montag warnte der wissenschaftliche Chefberater der britischen Regierung, Patrick Vallance, dass es in Gro\u00dfbritannien bis Mitte Oktober t\u00e4glich 50.000 neue F\u00e4lle von Coronavirus geben k\u00f6nnte, wenn nicht eingegriffen werde, um die aktuelle Infektionsrate zu verlangsamen.<\/p>\n<\/blockquote>\n<p>Die Zahl der neuen COVID-19-F\u00e4lle verdoppelte sich etwa alle sieben Tage und in Gro\u00dfbritannien k\u00f6nnten bis Mitte November 200 Todesf\u00e4lle pro Tag zu verzeichnen sein, sagte Vallance auf einer Pressekonferenz in der Downing Street 10.<\/p>\n<p>\u201cDie Herausforderung besteht daher darin, sicherzustellen, dass die Verdopplungszeit nicht bei sieben Tagen bleibt\u201d, sagte Vallance.<\/p>\n<p>\u201eDas erfordert Geschwindigkeit, es erfordert Ma\u00dfnahmen und es erfordert&#8230; genug, um das zu Fall bringen zu k\u00f6nnen\u201cf\u00fcgte er hinzu.<\/p>\n<p>Gro\u00dfbritannien verzeichnete am Montag \u00fcber Nacht weitere 4.368 Infektionen, womit sich die Gesamtzahl der Coronavirus-F\u00e4lle auf 398.625 erh\u00f6hte Die Zahl der Coronavirus-bedingten Todesopfer stieg nach am Montag ver\u00f6ffentlichten offiziellen Zahlen um 11 auf 41.788.<\/p>\n<p>Hochrangige Regierungsbeamte haben einen sozialen Lockdown signalisiert, der die Begegnung mit Menschen aus anderen Haushalten einschr\u00e4nkt und Schlie\u00dfungen oder k\u00fcrzere \u00d6ffnungszeiten f\u00fcr Pubs und Restaurants vorsieht.<\/p>\n<blockquote>\n<p>Unterdessen rennen L\u00e4nder wie Gro\u00dfbritannien, China, Russland und die Vereinigten Staaten gegen die Zeit, um Coronavirus-Impfstoffe zu entwickeln.<\/p>\n<\/blockquote>\n<p>Vallance sagte, es sei m\u00f6glich, dass ein Impfstoff sp\u00e4ter in diesem Jahr in kleinen Mengen verf\u00fcgbar sein k\u00f6nnte, aber es sei wahrscheinlicher, dass Anfang n\u00e4chsten Jahres ein Impfstoff verf\u00fcgbar sein werde, obwohl dies nicht garantiert sei.<\/p>\n<p>Englands Chief Medical Officer Chris Whitty, der sich Vallance f\u00fcr das im Fernsehen \u00fcbertragene Briefing angeschlossen hatte, sagte, die britische Regierung m\u00fcsse Entscheidungen treffen, die die Auswirkungen auf die Wirtschaft mit der Gefahr des Virus in Einklang bringen m\u00fcssten.<\/p>\n<p>\u201eWenn wir zu wenig tun, ger\u00e4t dieses Virus au\u00dfer Kontrolle&#8230; Aber wenn wir zu weit in die andere Richtung gehen, k\u00f6nnen wir der Wirtschaft Schaden zuf\u00fcgen, der sich bis hin zu Arbeitslosigkeit und Armut ausbreiten kann, die langfristige Auswirkungen auf die Gesundheit haben.\u201csagte er.<\/p>\n<p>Die Zahl der Coronavirus-F\u00e4lle nimmt in London, wie auch in weiten Teilen Gro\u00dfbritanniens, stark zu.<br \/>Gleichzeitig sagte ein Sprecher des Londoner B\u00fcrgermeisters, Sadiq Khan, \u201cDie Situation verschlechtert sich eindeutig\u201d Sadiq werde Ratsvorsitzende treffen und alle London-spezifischen Ma\u00dfnahmen w\u00fcrden den Ministern im Anschluss daran empfohlen.<\/p>\n<blockquote>\n<p>\u201cDer B\u00fcrgermeister will schnelles Handeln, da wir keine Verz\u00f6gerung riskieren k\u00f6nnen, wie es im M\u00e4rz geschehen ist\u201d<\/p>\n<\/blockquote>\n<p>Der Sprecher sagte \u201cEs ist besser, sowohl f\u00fcr die Gesundheit als auch f\u00fcr die Wirtschaft zu fr\u00fch als zu sp\u00e4t zu ziehen\u201d<\/p>\n<p>Die britische Regierung hat k\u00fcrzlich \u201cdie Sechs-Regel\u201d eingef\u00fchrt, die die Zahl der Menschen, die sich drinnen oder drau\u00dfen versammeln k\u00f6nnen, auf sechs begrenzt. In Teilen Gro\u00dfbritanniens wurden strengere Beschr\u00e4nkungen eingef\u00fchrt, zu denen auch ein Verbot der Mischung verschiedener Haushalte geh\u00f6rt, um die steigenden Infektionsraten zu bek\u00e4mpfen.<\/p>\n<ul>\n<li><a href=\"https:\/\/dailynewshungary.com\/de\/coronavirus-in-ungarn-drei-sterben-registrierte-infektionen-steigen-um-876\/\" target=\"_blank\" rel=\"noopener noreferrer\">Coronavirus in Ungarn: Drei sterben, registrierte Infektionen steigen um 876<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Laut einer am Montag von den CMOs ver\u00f6ffentlichten gemeinsamen Erkl\u00e4rung haben die britischen Chief Medical Officers (CMOs) empfohlen, die COVID-19-Alarmstufe des Landes von Stufe 3 auf Stufe 4 zu verschieben. \u201cDie CMOs f\u00fcr England, Schottland, Wales und Nordirland haben die Beweise \u00fcberpr\u00fcft und empfehlen allen 4 Nationen des Vereinigten K\u00f6nigreichs, auf Stufe 4 zu wechseln\u201d, [&hellip;]<\/p>\n","protected":false},"author":88,"featured_media":716516,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"","footnotes":""},"categories":[1154],"tags":[2243,1361],"class_list":["post-716515","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-welt","tag-coronavirus","tag-uk"],"blocksy_meta":[],"acf":[],"author_username":"alpar.kato","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"","focus_keyword":"","canonical_url":"","robots":"","primary_category":"1154","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/716515","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/88"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=716515"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/716515\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/716516"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=716515"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=716515"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=716515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}