{"id":721640,"date":"2020-04-19T10:00:00","date_gmt":"2020-04-19T08:00:00","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/coronavirus-67-neue-todesopfer-zahl-der-registrierten-falle-steigt-auf-1-916\/"},"modified":"2020-04-19T10:00:00","modified_gmt":"2020-04-19T08:00:00","slug":"coronavirus-67-neue-todesopfer-zahl-der-registrierten-falle-steigt-auf-1-916","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/coronavirus-67-neue-todesopfer-zahl-der-registrierten-falle-steigt-auf-1-916\/","title":{"rendered":"Coronavirus 67 neue Todesopfer, Zahl der registrierten F\u00e4lle steigt auf 1.916"},"content":{"rendered":"<p><strong>Weitere 17 Patienten, \u00fcberwiegend \u00e4ltere Menschen mit chronischen Krankheiten, sind in Ungarn gestorben und die Zahl der registrierten neuartigen Coronavirus-Infektionen ist um 82 auf 1.916 gestiegen, sagte koronavirus.gov.hu am Sonntagmorgen Bisher gab es 189 Todesopfer und 250 Menschen haben das Krankenhaus nach ihrer Genesung verlassen.<\/strong><\/p>\n<p>Es gibt 784 Patienten im Krankenhaus und fast 12.000 in h\u00e4uslicher Quarant\u00e4ne, 61 werden beatmet.<\/p>\n<blockquote>\n<p>Bisher wurden 46.353 Coronavirus-Tests in akkreditierten Laboren durchgef\u00fchrt.<\/p>\n<\/blockquote>\n<p>Die Epidemie befinde sich derzeit in der Phase der Ausbreitung in Gemeinden, und das Virus k\u00f6nne \u00fcberall vorhanden sein und jeden infizieren, hie\u00df es auf der Website und warnte davor, dass die tats\u00e4chliche Zahl der Menschen, die das Virus in sich tragen, viel h\u00f6her sei als die Zahl der registrierten Tr\u00e4ger.<\/p>\n<ul>\n<li><a href=\"https:\/\/dailynewshungary.com\/de\/coronavirus-in-ungarn-nicht-lebensnotwendige-geschafte-offnen-und-drohen-mit-einer-geldstrafe-belegt-zu-werden\/\"><strong>Coronavirus in Ungarn: Nicht lebensnotwendige Gesch\u00e4fte \u00f6ffnen und drohen mit einer Geldstrafe belegt zu werden<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/dailynewshungary.com\/de\/coronavirus-ungarn-erhalt-weiterhin-schutzausrustung\/\"><strong>Coronavirus \u2013 Ungarn erh\u00e4lt weiterhin Schutzausr\u00fcstung<\/strong><\/a><\/li>\n<\/ul>\n<p>\u00c4ltere Menschen, Studenten und Menschen, die aus dem Ausland zur\u00fcckkehren, m\u00fcssten zu Hause bleiben, hie\u00df esAlle m\u00fcssten die Ausgangssperren beachten, die die Regierung auf unbestimmte Zeit verl\u00e4ngert habe, f\u00fcgte sie hinzu.<\/p>\n<p>Budapest hat die h\u00f6chste Infektionszahl (971), gefolgt vom Landkreis Pest (278) und dem Kreis Fejer (146).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Weitere 17 Patienten, \u00fcberwiegend \u00e4ltere Menschen mit chronischen Krankheiten, sind in Ungarn gestorben und die Zahl der registrierten neuartigen Coronavirus-Infektionen ist um 82 auf 1.916 gestiegen, sagte koronavirus.gov.hu am Sonntagmorgen Bisher gab es 189 Todesopfer und 250 Menschen haben das Krankenhaus nach ihrer Genesung verlassen. Es gibt 784 Patienten im Krankenhaus und fast 12.000 in [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":721641,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1098],"tags":[2243,1778,1107,1108,1582,1138],"class_list":["post-721640","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gesellschaft","tag-coronavirus","tag-coronavirus-in-ungarn","tag-gesundheit","tag-gesundheitssystem","tag-krankenhaus","tag-statistik"],"blocksy_meta":[],"acf":[],"author_username":"ugyelet","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"","focus_keyword":"","canonical_url":"","robots":"","primary_category":"1098","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/721640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=721640"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/721640\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/721641"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=721640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=721640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=721640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}