{"id":721901,"date":"2020-04-11T10:00:00","date_gmt":"2020-04-11T08:00:00","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/coronavirus-anzahl-der-bestatigten-falle-1-310-acht-neue-todesfalle\/"},"modified":"2020-04-11T10:00:00","modified_gmt":"2020-04-11T08:00:00","slug":"coronavirus-anzahl-der-bestatigten-falle-1-310-acht-neue-todesfalle","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/coronavirus-anzahl-der-bestatigten-falle-1-310-acht-neue-todesfalle\/","title":{"rendered":"Coronavirus \u2013 Anzahl der best\u00e4tigten F\u00e4lle 1.310, acht neue Todesf\u00e4lle"},"content":{"rendered":"<p><strong>Die Zahl der registrierten Covid-19-F\u00e4lle in Ungarn ist auf 1.310 gestiegen, w\u00e4hrend acht Patienten an einem einzigen Tag starben, berichtete koronavirus.gov.hu am Samstagmorgen.<\/strong><\/p>\n<p>Laut der Website der Regierung liegt die Gesamtzahl der durch Covid-19 verursachten Todesf\u00e4lle bisher bei 85 und es gab insgesamt 115 Genesungen.<\/p>\n<ul>\n<li><a href=\"https:\/\/dailynewshungary.com\/de\/coronavirus-burgermeister-ordnet-schliesung-der-margareteninsel-und-anderer-freizeit-hotspots-an\/\"><strong>Coronavirus \u2013 B\u00fcrgermeister ordnet Schlie\u00dfung der Margareteninsel und anderer Freizeit-Hotspots an<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/dailynewshungary.com\/de\/ungarischer-arzt-sagt-corona-impfstoff-ist-ein-jahr-entfernt\/\"><strong>Ungarischer Arzt sagt, Corona-Impfstoff ist ein Jahr entfernt<\/strong><\/a><\/li>\n<\/ul>\n<p>Derzeit befinden sich 17.490 Menschen in offizieller Heimquarant\u00e4ne.<\/p>\n<p>Die Zahl der bisher durchgef\u00fchrten Tests betr\u00e4gt insgesamt 31.961.<\/p>\n<blockquote>\n<p>Budapest verzeichnete mit 655 F\u00e4llen die h\u00f6chste Zahl best\u00e4tigter Infektionen, gefolgt vom Landkreis Pest (199).<\/p>\n<\/blockquote>\n<p>Die Beh\u00f6rden sagen, dass das Virus immer noch in kleinen Clustern und nicht in gr\u00f6\u00dferen Gemeinden \u00fcbertragen wird, es kommt jedoch in allen Teilen des Landes vor.<\/p>\n<p>Im \u00dcbrigen wurden weitere 56 \u00e4ltere Menschen, bei denen entweder eine Infektion mit dem neuartigen Coronavirus best\u00e4tigt wurde oder der Verdacht besteht, dass sie mit dem neuartigen Coronavirus infiziert sind, vom Pflegeheim Pesti Street in Budapest in das St. Janos-Krankenhaus verlegt.<\/p>\n<p>Nach einem massenhaften Ausbruch von Krankheiten im Altenheim befahl der Oberarzt der Budapester Gemeinde, sofort zu handeln, am Donnerstag wurden 126 \u00e4ltere Bewohner des Pflegeheims ins Krankenhaus gebracht.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Zahl der registrierten Covid-19-F\u00e4lle in Ungarn ist auf 1.310 gestiegen, w\u00e4hrend acht Patienten an einem einzigen Tag starben, berichtete koronavirus.gov.hu am Samstagmorgen. Laut der Website der Regierung liegt die Gesamtzahl der durch Covid-19 verursachten Todesf\u00e4lle bisher bei 85 und es gab insgesamt 115 Genesungen. Coronavirus \u2013 B\u00fcrgermeister ordnet Schlie\u00dfung der Margareteninsel und anderer Freizeit-Hotspots [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":721902,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1098],"tags":[2243,1778,1107,1582,1138],"class_list":["post-721901","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gesellschaft","tag-coronavirus","tag-coronavirus-in-ungarn","tag-gesundheit","tag-krankenhaus","tag-statistik"],"blocksy_meta":[],"acf":[],"author_username":"ugyelet","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"","focus_keyword":"","canonical_url":"","robots":"","primary_category":"1098","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/721901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=721901"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/721901\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/721902"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=721901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=721901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=721901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}