{"id":722023,"date":"2020-04-08T08:10:00","date_gmt":"2020-04-08T06:10:00","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/coronavirus-die-zahl-der-neuen-falle-steigt-auf-895-mit-11-neuen-todesfallen\/"},"modified":"2020-04-08T08:10:00","modified_gmt":"2020-04-08T06:10:00","slug":"coronavirus-die-zahl-der-neuen-falle-steigt-auf-895-mit-11-neuen-todesfallen","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/coronavirus-die-zahl-der-neuen-falle-steigt-auf-895-mit-11-neuen-todesfallen\/","title":{"rendered":"Coronavirus \u2013 Die Zahl der neuen F\u00e4lle steigt auf 895, mit 11 neuen Todesf\u00e4llen"},"content":{"rendered":"<p><strong>Die Zahl der registrierten Covid-19-F\u00e4lle in Ungarn ist auf 895 gestiegen, w\u00e4hrend elf Patienten an einem einzigen Tag starben, sodass sich die Gesamtzahl der Todesopfer auf 58 erh\u00f6hte, sagte koronavirus.gov.hu am Mittwochmorgen.<\/strong><\/p>\n<p>Die elf Verstorbenen waren nach Angaben der Regierung \u00fcberwiegend \u00e4ltere Menschen.<\/p>\n<blockquote>\n<p>Ein Opfer war 49, hie\u00df es auf der Website.<\/p>\n<\/blockquote>\n<p>Laut der Website gab es insgesamt 94 Wiederherstellungen.<\/p>\n<p>Derzeit leben 15.481 Menschen in offizieller Hausquarant\u00e4ne.<\/p>\n<blockquote>\n<p>Die Zahl der durchgef\u00fchrten Tests betr\u00e4gt bisher insgesamt 25.748.<\/p>\n<\/blockquote>\n<p>Budapest verzeichnete mit 387 F\u00e4llen die h\u00f6chste Zahl best\u00e4tigter Infektionen, gefolgt vom Landkreis Pest (164).<\/p>\n<ul>\n<li><a href=\"https:\/\/dailynewshungary.com\/de\/coronavirus-porto-budapest-konnte-zu-einem-infektionszentrum-werden-sofern-keine-einschrankungen-eingehalten-werden\/\" target=\"_blank\" rel=\"noopener noreferrer\">Budapest k\u00f6nnte zu einem Infektionszentrum werden, wenn keine Einschr\u00e4nkungen eingehalten werden<\/a><\/li>\n<\/ul>\n<p>Die Beh\u00f6rden sagen, dass das Virus immer noch in kleinen Clustern und nicht in gr\u00f6\u00dferen Gemeinden \u00fcbertragen wird, es kommt jedoch in allen Teilen des Landes vor.<\/p>\n<p>Lesen Sie hier die neuesten Nachrichten auf <a href=\"https:\/\/dailynewshungary.com\/de\/coronavirus-porto-budapest-konnte-zu-einem-infektionszentrum-werden-sofern-keine-einschrankungen-eingehalten-werden\/\" target=\"_blank\" rel=\"noopener noreferrer\">Coronavirus in Ungarn<\/a>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Zahl der registrierten Covid-19-F\u00e4lle in Ungarn ist auf 895 gestiegen, w\u00e4hrend elf Patienten an einem einzigen Tag starben, sodass sich die Gesamtzahl der Todesopfer auf 58 erh\u00f6hte, sagte koronavirus.gov.hu am Mittwochmorgen. Die elf Verstorbenen waren nach Angaben der Regierung \u00fcberwiegend \u00e4ltere Menschen. Ein Opfer war 49, hie\u00df es auf der Website. Laut der Website [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":722024,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1098],"tags":[2243,1778,1076],"class_list":["post-722023","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gesellschaft","tag-coronavirus","tag-coronavirus-in-ungarn","tag-ungarn"],"blocksy_meta":[],"acf":[],"author_username":"alk","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"","focus_keyword":"","canonical_url":"","robots":"","primary_category":"1098","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/722023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=722023"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/722023\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/722024"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=722023"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=722023"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=722023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}