{"id":722611,"date":"2020-03-23T19:00:00","date_gmt":"2020-03-23T18:00:00","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/kochen-in-rot-weis-und-grun-wie-man-patriotismus-in-der-kuche-zum-ausdruck-bringt\/"},"modified":"2020-03-23T19:00:00","modified_gmt":"2020-03-23T18:00:00","slug":"kochen-in-rot-weis-und-grun-wie-man-patriotismus-in-der-kuche-zum-ausdruck-bringt","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/kochen-in-rot-weis-und-grun-wie-man-patriotismus-in-der-kuche-zum-ausdruck-bringt\/","title":{"rendered":"Kochen in Rot, Wei\u00df und Gr\u00fcn \u2013 Wie man Patriotismus in der K\u00fcche zum Ausdruck bringt"},"content":{"rendered":"<p><strong>Wenn Sie immer noch schlecht f\u00fchlen, dass alle Feierlichkeiten am 15. M\u00e4rz abgesagt werden, machen Sie diese roten, wei\u00dfen und gr\u00fcnen Rezepte, um sich selbst oder andere aufzumuntern Probieren Sie die Farben der ungarischen Flagge!<\/strong><\/p>\n<p><strong>Caprese-salat<\/strong><\/p>\n<p>Dies ist das einfachste und einfachste aller Rezepte. Die italienische Spezialit\u00e4t ist in weniger als 5 Minuten fertig. Das Einzige, worauf Sie achten m\u00fcssen, ist, die Farben richtig anzuordnen und dabei den Farben unserer Nationalflagge zu folgen: Rot, Wei\u00df, Gr\u00fcn.<\/p>\n<figure id=\"attachment_311651\" aria-describedby=\"caption-attachment-311651\" style=\"width: 1024px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-311651 size-large\" src=\"https:\/\/dailynewshungary.com\/wp-content\/uploads\/2020\/03\/italian-1732877_1280-1024x576.jpg\" alt=\"Caprese-salat\" width=\"1024\" height=\"576\" srcset=\"https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2020\/03\/italian-1732877_1280-1024x576.jpg 1024w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2020\/03\/italian-1732877_1280-300x169.jpg 300w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2020\/03\/italian-1732877_1280-768x432.jpg 768w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2020\/03\/italian-1732877_1280-800x450.jpg 800w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2020\/03\/italian-1732877_1280-1160x653.jpg 1160w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2020\/03\/italian-1732877_1280.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"><figcaption id=\"caption-attachment-311651\" class=\"wp-caption-text\">Foto: Pixabay<\/figcaption><\/figure>\n<h4>Breitet sich in unseren Nationalfarben aus<\/h4>\n<ul>\n<li><a href=\"https:\/\/izeselet.hu\/receptek\/piros-feher-zold-gokler-krisztina\/\" target=\"_blank\" rel=\"noopener\">Originalrezept<\/a><\/li>\n<\/ul>\n<figure id=\"attachment_311652\" aria-describedby=\"caption-attachment-311652\" style=\"width: 825px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-311652 size-full\" src=\"https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2020\/03\/3_825x620-sharpen.jpg\" alt=\"Spreizt\" width=\"825\" height=\"620\" srcset=\"https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2020\/03\/3_825x620-sharpen.jpg 825w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2020\/03\/3_825x620-sharpen-300x225.jpg 300w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2020\/03\/3_825x620-sharpen-768x577.jpg 768w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2020\/03\/3_825x620-sharpen-800x601.jpg 800w\" sizes=\"auto, (max-width: 825px) 100vw, 825px\"><figcaption id=\"caption-attachment-311652\" class=\"wp-caption-text\">Foto: www.izeselet.hu<\/figcaption><\/figure>\n<p><strong>Zutaten:<\/strong><\/p>\n<ul>\n<li>5 rote Paprika<\/li>\n<li>\u00bd rote Zwiebel<\/li>\n<li>Knoblauch nach Geschmack<\/li>\n<li>\u00bd Pfund Kokos\u00f6l<\/li>\n<li>Salz nach Geschmack<\/li>\n<li>Pfeffer nach Geschmack<\/li>\n<li>20 dkg wei\u00dfe Bohnen (konserven)<\/li>\n<li>20 dkg gefrorene Erbsen<\/li>\n<li>Petersilie nach Geschmack<\/li>\n<\/ul>\n<p><strong>Anleitung:<\/strong><\/p>\n<p>Roter Brotaufstrich: Die roten Paprika ca. 30 Minuten (200 Celsius) r\u00f6sten Rote Zwiebel und Knoblauch w\u00fcrfeln Kokos\u00f6l in eine Pfanne geben, dann die Zwiebeln und den Knoblauch unter gelegentlichem R\u00fchren dazu geben Zwiebelmischung und rote Paprika mit etwas Salz und Pfeffer in einen Mixer geben, gut verr\u00fchren.<\/p>\n<p>Wei\u00dfer Aufstrich: Verwenden Sie Bohnen aus der Dose, um den Prozess zu beschleunigen. Geben Sie die Bohnen, das Salz, den Pfeffer und den gehackten Knoblauch in einen Mixer und mischen Sie sie gut.<\/p>\n<p>Gr\u00fcnaufstrich: Die gefrorenen Erbsen nach der Packungsanleitung kochen Sp\u00fclen, dann mit etwas Kochwasser in einen Mixer geben Salz, Pfeffer, und Petersilie auch unter guter Mischung dazugeben.<\/p>\n<p>Genie\u00dfen Sie Ihre Aufstriche auf Toast.<\/p>\n<h4>Rot-wei\u00df-gr\u00fcne Creme im Glas<\/h4>\n<ul>\n<li><a href=\"https:\/\/korsocska.blogspot.com\/\" target=\"_blank\" rel=\"noopener\">Originalrezept<\/a><\/li>\n<\/ul>\n<figure id=\"attachment_311656\" aria-describedby=\"caption-attachment-311656\" style=\"width: 1024px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-311656 size-large\" src=\"https:\/\/dailynewshungary.com\/wp-content\/uploads\/2020\/03\/DSCF8067-m\u00e1solata-1024x768.jpg\" alt=\"Rot wei\u00df gr\u00fcn creme\" width=\"1024\" height=\"768\" srcset=\"https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2020\/03\/DSCF8067-m\u00e1solata-1024x768.jpg 1024w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2020\/03\/DSCF8067-m\u00e1solata-300x225.jpg 300w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2020\/03\/DSCF8067-m\u00e1solata-768x576.jpg 768w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2020\/03\/DSCF8067-m\u00e1solata-1536x1152.jpg 1536w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2020\/03\/DSCF8067-m\u00e1solata-800x600.jpg 800w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2020\/03\/DSCF8067-m\u00e1solata-1160x870.jpg 1160w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2020\/03\/DSCF8067-m\u00e1solata.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"><figcaption id=\"caption-attachment-311656\" class=\"wp-caption-text\">Foto: www.korsocska.blogspot.com<\/figcaption><\/figure>\n<p><strong>Zutaten f\u00fcr die gr\u00fcne Schicht:<\/strong><\/p>\n<ul>\n<li>2 dl Kiwisaft<\/li>\n<li>1 TL frisch gepresster Zitronensaft<\/li>\n<li>1 EL Gelatinepulver<\/li>\n<li>Zucker<\/li>\n<\/ul>\n<p><strong>Zutaten f\u00fcr die wei\u00dfe Schicht:<\/strong><\/p>\n<ul>\n<li>Tapioka-Pudding oder Joghurt und Milch mit Gelatine und Zucker mischen<\/li>\n<\/ul>\n<p><strong>Zutaten f\u00fcr die rote Schicht:<\/strong><\/p>\n<ul>\n<li>2 dl Granatapfelsaft<\/li>\n<li>1 EL Gelatinepulver<\/li>\n<li>Zucker<\/li>\n<\/ul>\n<p><strong>Anleitung:<\/strong><\/p>\n<p>Den Kiwisaft erhitzen dann Gelatine und frisch gepressten Zitronensaft dazugeben Den Tapioka-Pudding oben drauf geben F\u00fcr die rote Schicht Granatapfelsaft und die Gelatine zusammenmischen und zum Kochen bringen, erst nach dem Festwerden jeder Mischung die drei Schichten zusammenbauen.<\/p>\n<h4>Kokarde<\/h4>\n<ul>\n<li><a href=\"https:\/\/www.nosalty.hu\/recept\/kokarda\" target=\"_blank\" rel=\"noopener\">Originalrezept<\/a><\/li>\n<\/ul>\n<figure id=\"attachment_311655\" aria-describedby=\"caption-attachment-311655\" style=\"width: 443px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-311655 size-full\" src=\"https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2020\/03\/1.jpg\" alt=\"Cookie\" width=\"443\" height=\"600\" srcset=\"https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2020\/03\/1.jpg 443w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2020\/03\/1-222x300.jpg 222w\" sizes=\"auto, (max-width: 443px) 100vw, 443px\"><figcaption id=\"caption-attachment-311655\" class=\"wp-caption-text\">Foto: Nosalty<\/figcaption><\/figure>\n<p><strong>Zutaten f\u00fcr 6 Portionen<\/strong><\/p>\n<p><strong>F\u00fcr den braunen Mantel<\/strong><\/p>\n<ul>\n<li>15 dkg Hackkekse<\/li>\n<li>10 dkg Puderzucker<\/li>\n<li>5 dkg Margarine<\/li>\n<li>5 dkg dunkle Schokolade (geschmolzen)<\/li>\n<li>2 EL unges\u00fc\u00dftes Kakaopulver<\/li>\n<li>20 ml Creme<\/li>\n<\/ul>\n<p><strong>F\u00fcr die rote und gr\u00fcne Schicht<\/strong><\/p>\n<ul>\n<li>15 dkg Hackkekse<\/li>\n<li>10 dkg Puderzucker<\/li>\n<li>5 dkg Margarine<\/li>\n<li>20 ml Creme<\/li>\n<li>10 Tropfen Lebensmittelfarbe (rot, gr\u00fcn)<\/li>\n<li>5 Teel\u00f6ffel goldenes Birnenaroma<\/li>\n<li>5 Tropfen Bittermandelaroma<\/li>\n<\/ul>\n<p><strong>F\u00fcr den wei\u00dfen Mantel<\/strong><\/p>\n<ul>\n<li>10 dkg Kokossp\u00e4ne<\/li>\n<li>8 dkg Puderzucker<\/li>\n<li>5 dkg Margarine<\/li>\n<\/ul>\n<p><strong>Anleitung<\/strong><\/p>\n<p>F\u00fcr die braune Schicht den Hackkeks, Puderzucker und das Kakaopulver vermischen Alles zusammen mit der Margarine mischen, dann kneten, etwas Sahne und 5 dkg geschmolzene Schokolade dazugeben Genug Sahne hinzuf\u00fcgen, damit es sich leicht dehnen l\u00e4sst, aber nicht zu weich.<\/p>\n<p>F\u00fcr die roten und gr\u00fcnen Schichten den Puderzucker zu den Hackkeksen geben, die Margarine hineinbr\u00f6seln und so viel Sahne hinzuf\u00fcgen, dass sie fest wird. Dann teilen Sie die Mischung so auf, dass Sie etwas mehr von der roten Mischung haben. Zur roten Schicht f\u00fcgen wir das goldene Birnenaroma und die rote Lebensmittelfarbe hinzu. Um die gr\u00fcne Mischung herzustellen, f\u00fcgen Sie die gr\u00fcne Farbe und das Mandelaroma hinzu. Wenn das Aroma es zu weich macht, f\u00fcgen Sie einfach weitere zerbr\u00f6selte Kekse hinzu. F\u00fcr die wei\u00dfe Schicht mischen Sie die Kokosnuss mit Puderzucker und Margarine.<\/p>\n<p>Den Teig zwischen 2 Antihaft-Backpapieren (8 mm) verteilen, aufrollen! mit dem gr\u00fcnen Teig beginnen und sanft aufrollen, dann den wei\u00dfen Teig darum wickeln, dann den roten um die wei\u00dfe Rolle, und mit dem braunen abschlie\u00dfen, die Rolle fest in Folie wickeln und gut abk\u00fchlen lassen, mit einem scharfen Messer schneiden, mit Hilfe eines Zahnstochers kann man sie gerippt aussehen lassen, sodass sie eher wie eine Kokarde aussieht.<\/p>\n<blockquote>\n<p>Wenn Sie mehr \u00fcber die Herkunft der rot-wei\u00df-gr\u00fcnen Flagge Ungarns erfahren m\u00f6chten, schauen Sie sich unseren folgenden Artikel an.<\/p>\n<\/blockquote>\n<p><a class=\"dnh-embed-link\" href=\"https:\/\/dailynewshungary.com\/de\/warum-ist-die-farbe-der-ungarischen-flagge-rot-weis-grun\/\"><\/p>\n<div class=\"dnh-embed\">\n<div class=\"dnh-embed-thumb\"><img loading=\"lazy\" decoding=\"async\" width=\"3984\" height=\"2656\" src=\"https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2019\/03\/hungarian-flag-hungary.jpg\" class=\"attachment-embed_thumbnail size-embed_thumbnail wp-post-image\" alt=\"Ungarische Flagge, Ungarn\" srcset=\"https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2019\/03\/hungarian-flag-hungary.jpg 3984w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2019\/03\/hungarian-flag-hungary-300x200.jpg 300w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2019\/03\/hungarian-flag-hungary-768x512.jpg 768w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2019\/03\/hungarian-flag-hungary-1024x683.jpg 1024w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2019\/03\/hungarian-flag-hungary-220x147.jpg 220w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2019\/03\/hungarian-flag-hungary-600x400.jpg 600w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2019\/03\/hungarian-flag-hungary-200x133.jpg 200w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2019\/03\/hungarian-flag-hungary-1080x720.jpg 1080w\" sizes=\"auto, (max-width: 3984px) 100vw, 3984px\"><\/div>\n<h5 class=\"dnh-embed-title\"><span>Lesen Sie auch<\/span>Warum ist die Farbe der ungarischen Flagge Rot-Wei\u00df-Gr\u00fcn?<\/h5>\n<\/div>\n<p><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wenn Sie immer noch schlecht f\u00fchlen, dass alle Feierlichkeiten am 15. M\u00e4rz abgesagt werden, machen Sie diese roten, wei\u00dfen und gr\u00fcnen Rezepte, um sich selbst oder andere aufzumuntern Probieren Sie die Farben der ungarischen Flagge! Caprese-salat Dies ist das einfachste und einfachste aller Rezepte. Die italienische Spezialit\u00e4t ist in weniger als 5 Minuten fertig. Das [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":722612,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1098],"tags":[1473,1196,1268,1344,1529,1076],"class_list":["post-722611","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gesellschaft","tag-essen","tag-fotogalerie","tag-gastronomie","tag-liste","tag-rezept","tag-ungarn"],"blocksy_meta":[],"acf":[],"author_username":"Kitti0317","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"","focus_keyword":"","canonical_url":"","robots":"","primary_category":"1098","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/722611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=722611"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/722611\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/722612"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=722611"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=722611"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=722611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}