{"id":722908,"date":"2020-03-15T10:00:00","date_gmt":"2020-03-15T09:00:00","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/oppositionsparteien-schlagen-masnahmen-zur-unterstutzung-der-eltern-wahrend-der-schulschliesung-vor\/"},"modified":"2020-03-15T10:00:00","modified_gmt":"2020-03-15T09:00:00","slug":"oppositionsparteien-schlagen-masnahmen-zur-unterstutzung-der-eltern-wahrend-der-schulschliesung-vor","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/oppositionsparteien-schlagen-masnahmen-zur-unterstutzung-der-eltern-wahrend-der-schulschliesung-vor\/","title":{"rendered":"Oppositionsparteien schlagen Ma\u00dfnahmen zur Unterst\u00fctzung der Eltern w\u00e4hrend der Schulschlie\u00dfung vor"},"content":{"rendered":"<p><strong>Drei Oppositionsparteien schlugen am Samstag Ma\u00dfnahmen zur Entlastung der Eltern von Schulkindern vor, nachdem die Regierung im Rahmen von Ma\u00dfnahmen als Reaktion auf den Coronavirus-Ausbruch die vor\u00fcbergehende Schlie\u00dfung ungarischer Grund- und Oberschulen angek\u00fcndigt hatte.<\/strong><\/p>\n<p>Die Demokratische Koalition (DK) habe sechs Vorschl\u00e4ge zu Schulschlie\u00dfungen vorgelegt, sagte der Abgeordnete Gergely Arat\u00f3 auf einer Pressekonferenz.<\/p>\n<p>DK schl\u00e4gt die Zahlung des vollen Lohns f\u00fcr Eltern vor, die mit ihren Kindern zu Hause bleiben, um die Gro\u00dfeltern vor einer m\u00f6glichen Infektion zu sch\u00fctzen, sagte Arat\u00f3.<\/p>\n<ul>\n<li><a href=\"https:\/\/dailynewshungary.com\/news_to_go\/coronavirus-hungary-case-count-rises-to-30\/\"><strong>Die Zahl der F\u00e4lle im Fall Coronavirus 6 Ungarn steigt auf 30<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/dailynewshungary.com\/de\/coronavirus-budapests-kindergarten-sollen-geschlossen-werden\/\"><strong>Coronavirus \u2013 Budapests Kinderg\u00e4rten sollen geschlossen werden<\/strong><\/a><\/li>\n<\/ul>\n<p>Er forderte die Regierung auf, eine Tagesbetreuung f\u00fcr die Kinder von Polizisten, Soldaten, Gesundheitspersonal, Journalisten und anderen Personen zu organisieren, deren Position keinen l\u00e4ngeren Urlaub zul\u00e4sst.<\/p>\n<blockquote>\n<p>Kinder aus benachteiligten Familien sollten weiterhin Zugang zu kostenlosen Schulessen haben, sagte er.<\/p>\n<\/blockquote>\n<p>Bez\u00fcglich eines \u00dcbergangs zu digitalen Lehrmaterialien schlug Arat\u00f3 vor, dass Kan\u00e4le des \u00f6ffentlich-rechtlichen Fernsehens Grundschulmaterialien ausstrahlen sollten, die dann im Internet verf\u00fcgbar gemacht werden sollten. Arat\u00f3 forderte die Regierung au\u00dferdem auf, eine Entscheidung \u00fcber die Schlie\u00dfung von Kinderg\u00e4rten und Kinderkrippen zu treffen.<\/p>\n<p>Auf einer separaten Pressekonferenz sagte der sozialistische Abgeordnete \u00c1gnes Kunhalmi, der Premierminister habe das \u201eRichtige zu tun\u201czu sp\u00e4t erkannt und darauf bestanden, dass Viktor Orb\u00e1n am Freitagmorgen \u201eLehrern mit unbezahltem Urlaub und Sch\u00fclern drohte, das Jahr wiederholen zu m\u00fcssen\u201cim Falle einer Schulschlie\u00dfung ordnete er dann am Freitagabend die Schlie\u00dfung an, sagte Kunhalmi.<\/p>\n<p>Kunhalmi schlug au\u00dferdem vor, dass \u00f6ffentliche Fernsehsender die Unterrichtsmaterialien f\u00fcr 1-4-Kl\u00e4ssler ausstrahlen sollten, w\u00e4hrend Materialien f\u00fcr 5-8-Kl\u00e4ssler und Oberstufensch\u00fcler online verf\u00fcgbar sein sollten. Sie forderte die Regierung auf, Kinderg\u00e4rten zu schlie\u00dfen.<\/p>\n<blockquote>\n<p>Kunhalmi sagte, dass die Abschlusspr\u00fcfungen der Gymnasien, die urspr\u00fcnglich am 4. Mai beginnen sollten, nicht verschoben werden sollten. \u201eAlle rechtlichen und technischen Mittel stehen zur Verf\u00fcgung, um die Pr\u00fcfungen zu organisieren, m\u00f6glicherweise nur in schriftlicher Form, sagte sie.<\/p>\n<\/blockquote>\n<p>Die lokalen Beh\u00f6rden werden zus\u00e4tzliche Ressourcen und Schutzausr\u00fcstung ben\u00f6tigen, um den Ausnahmezustand zu bew\u00e4ltigen (die Regierung k\u00fcndigte am Mittwoch an), sagte KunhalmiSie bestand darauf, dass 600 Milliarden Forint (1,8 Mrd. EUR) \u201cleicht\u201d im Zentralhaushalt f\u00fcr die Coronavirus-Reaktion umgeschichtet werden k\u00f6nnten, dies k\u00f6nnte durch die Verwendung der 450 Milliarden Forint in der Haushaltsreserve, die Halbierung des 100-Milliarden-Forint-Budgets der \u00f6ffentlichen Medien und durch die Streichung des \u201cPropagandaministeriums\u201d von seiner gesamten 150 Milliarden Forint-Zuweisung geschehen, sagte Kunhalmi.<\/p>\n<p>Unterdessen forderte die gr\u00fcne LMP die Regierung auf, Einkaufszentren zu schlie\u00dfen, um zu verhindern, dass sich w\u00e4hrend der vor\u00fcbergehenden Schulschlie\u00dfung Sch\u00fcler dort versammeln.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Drei Oppositionsparteien schlugen am Samstag Ma\u00dfnahmen zur Entlastung der Eltern von Schulkindern vor, nachdem die Regierung im Rahmen von Ma\u00dfnahmen als Reaktion auf den Coronavirus-Ausbruch die vor\u00fcbergehende Schlie\u00dfung ungarischer Grund- und Oberschulen angek\u00fcndigt hatte. Die Demokratische Koalition (DK) habe sechs Vorschl\u00e4ge zu Schulschlie\u00dfungen vorgelegt, sagte der Abgeordnete Gergely Arat\u00f3 auf einer Pressekonferenz. DK schl\u00e4gt die [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":722909,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1098],"tags":[1438,2243,1222,1107,1502,1695,1076],"class_list":["post-722908","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gesellschaft","tag-bildung","tag-coronavirus","tag-demokratische-koalition","tag-gesundheit","tag-kinder","tag-sozialisten","tag-ungarn"],"blocksy_meta":[],"acf":[],"author_username":"ugyelet","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"","focus_keyword":"","canonical_url":"","robots":"","primary_category":"1098","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/722908","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=722908"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/722908\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/722909"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=722908"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=722908"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=722908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}