{"id":723117,"date":"2020-03-09T08:30:00","date_gmt":"2020-03-09T07:30:00","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/auslandische-studenten-sind-schockiert-uber-das-quarantanesystem-in-ungarn\/"},"modified":"2020-03-09T08:30:00","modified_gmt":"2020-03-09T07:30:00","slug":"auslandische-studenten-sind-schockiert-uber-das-quarantanesystem-in-ungarn","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/auslandische-studenten-sind-schockiert-uber-das-quarantanesystem-in-ungarn\/","title":{"rendered":"Ausl\u00e4ndische Studenten sind schockiert \u00fcber das Quarant\u00e4nesystem in Ungarn"},"content":{"rendered":"<p><strong>Obwohl die Gruppenkameraden des iranischen Studenten an SOTE freiwillig zum Coronavirus-Test ins St. Ladislaus-Krankenhaus gingen, weigerte sich das Krankenhaus, den Test durchzuf\u00fchren. Die Studenten waren besorgt, weil sie alle direkten Kontakt mit dem iranischen Studenten hatten, der sp\u00e4ter als infiziert mit dem Coronavirus entdeckt wurde, berichtet <a href=\"https:\/\/index.hu\/kulfold\/2020\/03\/08\/eloszor_elhajtottak_majd_megis_karantenba_kerultek_a_sote-s_diak_csoporttarsai\/\" target=\"_blank\" rel=\"noopener noreferrer\"><em>Index<\/em><\/a>.<\/strong><\/p>\n<p>Ein anonymer ausl\u00e4ndischer Pharmaziestudent erz\u00e4hlte <em>Index<\/em> Dass Sanit\u00e4ter am Samstag im Morgengrauen an die Haust\u00fcr seines Hauses klopften, sie lie\u00dfen ihn ein auf Ungarisch verfasstes Papier unterschreiben und sagten ihm, er solle einpacken, da er ins Krankenhaus gebracht werden m\u00fcsse, niemand erkl\u00e4rte ihm laut dem Studenten, was genau vor sich ging, noch erhielt er Informationen von den Sanit\u00e4tern, weil sie nicht sehr gut Englisch sprachen, und niemand hatte sie im Voraus \u00fcber die Situation informiert, nach Angaben des Pharmaziestudenten f\u00fchrten sie den Test erst viel sp\u00e4ter am Morgen durch.<\/p>\n<p>Der Student sagte, dass er und seine Gruppenkameraden in 3- und 6-Bett-Zimmern untergebracht wurden, obwohl sie darum gebeten hatten, sie auch voneinander getrennt zu halten, wenn dies m\u00f6glich sei.<\/p>\n<blockquote>\n<p>Das Krankenhaus behauptete, es g\u00e4be nicht gen\u00fcgend Zimmer, daher m\u00fcssten 2-5 Personen auf einer Station untergebracht werden.<\/p>\n<\/blockquote>\n<p>Ihr Gruppenkamerad, der auf einer 6-Betten-Station auf seine Ergebnisse wartete, wurde positiv auf das Virus getestet. Er wurde in der Nacht zum Samstag gegen 11 Uhr unter Quarant\u00e4ne gestellt und der neue Fall wurde am Sonntagmorgen von der Regierung best\u00e4tigt.<\/p>\n<p>Sie k\u00f6nnen auf unserem Tag nach weiteren Neuigkeiten zum Coronavirus suchen, aber hier sind zwei f\u00fcr Sie: die Regierung <a href=\"https:\/\/dailynewshungary.com\/de\/die-regierung-sagt-die-staatsfeierlichkeiten-am-15-marz-wegen-bedenken-hinsichtlich-des-coronavirus-ab\/\" target=\"_blank\" rel=\"noopener noreferrer\">Beschloss, die Feierlichkeiten am 15. M\u00e4rz aus Sorge um das Virus abzusagen<\/a>, und laut einer Umfrage, und <a href=\"https:\/\/dailynewshungary.com\/de\/umfrage-56-der-ungarn-sind-besorgt-uber-das-coronavirus\/\" target=\"_blank\" rel=\"noopener noreferrer\">Nur 56% der Ungarn sind besorgt \u00fcber das Coronavirus<\/a>.<\/p>\n<p>Laut Aussage des Pharmaziestudenten teilte ihnen der Arzt nur mit, dass im selben Fl\u00fcgel ein Infizierter gefunden worden sei, er sagte aber nicht, wer es sei und ob er bereits unter Quarant\u00e4ne gestellt worden sei oder nicht Der Student interviewte von <em>Index<\/em> Kam am 2. M\u00e4rz mit dem iranischen Studenten mit Coronavirus in Kontakt, aber alle m\u00fcssen bis zum 21. M\u00e4rz in Quarant\u00e4ne bleiben. Viele beschweren sich \u00fcber den Mangel an angemessenen Informationen und die Tatsache, dass Professoren nur verpflichtet sind, in h\u00e4uslicher Quarant\u00e4ne zu bleiben. Wer auf einer Station mit positiv getesteten Studenten untergebracht wurde, hat Angst, dass er sich im Krankenhaus infiziert haben k\u00f6nnte. Studenten w\u00fcrden es vorziehen, in h\u00e4uslicher Quarant\u00e4ne zu bleiben, weil sie es f\u00fcr sicherer halten, als in einem Zimmer mit anderen zu sein, die ebenfalls potenzielle Vektoren sind.<\/p>\n<p>Nach den Daten von Coronavirus.gov.hu vom Sonntagmorgen befinden sich derzeit in Ungarn 67 Personen in Quarant\u00e4ne statt bisher 48. Aus den Daten geht nicht hervor, wer die zus\u00e4tzlichen Patienten sind.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Obwohl die Gruppenkameraden des iranischen Studenten an SOTE freiwillig zum Coronavirus-Test ins St. Ladislaus-Krankenhaus gingen, weigerte sich das Krankenhaus, den Test durchzuf\u00fchren. Die Studenten waren besorgt, weil sie alle direkten Kontakt mit dem iranischen Studenten hatten, der sp\u00e4ter als infiziert mit dem Coronavirus entdeckt wurde, berichtet Index. Ein anonymer ausl\u00e4ndischer Pharmaziestudent erz\u00e4hlte Index Dass Sanit\u00e4ter [&hellip;]<\/p>\n","protected":false},"author":28,"featured_media":723118,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1098],"tags":[2243,1582,1076],"class_list":["post-723117","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gesellschaft","tag-coronavirus","tag-krankenhaus","tag-ungarn"],"blocksy_meta":[],"acf":[],"author_username":"Theecchipete","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"","focus_keyword":"","canonical_url":"","robots":"","primary_category":"1098","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/723117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=723117"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/723117\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/723118"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=723117"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=723117"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=723117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}