{"id":723418,"date":"2020-02-28T14:50:00","date_gmt":"2020-02-28T13:50:00","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/etwa-30-40-ungarn-auf-touristenbooten-wurden-aufgrund-des-coronavirus-in-mexiko-unter-quarantane-gestellt\/"},"modified":"2020-02-28T14:50:00","modified_gmt":"2020-02-28T13:50:00","slug":"etwa-30-40-ungarn-auf-touristenbooten-wurden-aufgrund-des-coronavirus-in-mexiko-unter-quarantane-gestellt","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/etwa-30-40-ungarn-auf-touristenbooten-wurden-aufgrund-des-coronavirus-in-mexiko-unter-quarantane-gestellt\/","title":{"rendered":"Etwa 30-40 Ungarn auf Touristenbooten wurden aufgrund des Coronavirus in Mexiko unter Quarant\u00e4ne gestellt"},"content":{"rendered":"<p><strong>Etwa 30-40 Ungarn seien aufgrund des Verdachts auf Coronavirus-F\u00e4lle in Mexiko auf einem Touristenboot unter Quarant\u00e4ne gestellt, sagte der Au\u00dfenminister am Freitag auf einer Pressekonferenz zu einem anderen Thema.<\/strong><\/p>\n<p>Die Regierung stehe in direktem Kontakt mit zwei der Familien, sagte P\u00e9ter Szijj\u00e1rt\u00f3.<\/p>\n<p>Zwei Personen auf dem Boot h\u00e4tten \u00fcber Grippesymptome berichtet, erste Berichte zeigten jedoch, dass diese nicht mit dem Coronavirus in Zusammenhang st\u00fcnden, f\u00fcgte er hinzu.<\/p>\n<p>Das Boot namens Meraviglia bef\u00f6rdere rund 6.000 Menschen und \u00c4rzte f\u00fchren derzeit Tests durch, um Covid-19 auszuschlie\u00dfen, sagte Szijj\u00e1rt\u00f3.<\/p>\n<p>Dar\u00fcber hinaus seien derzeit insgesamt 12 Ungarn in f\u00fcnf L\u00e4ndern in Quarant\u00e4ne und einer von ihnen sei positiv auf das Coronavirus getestet worden, sagte er. F\u00fcnf davon seien in Spanien, drei in Japan, zwei in China, einer in Italien und ein weiterer in Deutschland, f\u00fcgte er hinzu.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Etwa 30-40 Ungarn seien aufgrund des Verdachts auf Coronavirus-F\u00e4lle in Mexiko auf einem Touristenboot unter Quarant\u00e4ne gestellt, sagte der Au\u00dfenminister am Freitag auf einer Pressekonferenz zu einem anderen Thema. Die Regierung stehe in direktem Kontakt mit zwei der Familien, sagte P\u00e9ter Szijj\u00e1rt\u00f3. Zwei Personen auf dem Boot h\u00e4tten \u00fcber Grippesymptome berichtet, erste Berichte zeigten jedoch, [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":723419,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1098],"tags":[1470,2243,1107,1108,1076],"class_list":["post-723418","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gesellschaft","tag-ausenministerium-fur-ungarn","tag-coronavirus","tag-gesundheit","tag-gesundheitssystem","tag-ungarn"],"blocksy_meta":[],"acf":[],"author_username":"ugyelet","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"","focus_keyword":"","canonical_url":"","robots":"","primary_category":"1098","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/723418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=723418"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/723418\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/723419"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=723418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=723418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=723418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}