{"id":725909,"date":"2019-11-30T12:00:31","date_gmt":"2019-11-30T11:00:31","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/eu-kommission-gesundheitszustand-in-ungarn-2019\/"},"modified":"2019-11-30T12:00:31","modified_gmt":"2019-11-30T11:00:31","slug":"eu-kommission-gesundheitszustand-in-ungarn-2019","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/eu-kommission-gesundheitszustand-in-ungarn-2019\/","title":{"rendered":"EU-Kommission: Gesundheitszustand in Ungarn 2019"},"content":{"rendered":"<p><strong>Niedrige Zahlungen, nicht gen\u00fcgend finanzielle Unterst\u00fctzung, ein ungesundes Umfeld und viele andere Faktoren legen nahe, dass die Gesundheitsversorgung nicht die Priorit\u00e4t Ungarns ist Dazu tragen auch die Gesundheit, die Lebenssituation und die chronischen Krankheiten vieler Kinder der Ungarn bei. <\/strong><\/p>\n<p><a href=\"https:\/\/www.napi.hu\/magyar_gazdasag\/europai-bizottsag-orszagjelentes-egeszsegugy-siralmas-adatok-betegseg.695959.html\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Nach <em>Napi<\/em><\/strong><\/a>28 L\u00e4ndern zusammen mit Norwegen und Island ihren Bericht bez\u00fcglich der Qualit\u00e4t des Gesundheitssystems ver\u00f6ffentlichte die Europ\u00e4ische Kommission Der Bericht ma\u00df auch die Gesundheit der Bev\u00f6lkerung und die Wirksamkeit der Gesundheitseinrichtungen und &#8211; dienste in jedem Land.<\/p>\n<blockquote>\n<p>In dem Bericht hei\u00dft es, dass dies trotz vieler Entwicklungen im ungarischen Gesundheitssystem seit dem Jahr 2000 der Fall sei <a href=\"https:\/\/dailynewshungary.com\/de\/ungarn-verfugt-uber-das-schwachste-gesundheitssystem-im-mitteleuropaischen-raum\/\" target=\"_blank\" rel=\"noopener noreferrer\">immer noch einer der ung\u00fcnstigsten in der Europ\u00e4ischen Union<\/a>. Das System ist zu krankenhausorientiert und unternimmt keine Anstrengungen in der Pr\u00e4vention und den Grundbed\u00fcrfnissen.<\/p>\n<\/blockquote>\n<p>Die durchschnittliche Lebensspanne ist seit 2000 gestiegen, liegt aber immer noch um f\u00fcnf Jahre unter dem EU-Durchschnitt Ungarische Frauen leben sieben Jahre l\u00e4nger als M\u00e4nner Unter den 65-j\u00e4hrigen Ungarn berichteten \u00fcber 2\/3 von ihnen \u00fcber chronische KrankheitenDas liegt daran <a href=\"https:\/\/dailynewshungary.com\/de\/viele-menschen-sterben-in-ungarn-wo-ein-neues-gesundheitsprogramm-erforderlich-ist\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Ungarn leiden an Krankheiten, die ihren Alltag und ihre Gesundheit beeintr\u00e4chtigen<\/strong><\/a>.<\/p>\n<blockquote>\n<p>Ungarn geh\u00f6rt zu den <a href=\"https:\/\/dailynewshungary.com\/de\/ungarn-zum-ersten-nichtraucherland-der-eu\/\" target=\"_blank\" rel=\"noopener noreferrer\">St\u00e4rkste Raucherl\u00e4nder<\/a> In der EU. <a href=\"https:\/\/dailynewshungary.com\/de\/ungarn-trinken-wie-russen\/\" target=\"_blank\" rel=\"noopener noreferrer\">Konsum alkoholischer Getr\u00e4nke<\/a> Auch hat einen extrem hohen Prozentsatz, vor allem unter den Angeh\u00f6rigen der j\u00fcngeren Generationen Diese Zahl liegt 10% \u00fcber dem EU-Durchschnitt Au\u00dferdem betreffen die meisten t\u00f6dlichen Krebserkrankungen durch Rauchen Ungarn in der EU.<\/p>\n<\/blockquote>\n<p>Dem Bericht zufolge h\u00e4tten im Jahr 2016 etwa 30.000 t\u00f6dliche Vorf\u00e4lle durch effizientere Gesundheitsdienste verhindert werden k\u00f6nnen, weitere 16.000 mit sofortiger Hilfe von Gesundheitsinstituten. Der Bericht schlug vor, Entwicklungen und Anstrengungen in Bezug auf die Grundbed\u00fcrfnisse des Gesundheitsdienstes zu unternehmen, um viele t\u00f6dliche Vorf\u00e4lle zu verhindern. Au\u00dferdem gibt es eine <a href=\"https:\/\/dailynewshungary.com\/de\/nicht-genugend-arzte-im-saint-margaret-hospital-bereitschaftsdienst-angeordnet\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Starker Bedarf an mehr \u00c4rzten und Fach\u00e4rzten<\/strong><\/a> In der Branche, und das ist der Grund, warum die ungarische Regierung die Zahlungen dieser Menschen erh\u00f6ht hat.<\/p>\n<blockquote>\n<p>Neben einer noch st\u00e4rkeren Erh\u00f6hung ihrer Zahlungen ist auch die Entwicklung des Arbeitsumfelds der \u00c4rzte, Krankenschwestern und anderen Arbeitnehmer von entscheidender Bedeutung.<\/p>\n<\/blockquote>\n<p>Die j\u00fcngsten von der Regierung eingef\u00fchrten Projekte waren erfolgreich, aber Ungarn braucht noch etwas mehr Mit der Reform des Krankenhaussystems des Landes k\u00f6nnte Ungarn nach Ansicht der Europ\u00e4ischen Union einen enormen Schritt in Richtung Entwicklung machen.<\/p>\n<h4>Lesen Sie den vollst\u00e4ndigen Bericht <a href=\"https:\/\/ec.europa.eu\/health\/sites\/health\/files\/state\/docs\/2019_chp_hu_hungary.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>HIER (ungarische Sprache)<\/strong><\/a><\/h4>\n","protected":false},"excerpt":{"rendered":"<p>Niedrige Zahlungen, nicht gen\u00fcgend finanzielle Unterst\u00fctzung, ein ungesundes Umfeld und viele andere Faktoren legen nahe, dass die Gesundheitsversorgung nicht die Priorit\u00e4t Ungarns ist Dazu tragen auch die Gesundheit, die Lebenssituation und die chronischen Krankheiten vieler Kinder der Ungarn bei. Nach Napi28 L\u00e4ndern zusammen mit Norwegen und Island ihren Bericht bez\u00fcglich der Qualit\u00e4t des Gesundheitssystems ver\u00f6ffentlichte [&hellip;]<\/p>\n","protected":false},"author":30,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1098],"tags":[1082,1107,1138,1076],"class_list":["post-725909","post","type-post","status-publish","format-standard","hentry","category-gesellschaft","tag-europaische-union","tag-gesundheit","tag-statistik","tag-ungarn"],"blocksy_meta":[],"acf":[],"author_username":"klbgrg","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"","focus_keyword":"","canonical_url":"","robots":"","primary_category":"1098","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/725909","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=725909"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/725909\/revisions"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=725909"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=725909"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=725909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}