{"id":728278,"date":"2019-08-14T11:30:07","date_gmt":"2019-08-14T09:30:07","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/ungarns-bip-stieg-im-zweiten-quartal-um-49-prozent\/"},"modified":"2019-08-14T11:30:07","modified_gmt":"2019-08-14T09:30:07","slug":"ungarns-bip-stieg-im-zweiten-quartal-um-49-prozent","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/ungarns-bip-stieg-im-zweiten-quartal-um-49-prozent\/","title":{"rendered":"Ungarns BIP stieg im zweiten Quartal um 4,9 Prozent"},"content":{"rendered":"<p><strong>Ungarns BIP stieg im zweiten Quartal 2019 um j\u00e4hrlich 4,9 Prozent, teilte das Statistische Zentralamt (KSH) am Mittwoch in einer ersten Datenlesung mit.<\/strong><\/p>\n<p>Das Wachstumstempo verlangsamte sich von 5,3 Prozent im ersten Quartal.<\/p>\n<blockquote>\n<p>Im ersten Halbjahr lag das unbereinigte Wachstum bei 5,1 Prozent gegen\u00fcber 4,8 Prozent im Vorjahreszeitraum.<\/p>\n<\/blockquote>\n<p>Marktbasierte Dienstleistungen, der Bausektor und die Industrie trugen im zweiten Quartal 2019 haupts\u00e4chlich zum Wachstum bei, sagte KSH.<\/p>\n<blockquote>\n<p>Bereinigt um Kalenderjahreffekte erreichte das BIP-Wachstum im zweiten Quartal j\u00e4hrliche 5,1 Prozent, gegen\u00fcber 5,3 Prozent im ersten Quartal in Q1.<\/p>\n<\/blockquote>\n<p>Im ersten Halbjahr lag die Wachstumsrate bei 5,2 Prozent, gegen\u00fcber 4,8 Prozent im gleichen Zeitraum des Jahres 2018.<\/p>\n<p>Im Vergleich zum Vorquartal stieg das BIP-Wachstum im zweiten Quartal um 1,1 Prozent, verglichen mit 1,4 Prozent im ersten Quartal, bereinigt um Saison- und Kalenderjahreffekte.<\/p>\n<p>Ungarns aktualisiertes Konvergenzprogramm beziffert das BIP-Wachstum im Jahr 2019 auf 4,0 Prozent.<\/p>\n<ul>\n<li><a href=\"https:\/\/dailynewshungary.com\/de\/tourismus-auf-dem-vormarsch-ungarische-gastnachte-steigen-weiter-an\/\" target=\"_blank\" rel=\"noopener noreferrer\">Tourismus auf dem Vormarsch! ungarische Gastn\u00e4chte steigen weiter an<\/a><\/li>\n<li><a href=\"https:\/\/dailynewshungary.com\/de\/die-produktion-im-bausektor-steigt-im-juni-um-203-prozent\/\" target=\"_blank\" rel=\"noopener noreferrer\">Die Produktion im Bausektor steigt im Juni um 20,3 Prozent<\/a><\/li>\n<\/ul>\n<p>Finanzminister Mih\u00e1ly Varga kommentierte die Daten und sagte, die ungarische Wirtschaft werde sich auch in der zweiten Jahresh\u00e4lfte weiterhin gut entwickeln. Einer konservativen Sch\u00e4tzung zufolge werde das BIP-Wachstum in diesem Jahr voraussichtlich bei etwa 4,3-4,4 Prozent liegen, sagte er.<\/p>\n<p>Die Wirtschaft habe nicht an Schwung verloren, sagte Varga und f\u00fcgte hinzu, dass die Q2-Wachstumsrate die Erwartungen des Ministeriums \u00fcbertroffen habe. Die vorl\u00e4ufigen Daten deuten darauf hin, dass Ungarn im zweiten Quartal die h\u00f6chste Wachstumsrate in der Europ\u00e4ischen Union verzeichnete, sagte er.<\/p>\n<blockquote>\n<p>Der Bericht der KSH sei besonders positiv, sagte der Minister, da die Wirtschaftsleistung zwar gestiegen sei, die Staatsverschuldung jedoch weiter zur\u00fcckgegangen sei.<\/p>\n<\/blockquote>\n<p>Varga sagte, staatliche Ma\u00dfnahmen wie ein sechsj\u00e4hriger Lohnvertrag mit Arbeitgebern, die Verbesserung der Wettbewerbsf\u00e4higkeit, Wohnbauf\u00f6rderungen und staatliche Investitionen h\u00e4tten das Wirtschaftswachstum um 1,6 Prozentpunkte gesteigert. Das Wachstum werde immer noch durch den Konsum der privaten Haushalte, die Erh\u00f6hung der Exportkapazit\u00e4ten und eine effizientere Nutzung von EU-Mitteln vorangetrieben, f\u00fcgte er hinzu.<\/p>\n<p>P\u00e9ter Virov\u00e1cz von der ING Bank sagte, das Wirtschaftswachstum im Q2 sei h\u00f6her als von Analysten erwartet und \u00fcberraschend, da monatliche Wirtschaftsdaten aus verschiedenen Sektoren eine Verlangsamung verhei\u00dfen h\u00e4tten. In H2 k\u00f6nnte sich das Wachstumstempo weiter verlangsamen und das BIP k\u00f6nnte f\u00fcr das Jahr um rund 4,5 Prozent wachsen.<\/p>\n<p>Analyst Gergely Supp\u00e1n von der Takarekbank betonte neben EU-Mitteln und Inlandsverbrauch auch die Rolle ausl\u00e4ndischer Direktinvestitionen bei der Ankurbelung des Wachstums. Staatliche Ma\u00dfnahmen zur Unterst\u00fctzung von Familien und der Wirtschaft k\u00f6nnten negative externe Effekte in H2 ausgleichen und zu einer durchschnittlichen BIP-Wachstumsrate von 4,8 Prozent f\u00fcr das Jahr f\u00fchren, sagte er.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ungarns BIP stieg im zweiten Quartal 2019 um j\u00e4hrlich 4,9 Prozent, teilte das Statistische Zentralamt (KSH) am Mittwoch in einer ersten Datenlesung mit. Das Wachstumstempo verlangsamte sich von 5,3 Prozent im ersten Quartal. Im ersten Halbjahr lag das unbereinigte Wachstum bei 5,1 Prozent gegen\u00fcber 4,8 Prozent im Vorjahreszeitraum. Marktbasierte Dienstleistungen, der Bausektor und die Industrie [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":728279,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1281],"tags":[1076,1104],"class_list":["post-728278","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geschaft","tag-ungarn","tag-wirtschaft"],"blocksy_meta":[],"acf":[],"author_username":"alk","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"","focus_keyword":"","canonical_url":"","robots":"","primary_category":"1281","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/728278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=728278"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/728278\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/728279"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=728278"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=728278"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=728278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}