{"id":728911,"date":"2019-07-16T14:20:05","date_gmt":"2019-07-16T12:20:05","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/das-produktionswachstum-im-ungarischen-bausektor-verlangsamt-sich-auf-263-prozent\/"},"modified":"2019-07-16T14:20:05","modified_gmt":"2019-07-16T12:20:05","slug":"das-produktionswachstum-im-ungarischen-bausektor-verlangsamt-sich-auf-263-prozent","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/das-produktionswachstum-im-ungarischen-bausektor-verlangsamt-sich-auf-263-prozent\/","title":{"rendered":"Das Produktionswachstum im ungarischen Bausektor verlangsamt sich auf 26,3 Prozent"},"content":{"rendered":"<p><strong>Die Produktion des ungarischen Bausektors stieg im Mai im Jahresvergleich um 26,3 Prozent, wie vom Statistischen Zentralamt (KSH) am Dienstag ver\u00f6ffentlichte Daten zeigen.<\/strong><\/p>\n<p>Die Produktion des Geb\u00e4udesegments sei um 27,0 Prozent gestiegen, was durch den Bau von Fabriken und Lagerh\u00e4usern gesteigert worden sei, sagte KSH.<\/p>\n<blockquote>\n<p>Die Tiefbauproduktion sei um 25,7 Prozent gestiegen, unterst\u00fctzt durch Stra\u00dfen- und Eisenbahnprojekte, hie\u00df es weiter.<\/p>\n<\/blockquote>\n<p>Das Gesamtproduktionswachstum verlangsamte sich von 40,1 Prozent im April und 67,6 Prozent im M\u00e4rz F\u00fcr den Zeitraum Januar-Mai, <a href=\"https:\/\/dailynewshungary.com\/de\/der-grose-britische-zuguberfall-wie-eine-15-kopfige-bande-1963-26-millionen-pfund-stahl\/\" target=\"_blank\" rel=\"noopener noreferrer\">Konstruktion<\/a> Die Branchenproduktion stieg im Jahresvergleich um 40,4 Prozent.<\/p>\n<p>In absoluten Zahlen belief sich die Produktion im Mai auf 361,5 Milliarden Forint (1,1 Mrd. EUR) und im Januar-Mai auf 1.446,1 Milliarden.<\/p>\n<p>Der Auftragsbestand in der Branche war Ende Mai gegen\u00fcber zw\u00f6lf Monaten zuvor um 8,1 Prozent gesunken. Der Bestand stieg im Geb\u00e4udesegment um 38,4 Prozent, im Tiefbausegment fiel er jedoch um 19,1 Prozent.<\/p>\n<blockquote>\n<p>Das Auftragseingangsvolumen ging um 1,1 Prozent zur\u00fcck, da die Auftragseing\u00e4nge f\u00fcr Geb\u00e4ude um 24,0 Prozent zur\u00fcckgingen und die Auftr\u00e4ge f\u00fcr den Tiefbau um 11,9 Prozent stiegen.<\/p>\n<\/blockquote>\n<p>L\u00e1szl\u00f3 Gy\u00f6rgy, Staatssekret\u00e4r im Innovations- und Technologieministerium, sagte dem Nachrichtensender M1, dass die Baubranche drei Jahre in Folge gewachsen sei und die Produktivit\u00e4t im Jahr 2018 23 Prozent erreicht habe. Der Sektor werde voraussichtlich zwischen 2018 und 2023 Auftr\u00e4ge in H\u00f6he von 25 Milliarden Forint erhalten, sagte er und f\u00fcgte hinzu, dass angesichts dieser Arbeitsbelastung ein j\u00e4hrliches Wachstum von 10 bis 11 Prozent erforderlich sei. Die Investitionsagentur der Regierung sei eingerichtet worden, um staatliche Auftr\u00e4ge zu verwalten und den Auftragsbestand \u201eleicht einzud\u00e4mmen\u201csagte er\u201d.<\/p>\n<blockquote>\n<p>\u201cEs ist gut zu sehen, dass der Gro\u00dfteil der Bestellungen f\u00fcr Lagerh\u00e4user und Industriegeb\u00e4ude erfolgt&#8230; wobei Stra\u00dfen und Eisenbahnen eine bedeutende Rolle spielen\u201d, sagte er.<\/p>\n<\/blockquote>\n<p>In seinem Kommentar zu den Daten sagte Analyst Gergely Supp\u00e1n von Takarekbank, dass ungew\u00f6hnlich kaltes und nasses Wetter und eine h\u00f6here Basis beide eine Rolle bei der Verlangsamung des Produktionswachstums im Mai gespielt haben k\u00f6nnten. Supp\u00e1n sagte, er erwarte, dass in diesem Jahr etwa 25.000 neue H\u00e4user fertiggestellt w\u00fcrden, und prognostizierte ein ganzj\u00e4hriges Produktionswachstum von rund 30 Prozent in der Branche.<\/p>\n<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"tnnvdWZl6J\"><p><a href=\"https:\/\/dailynewshungary.com\/de\/das-weltberuhmte-ungarische-opernhaus-konnte-mehrere-jahre-lang-geschlossen-sein\/\">Das weltber\u00fchmte ungarische Opernhaus k\u00f6nnte mehrere Jahre lang geschlossen sein!<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u201cWorld famous Hungarian Opera house might be closed for several years!\u201d \u2014 DailyNewsHungary\" src=\"https:\/\/dailynewshungary.com\/de\/das-weltberuhmte-ungarische-opernhaus-konnte-mehrere-jahre-lang-geschlossen-sein\/embed\/#?secret=eeNcUL6qKy#?secret=tnnvdWZl6J\" data-secret=\"tnnvdWZl6J\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Produktion des ungarischen Bausektors stieg im Mai im Jahresvergleich um 26,3 Prozent, wie vom Statistischen Zentralamt (KSH) am Dienstag ver\u00f6ffentlichte Daten zeigen. Die Produktion des Geb\u00e4udesegments sei um 27,0 Prozent gestiegen, was durch den Bau von Fabriken und Lagerh\u00e4usern gesteigert worden sei, sagte KSH. Die Tiefbauproduktion sei um 25,7 Prozent gestiegen, unterst\u00fctzt durch Stra\u00dfen- [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":728912,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1281],"tags":[1190,1076,1104],"class_list":["post-728911","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geschaft","tag-bau","tag-ungarn","tag-wirtschaft"],"blocksy_meta":[],"acf":[],"author_username":"alk","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"","focus_keyword":"","canonical_url":"","robots":"","primary_category":"1281","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/728911","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=728911"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/728911\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/728912"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=728911"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=728911"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=728911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}