{"id":732407,"date":"2019-02-16T15:00:22","date_gmt":"2019-02-16T14:00:22","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/katinka-hosszu-sollte-sich-dem-synchronschwimmen-zuwenden\/"},"modified":"2019-02-16T15:00:22","modified_gmt":"2019-02-16T14:00:22","slug":"katinka-hosszu-sollte-sich-dem-synchronschwimmen-zuwenden","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/katinka-hosszu-sollte-sich-dem-synchronschwimmen-zuwenden\/","title":{"rendered":"\u2018Katinka Hossz\u00fa sollte sich dem Synchronschwimmen zuwenden\u2019"},"content":{"rendered":"<p><strong>Die neun Mitgliedsorganisationen des Ungarischen Synchronschwimmverbandes haben ihre Zweifel am derzeitigen Pr\u00e4sidenten S\u00e1ndor Balogh ge\u00e4u\u00dfert. Bevor er jedoch offiziell zur\u00fccktreten musste, widerrief er sein Amt per SMS. <\/strong><\/p>\n<p>F\u00fcr den 9. Februar wurde eine Dringlichkeitssitzung angesetzt, bei der die Mitgliedsorganisationen die Abberufung von Baloghs Pr\u00e4sidentschaft besprechen sollten. 24.hu berichtet, dass Balogh per WhatsApp-SMS signalisiert habe, dass er mit Wirkung zum 17. M\u00e4rz zur\u00fccktritt, und dies sp\u00e4ter auf den 9. Februar \u00e4ndert.<\/p>\n<p>Im Folgenden finden Sie ein Interview von 24.hu mit dem Ex-Pr\u00e4sidenten zum Thema seines Abgangs und seiner d\u00fcsteren Sicht auf das ungarische Synchronschwimmen.<\/p>\n<p><strong>Haben Sie irgendwelche b\u00f6sen Gef\u00fchle wegen Ihrer erzwungenen K\u00fcndigung nach nur neun Monaten?<\/strong><\/p>\n<p>Ich schon, aber gleichzeitig nicht In Situationen, wo andere mich f\u00fcr die Stelle f\u00fcr ungeeignet halten oder meinen, ich h\u00e4tte meine Rolle erf\u00fcllt und ich werde nicht mehr gebraucht, werde ich nicht l\u00e4nger k\u00e4mpfen, wenn zwei Karren Kopf an Kopf stehen und einer von ihnen beschleunigt, ohne die Absicht zu bremsen, wird der Dialog zwischen ihnen unm\u00f6glich, da die Entfernung w\u00e4chst.<\/p>\n<p><strong>Was prognostizieren Sie f\u00fcr die Zukunft?<\/strong><\/p>\n<p>Das Staatssekretariat stellt im Jahr 2019 9 Millionen Forint (28 Tausend EUR) f\u00fcr den Sport bereit, also lassen Sie uns die Zahlen ermitteln:<\/p>\n<blockquote>\n<p><span style=\"color: #008080;\">Die Weltmeisterschaft findet in S\u00fcdkorea statt und die Reisekosten betragen das 1,5-fache dieser Summe.<\/span><\/p>\n<\/blockquote>\n<p><strong>Wo hast du wohl einen Fehler gemacht?<\/strong><\/p>\n<p>Meine Budgetsch\u00e4tzung f\u00fcr 2019 lag bei 250 Millionen Forint, damit w\u00e4re ein symbolisches Gehalt f\u00fcr jeden Sportler und jede Sportlerin gedeckt gewesen, damit sie auch in jungen Jahren auf der Spur bleiben k\u00f6nnten Vereine h\u00e4tten auch Hilfe bekommen Wir bekommen kaum Geld aus dem Gerevich-Fonds, das \u00c4ndern ist von gro\u00dfer Bedeutung.<\/p>\n<p><em>Balogh erw\u00e4hnte, dass er zu gro\u00dfe Tr\u00e4ume hatte, als er hoffte, dass Fortschritte finanzielle Unterst\u00fctzung erhalten w\u00fcrden, aber Sponsoren und die Regierung scheinen dieser Ansicht nicht zuzustimmen.<\/em><\/p>\n<figure id=\"attachment_211459\" aria-describedby=\"caption-attachment-211459\" style=\"width: 1024px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-211459\" src=\"https:\/\/dailynewshungary.com\/wp-content\/uploads\/2018\/09\/BS-e1537619737745-1024x564.jpg\" alt=\"S\u00e1ndor Balogh HTCC AHU Afrika Ungarn\" width=\"1024\" height=\"564\" srcset=\"https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2018\/09\/BS-e1537619737745-1024x564.jpg 1024w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2018\/09\/BS-e1537619737745-300x165.jpg 300w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2018\/09\/BS-e1537619737745-768x423.jpg 768w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2018\/09\/BS-e1537619737745-220x121.jpg 220w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2018\/09\/BS-e1537619737745-600x330.jpg 600w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2018\/09\/BS-e1537619737745-200x110.jpg 200w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2018\/09\/BS-e1537619737745-1080x595.jpg 1080w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2018\/09\/BS-e1537619737745.jpg 1584w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"><figcaption id=\"caption-attachment-211459\" class=\"wp-caption-text\">Foto: Tropical Magazine<\/figcaption><\/figure>\n<p><strong>Ergebnisse brauchen nicht nur Wettk\u00e4mpfe sondern auch Wettk\u00e4mpfer, bei denen es an Ungarn mangelt, ist es deshalb die Rede davon, einen russischen Schwimmer zu verpflichten?<\/strong><\/p>\n<p>Ja, ich glaubte, dass der Fortschritt beschleunigt werden muss, deshalb habe ich mich an russische Vereine gewandt, die nicht nur hervorragende Sportler sind, sondern auch gro\u00dfartig in der Sportdiplomatie sind.<\/p>\n<p>Wir bekamen einen Einblick in das Training der Russen und kamen zu dem Schluss, dass uns ihr Training in Tokio einige Punkte einbringen k\u00f6nnte, wir hatten sogar drei Kandidaten, aber keiner von ihnen wurde verpflichtet: Der erste war ein Zwillingspaar, aber<\/p>\n<blockquote>\n<p><span style=\"color: #008080;\">Den ungarischen Fachleuten und den Pr\u00e4sidenten der Mitgliedsorganisationen gefiel die Idee, dass Ausl\u00e4nder Ungarn vertreten, nicht, \u201ez. B. h\u00e4tte dies die Ungarn entmutigen k\u00f6nnen.<\/span><\/p>\n<\/blockquote>\n<p>Das zweite war ein M\u00e4dchen namens Matviyenko, aber wir konnten ihr nicht sagen, wie hoch ihr Gehalt innerhalb einer Woche sein w\u00fcrde, also trat sie zur\u00fcck. Wir wussten nicht, warum der dritte Kandidat sich weigerte.<\/p>\n<p>Gespr\u00e4che \u00fcber Finanzfragen und die Zusammenarbeit mit den Russen verlaufen schleppend und kommen nicht weiter, abschlie\u00dfend wird man nicht bereit sein, eine Olympiaqualifikation zu bekommen, so dass wir 2020 in Tokio nicht dabei sein werden.<\/p>\n<p style=\"text-align: center;\">[button link=\u201dhttps:\/\/dailynewshungary.com\/hungary-has-one-of-the-biggest-olympics-gold-collections-video\/\u201d type=\u201dbig\u201d color=\u201d silver\u201d newwindow=\u201d yes\u201d] Wussten Sie, dass Ungarn eine der gr\u00f6\u00dften olympischen Goldsammlungen hat?[\/button]<\/p>\n<p>Die meisten erwachsenen Sportlerinnen und Sportler treten nicht mehr an, aber zum Gl\u00fcck haben wir viele vielversprechende junge Schwimmer, aber sie brauchen jahrelange Routine auf internationalem Boden, bis die Jury sie gut kennenlernt Das dauert etwa vier bis sechs Jahre, und da die Russen damit schon durch sind, h\u00e4tten wir mit der Verpflichtung viel Zeit sparen k\u00f6nnen.<\/p>\n<p><strong>Geht es nicht anders?<\/strong><\/p>\n<p>Auch dieser Sportzweig lebt vom Geld, ohne eine Einstellung, die dieses Gesch\u00e4ft in den Mittelpunkt stellt, wird er nicht weiterkommen. Wir m\u00fcssen uns damit auseinandersetzen <a href=\"https:\/\/dailynewshungary.com\/de\/katinka-hosszu-schwimmerin-clubbesitzerin-und-botschafterin\/\" target=\"_blank\" rel=\"noopener noreferrer\">Katinka Hossz\u00fa ist eine ausgezeichnete Schwimmerin<\/a>, aber sie n\u00e4hert sich dem Schwimmen als Gesch\u00e4ftsfrau. Ich schlage vor, dass sie eine Synchronschwimmabteilung einrichtet und so schnell wie m\u00f6glich eine russische Schwimmerin verpflichtet, weil das eine gute und profitable Idee ist. Daf\u00fcr hat sie etwas mehr als zwei Monate Zeit und k\u00f6nnte mit minimalem Aufwand die Leiterin des ungarischen Synchronschwimmens sein.<\/p>\n<p><em>Bild vorgestellt: facebook.com\/fina1908\/<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die neun Mitgliedsorganisationen des Ungarischen Synchronschwimmverbandes haben ihre Zweifel am derzeitigen Pr\u00e4sidenten S\u00e1ndor Balogh ge\u00e4u\u00dfert. Bevor er jedoch offiziell zur\u00fccktreten musste, widerrief er sein Amt per SMS. F\u00fcr den 9. Februar wurde eine Dringlichkeitssitzung angesetzt, bei der die Mitgliedsorganisationen die Abberufung von Baloghs Pr\u00e4sidentschaft besprechen sollten. 24.hu berichtet, dass Balogh per WhatsApp-SMS signalisiert habe, dass [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":732408,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1219],"tags":[1779,1076],"class_list":["post-732407","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport","tag-schwimmen","tag-ungarn"],"blocksy_meta":[],"acf":[],"author_username":"kovacszsoka","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"","focus_keyword":"","canonical_url":"","robots":"","primary_category":"1219","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/732407","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=732407"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/732407\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/732408"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=732407"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=732407"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=732407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}