{"id":738050,"date":"2018-06-30T09:00:24","date_gmt":"2018-06-30T07:00:24","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/neuer-us-botschafter-der-die-beziehungen-zu-ungarn-festigen-mochte-video\/"},"modified":"2018-06-30T09:00:24","modified_gmt":"2018-06-30T07:00:24","slug":"neuer-us-botschafter-der-die-beziehungen-zu-ungarn-festigen-mochte-video","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/neuer-us-botschafter-der-die-beziehungen-zu-ungarn-festigen-mochte-video\/","title":{"rendered":"Neuer US-Botschafter, der die Beziehungen zu Ungarn festigen m\u00f6chte \u2013 Video"},"content":{"rendered":"<p><strong>David B. Cornstein, der neue Botschafter der Vereinigten Staaten in Ungarn, sagte in einer am Freitag auf der Facebook-Seite der US-Botschaft ver\u00f6ffentlichten Nachricht, er wolle die Beziehungen zwischen den USA und Ungarn st\u00e4rken.<\/strong><\/p>\n<p>Cornstein sagte, es sei ihm \u201ceine tiefe Ehre\u201d, als Botschafter zu fungieren.<\/p>\n<blockquote>\n<p>Er bemerkte, dass seine Gro\u00dfmutter in Ungarn geboren wurde.<\/p>\n<\/blockquote>\n<p>\u201cDie Geschichte meiner Familie veranschaulicht die tiefen historischen Bindungen zwischen unseren L\u00e4ndern, und ich bin bestrebt, unsere Beziehung noch st\u00e4rker zu machen\u201d, sagte er.<\/p>\n<p>Cornstein \u00fcberreichte Pr\u00e4sident J\u00e1nos \u00c1der am Montag sein Beglaubigungsschreiben <a href=\"https:\/\/dailynewshungary.com\/new-u-s-ambassador-presents-credentials-to-hungarian-president-ades\/\" target=\"_blank\" rel=\"noopener noreferrer\">Lesen Sie hier mehr<\/a>.<\/p>\n<p>Bei einer Anh\u00f6rung zur Best\u00e4tigung seiner Ernennung vor dem Ausschuss f\u00fcr ausw\u00e4rtige Beziehungen des Senats im Mai sagte Cornstein<\/p>\n<blockquote>\n<p>Er w\u00fcrde sich auf die F\u00f6rderung amerikanischer Werte und die F\u00f6rderung der wirtschaftlichen Interessen der USA in Ungarn konzentrieren.<\/p>\n<\/blockquote>\n<p>Cornstein baute ein Schmuckgesch\u00e4ft auf, das bei seiner Pensionierung einen Umsatz von weit \u00fcber 1 Milliarde Dollar erwirtschaftete, au\u00dferdem hatte er eine Reihe von Positionen im Staatsdienst inne und sa\u00df in mehreren philanthropischen Gremien.<\/p>\n<p style=\"text-align: center;\">&nbsp;<iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/video.php?href=https%3A%2F%2Fwww.facebook.com%2Fhungary.usembassy%2Fvideos%2F10156536683038979%2F&amp;show_text=0&amp;width=560\" width=\"560\" height=\"315\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p style=\"text-align: center;\">[button link=\u201dhttps:\/\/dailynewshungary.com\/tag\/video\/\u201d type=\u201dbig\u201d color=\u201d lila\u201d newwindow=\u201d yes\u201d] Weitere interessante VIDEOS HIER ansehen![\/button]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>David B. Cornstein, der neue Botschafter der Vereinigten Staaten in Ungarn, sagte in einer am Freitag auf der Facebook-Seite der US-Botschaft ver\u00f6ffentlichten Nachricht, er wolle die Beziehungen zwischen den USA und Ungarn st\u00e4rken. Cornstein sagte, es sei ihm \u201ceine tiefe Ehre\u201d, als Botschafter zu fungieren. Er bemerkte, dass seine Gro\u00dfmutter in Ungarn geboren wurde. \u201cDie [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1081],"tags":[1132,1157,1192],"class_list":["post-738050","post","type-post","status-publish","format-standard","hentry","category-politik","tag-diplomatie","tag-vereinigte-staaten","tag-video"],"blocksy_meta":[],"acf":[],"author_username":"alk","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"David B. Cornstein, der neue Botschafter der Vereinigten Staaten in Ungarn, sagte in einer am Freitag auf der Facebook-Seite der US-Botschaft ver\u00f6ffentlichten Nachricht, er wolle die Beziehungen zwischen den USA und Ungarn st\u00e4rken.","focus_keyword":"Neuer Botschafter","canonical_url":"","robots":"","primary_category":"1081","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"20","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/738050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=738050"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/738050\/revisions"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=738050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=738050"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=738050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}