{"id":739064,"date":"2018-05-17T10:30:30","date_gmt":"2018-05-17T08:30:30","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/kabinett-orban-lobt-wende-in-der-deutschen-migrationspolitik\/"},"modified":"2018-05-17T10:30:30","modified_gmt":"2018-05-17T08:30:30","slug":"kabinett-orban-lobt-wende-in-der-deutschen-migrationspolitik","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/kabinett-orban-lobt-wende-in-der-deutschen-migrationspolitik\/","title":{"rendered":"Kabinett Orb\u00e1n lobt \u2018Wende\u2019 in der deutschen Migrationspolitik"},"content":{"rendered":"<p><strong>Deutschland hat seine klar gedreht <a href=\"https:\/\/dailynewshungary.com\/de\/der-grose-britische-zuguberfall-wie-eine-15-kopfige-bande-1963-26-millionen-pfund-stahl\/\" target=\"_blank\" rel=\"noopener\">Migrationspolitik<\/a> Um und der Unterschied zwischen den Positionen der ungarischen und der deutschen Regierung \u201cist nicht mehr so gro\u00df wie zuvor\u201d, sagte der gew\u00e4hlte Minister an der Spitze des Ministerpr\u00e4sidentenb\u00fcros am Mittwoch in Berlin.<\/strong><\/p>\n<p>\u201eDas Einzige, wor\u00fcber wir jetzt eine gemeinsame Grundlage finden m\u00fcssen, ist, dass unsere Ablehnung aller Arten obligatorischer Umverteilungssysteme ethisch und verteilungsbezogen ist, weil wir die Einhaltung der Vorschriften einhalten <a href=\"https:\/\/dailynewshungary.com\/de\/der-grose-britische-zuguberfall-wie-eine-15-kopfige-bande-1963-26-millionen-pfund-stahl\/\" target=\"_blank\" rel=\"noopener\">Schengen<\/a> Regeln und der Lissabon-Vertrag gesetzlich gerechtfertigt, sagte Gerge Guly\u00e1s gegen\u00fcber den Medien.<\/p>\n<p>\u201eWir sind uns nicht einig, was die obligatorische Umverteilung [von Migranten] betrifft, aber das ist keine prinzipielle Meinungsverschiedenheit, sondern eine, die auf die Unterschiede in unseren Umst\u00e4nden zur\u00fcckzuf\u00fchren ist,\u201csagte Guly\u00e1s\u201d.<\/p>\n<p>Er sagte<\/p>\n<blockquote>\n<p><a href=\"https:\/\/dailynewshungary.com\/de\/der-grose-britische-zuguberfall-wie-eine-15-kopfige-bande-1963-26-millionen-pfund-stahl\/\" target=\"_blank\" rel=\"noopener\">Deutschland<\/a> \u201chatte 2015 ziemlich unverantwortlich gehandelt\u201d, indem er mehr als eine Million Migranten aufgenommen hatte.<\/p>\n<\/blockquote>\n<p>\u201cJetzt m\u00f6chte es die Konsequenzen dieser Entscheidung mit anderen teilen\u201d, sagte er. \u201eUngarn ist mit diesem Ziel nicht einverstanden, aber die beiden L\u00e4nder sind sich jedoch einig, dass die Au\u00dfengrenzen der Europ\u00e4ischen Union gesch\u00fctzt werden m\u00fcssen, sagte Guly\u00e1s.\u201c\u201eLeider k\u00f6nnen wir noch nicht sehen, ob Sanktionen gegen L\u00e4nder verh\u00e4ngt werden, die dieser Pflicht nicht nachkommen\u201d, f\u00fcgte er hinzu.<\/p>\n<p>sagte Guly\u00e1s<\/p>\n<blockquote>\n<p>Ungarn weigert sich, jede Politik zu akzeptieren, die das Thema Migration von der Idee der obligatorischen Umverteilung von Migranten her angeht.<\/p>\n<\/blockquote>\n<p>Ungarn meint, dass der Ausgangspunkt in dieser Frage der Schutz der Au\u00dfengrenzen des Blocks sein sollte, denn \u201cdies ist die Garantie daf\u00fcr, dass die Schwierigkeiten, die sich aus den 2015 getroffenen Entscheidungen ergaben, nicht eskalieren k\u00f6nnen\u201d, sagte er.<\/p>\n<p>Guly\u00e1s ist in Berlin, um eine Konferenz \u00fcber Ungarns Platz in Europa zu er\u00f6ffnen, die von der Stiftung der Freunde Ungarns und dem Philidor-Institut organisiert wird.<\/p>\n<p><em>Foto: MTI\/EPA\/Vaszil Donev<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Deutschland hat seine klar gedreht Migrationspolitik Um und der Unterschied zwischen den Positionen der ungarischen und der deutschen Regierung \u201cist nicht mehr so gro\u00df wie zuvor\u201d, sagte der gew\u00e4hlte Minister an der Spitze des Ministerpr\u00e4sidentenb\u00fcros am Mittwoch in Berlin. \u201eDas Einzige, wor\u00fcber wir jetzt eine gemeinsame Grundlage finden m\u00fcssen, ist, dass unsere Ablehnung aller Arten [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":739065,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1081],"tags":[1177,1091,1445,1299],"class_list":["post-739064","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politik","tag-deutschland","tag-fidesz","tag-migration","tag-schengen"],"blocksy_meta":[],"acf":[],"author_username":"alk","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"Deutschland habe seine Migrationspolitik klar umgedreht und der Unterschied zwischen den Positionen der ungarischen und der deutschen Regierung sei \"nicht so gro\u00df wie zuvor\", sagte der gew\u00e4hlte Minister an der Spitze des Ministerpr\u00e4sidentenb\u00fcros am Mittwoch in Berlin.","focus_keyword":"Migrationspolitik","canonical_url":"","robots":"","primary_category":"1081","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"55","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/739064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=739064"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/739064\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/739065"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=739064"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=739064"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=739064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}