{"id":740105,"date":"2018-04-06T10:30:27","date_gmt":"2018-04-06T08:30:27","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/wahl-2018-vorsitzender-der-fidesz-gruppe-fidesz-kdnp-wird-mit-keiner-oppositionspartei-eine-koalition-bilden\/"},"modified":"2018-04-06T10:30:27","modified_gmt":"2018-04-06T08:30:27","slug":"wahl-2018-vorsitzender-der-fidesz-gruppe-fidesz-kdnp-wird-mit-keiner-oppositionspartei-eine-koalition-bilden","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/wahl-2018-vorsitzender-der-fidesz-gruppe-fidesz-kdnp-wird-mit-keiner-oppositionspartei-eine-koalition-bilden\/","title":{"rendered":"Wahl 2018 \u2013 Vorsitzender der Fidesz-Gruppe: Fidesz-KDNP wird mit keiner Oppositionspartei eine Koalition bilden"},"content":{"rendered":"<p><strong>Das regierende B\u00fcndnis zwischen Fidesz und den Christdemokraten w\u00fcrde sich nach den Parlamentswahlen am 8. April weigern, eine Regierungskoalition mit einer der aktuellen Oppositionsparteien einzugehen, sagte Gergely Guly\u00e1s, Fraktionsvorsitzender der Fidesz-Gruppe, in einem am Freitag ver\u00f6ffentlichten Interview mit der Tageszeitung Magyar Id.k.<\/strong><\/p>\n<p>\u201cEs lohnt sich klarzustellen, dass nicht nur keine der anderen Parteien eine Koalition mit uns eingehen will sondern auch Fidesz-KDNP mit keiner der Oppositionsparteien regieren m\u00f6chte Wenn die W\u00e4hler entscheiden, dass wir nicht weiter regieren sollen dann auch ein <a href=\"https:\/\/dailynewshungary.com\/de\/wahl-2018-gyurcsany-wenn-die-linke-gewinnt-mussen-die-koalitionsgesprache-am-9-april-beginnen\/\" target=\"_blank\" rel=\"noopener\">Vona-Gjurken-Sz\u00e9l-Kar\u00e1csony<\/a> Die Regierung w\u00fcrde gebildet, was f\u00fcr das Land ebenso unwahrscheinlich wie tragisch w\u00e4re, sonst w\u00fcrden Unsicherheit, Chaos und Instabilit\u00e4t folgen, sagte Gulyas der Zeitung.<\/p>\n<p>Keiner der Oppositionsf\u00fchrer oder Premierministerkandidaten w\u00e4re geeignet, Ungarn zu regieren, sagte er.<\/p>\n<p>\u201cEs ist nicht so, dass sie das Land mit einer anderen Ideologie und Politik regieren w\u00fcrden, aber keiner von ihnen hat den beruflichen, politischen und intellektuellen Hintergrund, der einen davon ausgehen l\u00e4sst, dass er in der Lage ist, das Land zu regieren\u201d, sagte Guly\u00e1s.<\/p>\n<p>\u201cDas ist seit einigen Jahren unsere Erfahrung, dass<\/p>\n<blockquote>\n<p>Der politische und berufliche Hintergrund [der Opposition] stammt von Organisationen, die ihren Lebensunterhalt bestreiten <a href=\"https:\/\/darkgoldenrod-woodcock-377971.hostingersite.com\/tag\/Soros\" target=\"_blank\" rel=\"noopener\">US-Milliard\u00e4r George Soros<\/a>\u201csagte er\u201d.<\/p>\n<\/blockquote>\n<p>\u201cDerzeit haben sie einen entscheidenden Einfluss auf die Oppositionspolitik. Eine interessante Frage ist, warum die Opposition nicht in der Lage ist, ihren eigenen beruflichen Hintergrund aufzubauen und weiterzuentwickeln, und warum sie fast immer auf Soros setzen muss\u201d, sagte Guly\u00e1s.<\/p>\n<p>In seinem Kommentar zur Migration sagte der Fidesz-Politiker, sie sei unumkehrbar, und deshalb sei Migration das zentrale Thema. Sobald jemand die Migrationsquote akzeptiere, werde die Garantie eines wirksamen Grenzschutzes ein f\u00fcr alle Mal zerrissen und die Tore f\u00fcr Migranten w\u00fcrden sich \u00f6ffnen, f\u00fcgte er hinzu.<\/p>\n<p>Auch wenn die linksliberale Seite und radikalnationalistische Jobbik, die \u201cv\u00f6llig opportunistisch geworden ist, in der internationalen Presse \u00fcber die Annahme von Migrantenquoten zu sprechen\u201d, an eine Ablehnung der Quoten denken, wird der geringste Druck der Europ\u00e4ischen Union sie dazu bringen, ihre Position aufzugeben, sagte er.<\/p>\n<p>Er kommentierte den Unterschied zwischen dem Ansatz der Regierungsparteien und dem Ansatz der Opposition zur Idee der Nation und sagte, die ungarische Regierung vertrete einen traditionellen christdemokratischen Politikstil, den sogar einige der rechtskonservativen europ\u00e4ischen Parteien aufgegeben h\u00e4tten. \u201eWir denken in Europa der Nationen.\u201cEs gibt keine Alternative zur institutionalisierten Zusammenarbeit in Europa und daher ist es gut, dass wir der EU beigetreten sind. Gleichzeitig liegt die St\u00e4rke des Kontinents in der Vielfalt\u201d, sagte er.<\/p>\n<p><em>Bild vorgestellt: MTI<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das regierende B\u00fcndnis zwischen Fidesz und den Christdemokraten w\u00fcrde sich nach den Parlamentswahlen am 8. April weigern, eine Regierungskoalition mit einer der aktuellen Oppositionsparteien einzugehen, sagte Gergely Guly\u00e1s, Fraktionsvorsitzender der Fidesz-Gruppe, in einem am Freitag ver\u00f6ffentlichten Interview mit der Tageszeitung Magyar Id.k. \u201cEs lohnt sich klarzustellen, dass nicht nur keine der anderen Parteien eine Koalition [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":740106,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1081],"tags":[1091,1445,1447,3695],"class_list":["post-740105","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politik","tag-fidesz","tag-migration","tag-wahl","tag-wahl-2018"],"blocksy_meta":[],"acf":[],"author_username":"kovacszsoka","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"\"Nicht nur, dass keine der anderen Parteien mit uns koalieren will sondern auch Fidesz-KDNP mit keiner der Oppositionsparteien regieren m\u00f6chte, wenn wir nicht weiter regieren sollten dann w\u00fcrde entweder eine Vona-Gjurks\u00e1ny-Sz\u00e9l-Kar\u00e1csony Regierung gebildet oder es w\u00fcrde Unsicherheit, Chaos und Instabilit\u00e4t folgen,\"","focus_keyword":"fidesz-kdnp","canonical_url":"","robots":"","primary_category":"1081","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"54","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/740105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=740105"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/740105\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/740106"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=740105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=740105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=740105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}