{"id":740419,"date":"2018-03-24T13:00:32","date_gmt":"2018-03-24T12:00:32","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/leekenserstes-spiel-endet-mit-einer-niederlage-gegen-kasachstan-video\/"},"modified":"2018-03-24T13:00:32","modified_gmt":"2018-03-24T12:00:32","slug":"leekenserstes-spiel-endet-mit-einer-niederlage-gegen-kasachstan-video","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/leekenserstes-spiel-endet-mit-einer-niederlage-gegen-kasachstan-video\/","title":{"rendered":"Leekens\u2018erstes Spiel endet mit einer Niederlage gegen Kasachstan \u2013 VIDEO"},"content":{"rendered":"<p><strong>Das erste Spiel von Georges Leekens als Trainer Ungarns endete mit einer 3-2-Niederlage gegen Ungarn <a href=\"https:\/\/dailynewshungary.com\/?s=kazakhstan\" target=\"_blank\" rel=\"noopener\">Kasachstan<\/a> Heute Abend in der Groupama Ar\u00e9na. Zwei fr\u00fche Tore hatten den G\u00e4sten einen unerwarteten Vorteil verschafft, aber Ungarn erholte sich mit Hilfe des Tores von \u00c1d\u00e1m Szalai teilweise und h\u00e4tte auf Augenh\u00f6he in die Halbzeit gehen k\u00f6nnen, doch Nemanja Nikolic wurde bei guten Pl\u00e4tzen abgelehnt und die Kasachen nutzten eine Defensivpause, um vor der Pause ihren dritten Treffer zu erzielen. Kriszti\u00e1n N\u00e9meth halbierte den R\u00fcckstand Mitte des zweiten Drittels erneut, aber Leekens Sch\u00fctzlinge konnten keinen Ausgleich erzielen.<\/strong><\/p>\n<p>Die beiden fr\u00fchen Zugest\u00e4ndnisse waren ein verheerender Doppelschlag f\u00fcr Ungarn, erstens, als eine Ecke des linken Bauyrzhan Islamkan in der sechsten Minute \u00c1kos Elek, \u00c1d\u00e1m Szalai und Roland Ugrai auf dem Weg zu Roman Murtazajew auswich, der den Ball dankbar unter die Latte und ins Dach drehte Netz am hinteren Pfosten Vier Minuten sp\u00e4ter verdoppelte Kasachstan seinen \u00fcberraschenden Vorsprung, als Islamkan sich an zwei Verteidigern vorbeizog und an die Kante des Sechs-Yard-Strafraums \u00fcberquerte. Fiola kam zuerst zum Ball und versuchte, den Ball zu kl\u00e4ren, aber nur gelang es Zainutdinov, der keine Zeit hatte, tief in Richtung der linken Ecke des Netzes zu schie\u00dfen und den Ball zu ihm abwehrte Fylle, der Hand<\/p>\n<p>Es folgte eine Phase v\u00f6lliger Best\u00fcrzung f\u00fcr die Heimmannschaft und ihre Fans, aber die Hoffnung f\u00fcr Ungarn kam in Form eines schnell geschossenen Freisto\u00dfes von Dzsudzs\u00e1k in der 21. Minute, mit dem er die F\u00fc\u00dfe von L\u00e1szl\u00f3 Kleinheisler fand, der einen geschickten Lauf hingelegt hatte der rechte Kanal des Strafraums, sein Cut-Back wurde vom ausgestreckten linken Fu\u00df von \u00c1d\u00e1m Szalai elf Meter vom Tor entfernt in die \u00e4u\u00dferste linke Ecke des kasachischen Netzes abgelenkt.<\/p>\n<figure id=\"attachment_178169\" aria-describedby=\"caption-attachment-178169\" style=\"width: 1024px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2018\/03\/D__YT20180323020.jpg\" data-pswp-width=\"2048\" data-pswp-height=\"1369\" data-cropped=\"true\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-178169\" src=\"https:\/\/dailynewshungary.com\/wp-content\/uploads\/2018\/03\/D__YT20180323020-1024x684.jpg\" alt=\"Ungarisch-Kasachstan 2-3 Fu\u00dfball\" width=\"1024\" height=\"684\" srcset=\"https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2018\/03\/D__YT20180323020-1024x684.jpg 1024w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2018\/03\/D__YT20180323020-300x200.jpg 300w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2018\/03\/D__YT20180323020-768x513.jpg 768w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2018\/03\/D__YT20180323020-220x147.jpg 220w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2018\/03\/D__YT20180323020-600x401.jpg 600w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2018\/03\/D__YT20180323020-200x134.jpg 200w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2018\/03\/D__YT20180323020-1080x722.jpg 1080w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2018\/03\/D__YT20180323020.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"><\/a><figcaption id=\"caption-attachment-178169\" class=\"wp-caption-text\">Foto: MTI<\/figcaption><\/figure>\n<p>Zwei Minuten sp\u00e4ter hatte der kasachische Verteidiger Jewgeni Postnikow das Gl\u00fcck, immer noch auf dem Platz zu stehen, nachdem er nur eine gelbe Karte erhalten hatte, weil er Nemanja Nikolic zu Fall gebracht hatte, der auf Kleinheislers punktgenauen Pass und ins Tor gerast war. Der Schwung war zu diesem Zeitpunkt sehr bei Ungarn und Nikolic wird entt\u00e4uscht sein, dass er Ungarn nicht auf die H\u00f6he gebracht hat, als er sich den Strafraum auf den linken Fu\u00df schnitt, nachdem er erneut auf den Weg zum Tor geschickt worden war. Sein anschlie\u00dfender Curling-Einsatz war zu nah an Kasachstans Torh\u00fcter Nenad Erics, um ihn \u00fcberm\u00e4\u00dfig zu beunruhigen.<\/p>\n<p>Zu diesem Zeitpunkt sah es nur eine Frage der Zeit aus, bis ein Ausgleich erzielt werden w\u00fcrde, aber den G\u00e4sten gelang es, sich neu zu formieren und sogar vor der Halbzeit ihr Zwei-Tore-Polster wiederherzustellen, wobei Murtazayev ausnutzte, weil man feststellte, dass er Barnab\u00e1s Bese bei seiner Enteignung nicht gedr\u00e4ngt hatte und den Ball \u00fcber den ungarischen Strafraum verteilen, damit Erkebulan Seidakhmet den Ball \u00fcber Gul\u00e1csi zur\u00fcck und auf die linke Seite des Tores schieben konnte.<\/p>\n<blockquote>\n<p>Die Halbzeit brachte unvermeidliche personelle Ver\u00e4nderungen mit sich, da Leekens versuchte, einen Gro\u00dfteil seines Kaders im Einsatz zu sehen, Szilveszter Hangya f\u00fcr Endre Botka als Linksverteidiger eingewechselt wurde und Gerg. Lovrencsics den Platz von Barnab\u00e1s Bese auf der anderen Au\u00dfenverteidigerposition einnahm Kriszti\u00e1n N\u00e9meth ersetzt Roland Ugrai auf dem linken Fl\u00fcgel.<\/p>\n<\/blockquote>\n<p>Es war N\u00e9meth, der in der zweiten Halbzeit f\u00fcr den ersten Moment von echter Qualit\u00e4t sorgte, als ihm knapp au\u00dferhalb des Strafraums eine linke Hangya-Flanke zugesprochen wurde und er den Ball bei seiner ersten Ber\u00fchrung kr\u00e4ftig schlug und voller Freude zusah, wie er mit gewaltigem Gift ins Tor fegte ganz rechts im kasachischen Netz, so dass Ungarn 23 Minuten vor Spielende nur noch ein Tor im R\u00fcckstand hatte.<\/p>\n<p style=\"text-align: center;\">[button link=\u201dhttps:\/\/dailynewshungary.com\/tag\/football\/\u201d type=\u201dbig\u201d color=\u201d red\u201d newwindow=\u201d yes\u201d] Lesen Sie mehr News \u00fcber UNGARISCHE FUSSBALLMANNSCHAFT![\/button]<\/p>\n<p>Trotz zahlreicher Angriffsbem\u00fchungen konnte sich Leekens\u2018Team jedoch nicht durch eine vollbesetzte kasachische Verteidigung zurechtfinden, als die Zeit auf Vollzeit tickte. Der lange Ballst\u00fcrmer von Central Defensive Deb\u00fctant Kenneth Otigba wurde vom eingewechselten D\u00e1niel B\u00f6de angegriffen, um schlie\u00dflich einen weiteren Ersatzspieler, M\u00e1ttee Patkai, mit der Chance zu pr\u00e4sentieren, das Ziel zu finden, aber sein abgef\u00e4lschter Schuss wurde von Erics sicher gesammelt. Szalai sah dann einen weiteren Schuss geblockt und ein Freisto\u00df von Dzudz\u00e1k steckte in der Nachspielzeit tief in die Handfl\u00e4chen des kasachischen Torwarts, aber es sollte keine Wiederherstellung der Parit\u00e4t geben, bevor der polnische Schiedsrichter Tomas Musial seinen letzten Pfiff blies blies.<\/p>\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=pMYzOklT4I4\" target=\"_blank\" rel=\"noopener\">https:\/\/www.youtube.com\/watch?v=pMYzOklT4I4<\/a><\/p>\n<p><em>Foto: MTI<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das erste Spiel von Georges Leekens als Trainer Ungarns endete mit einer 3-2-Niederlage gegen Ungarn Kasachstan Heute Abend in der Groupama Ar\u00e9na. Zwei fr\u00fche Tore hatten den G\u00e4sten einen unerwarteten Vorteil verschafft, aber Ungarn erholte sich mit Hilfe des Tores von \u00c1d\u00e1m Szalai teilweise und h\u00e4tte auf Augenh\u00f6he in die Halbzeit gehen k\u00f6nnen, doch Nemanja [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":740420,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1219],"tags":[1218],"class_list":["post-740419","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport","tag-fusball"],"blocksy_meta":[],"acf":[],"author_username":"alk","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"Das erste Spiel von Georges Leekens als Trainer Ungarns endete heute Abend mit einer 3-2-Niederlage gegen Kasachstan in der Groupama Ar\u00e9na. Zwei fr\u00fche Tore hatten den G\u00e4sten einen unerwarteten Vorteil verschafft, aber Ungarn erholte sich mit Hilfe des Tores von \u00c1d\u00e1m Szalai teilweise und h\u00e4tte auf Augenh\u00f6he in die Halbzeit gehen k\u00f6nnen.","focus_keyword":"Kasachstan","canonical_url":"","robots":"","primary_category":"1219","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/740419","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=740419"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/740419\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/740420"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=740419"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=740419"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=740419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}