{"id":741986,"date":"2018-01-22T11:30:17","date_gmt":"2018-01-22T10:30:17","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/drei-ungarische-spieler-die-es-in-die-mls-schaffen-konnten\/"},"modified":"2018-01-22T11:30:17","modified_gmt":"2018-01-22T10:30:17","slug":"drei-ungarische-spieler-die-es-in-die-mls-schaffen-konnten","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/drei-ungarische-spieler-die-es-in-die-mls-schaffen-konnten\/","title":{"rendered":"Drei ungarische Spieler, die es in die MLS schaffen k\u00f6nnten"},"content":{"rendered":"<p><strong>Der ungarische Fu\u00dfball durchlebt ein wenig einen schlechten Abschnitt Als das Land, das die Welt Pusk\u00e1s, Kocsis, Lantos und mehr brachte, war Ungarn einst ein Ort, der die Fu\u00dfballwelt beherrschte. \u00c4hnlich wie die niederl\u00e4ndische Mannschaft von 1970 bleibt ihre WM-Mannschaft von 1954 eine der beliebtesten Mannschaften, die das Turnier nicht gewonnen hat Sie spielten mit einem Elan und einer Kraft, die andere Mannschaften einfach nicht hatten Sie revolutionierten und ver\u00e4nderten die Art und Weise, wie wir das Spiel spielen, und stecken in den K\u00f6pfen der Menschen fest, eine ganz besondere und sch\u00f6ne Seite.<\/strong><\/p>\n<p><span style=\"font-weight: 400;\">Leider haben sich die Zeiten ge\u00e4ndert und es ist der ungarische Fu\u00dfball, der tiefgreifende Ver\u00e4nderungen und eine Revolution braucht. Die Nationalmannschaft blieb in ihrer WM-Qualifikationsgruppe 14 Punkte hinter dem Zweitplatzierten Schweiz zur\u00fcck, meilenweit von der WM entfernt. Noch schlimmer war die Tatsache, dass sie mit der F\u00e4r\u00f6er-Insel unentschieden spielte, gegen Andorra verlor und dann auch gegen Luxemburg in einem Freundschaftsspiel verlor. Diese aktuelle Mannschaft ist nicht in der Lage, die Fu\u00dfballschuhe der gro\u00dfen ungarischen Mannschaft der 50er Jahre zu polieren, und es ist klar, dass Ungarn einen neuen Schwung und Schwung braucht Leben, wenn es um das beliebteste Spiel der Welt geht.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Eine Liga, die mehr als die meisten anderen tut, um \u00c4nderungen an der Art und Weise vorzunehmen, wie Teams organisiert sind und Spieler wachsen, ist die MLS. Die Vereinigten Staaten und Kanada werden nicht lange mit Fu\u00dfball in Verbindung gebracht, aber da die MLS weiter w\u00e4chst, ist klar, dass sie zu einer aufstrebenden Macht wird. Wir leben in einer vernetzteren Welt, was bedeutet, dass Spieler jetzt gl\u00fccklicher sind, um um die ganze Welt zu reisen, um zu spielen, und wie wir hier unter festgestellt haben<\/span><a href=\"https:\/\/dailynewshungary.com\/de\/ab-dem-nachsten-sommer-wird-air-canada-taglich-fluge-nach-ungarn-anbieten\/\"> <span style=\"font-weight: 400;\">dailynewshungary.com<\/span><\/a><span style=\"font-weight: 400;\"> F\u00fcr Heimweh-Spieler soll es bald t\u00e4gliche Direktfl\u00fcge von Kanada nach Ungarn geben.<\/span><\/p>\n<blockquote>\n<p><span style=\"font-weight: 400;\">Derzeit sind lt<\/span><a href=\"https:\/\/www.mlssoccer.com\/post\/2016\/12\/20\/chicago-fire-sign-hungarian-striker-nemanja-nikolic-designated-player\" target=\"_blank\" rel=\"noopener\"> <span style=\"font-weight: 400;\">MLSsoccer.com,<\/span><\/a><span style=\"font-weight: 400;\"> Drei Spieler aus Ungarn \u00fcben ihr Handwerk in der MLS aus und alle drei spielen in der Nationalmannschaft, was darauf hindeutet, dass ein Wechsel in die MLS allen Spielern am Rande helfen kann und als eine Liga angesehen wird, die gut genug f\u00fcr die Nationalmannschaft ist. <\/span><\/p>\n<\/blockquote>\n<p><span style=\"font-weight: 400;\">Fr\u00fcher h\u00e4tte der Wechsel in die MLS vielleicht den Tod der Karriere bedeutet, aber jetzt kann er sie wiederbeleben. Hier sind also drei Spieler, die einen Wechsel in Betracht ziehen sollten, sowie die drei Vereine, die dar\u00fcber nachdenken sollten, sie zu verpflichten.<\/span><\/p>\n<h1><b>Barnab\u00e1s Bese zu Montreal Impact<\/b><\/h1>\n<p><span style=\"font-weight: 400;\">Montreal hatte ein Hundeessen einer Saison, die auf Platz 17 der MLS-Gesamtwertung endete und die gemeinsame drittschlechteste Verteidigung in ihrer Konferenz hatte. Sie m\u00fcssen spielen, sie m\u00fcssen sich auf die gro\u00dfartige kanadische Tradition berufen, eine Runde zu drehen, die durch die erstaunliche Auswahl an Gl\u00fccksspielen veranschaulicht wird<\/span> <span style=\"font-weight: 400;\">online-slots.ca<\/span><span style=\"font-weight: 400;\"> Das zeigt, wie innovativ Kanada ist, wenn es darum geht, gro\u00dfartige Spielautomaten zu bieten und Risiken einzugehen. Sie h\u00e4tten ihr Geld sicherlich besser in diese fantastischen Spielautomaten gesteckt, als sie es f\u00fcr einige der Schlacken ausgegeben h\u00e4tten, die sie in den letzten Jahren hatten. Bese w\u00e4re eine enorme Verbesserung, er ist ein junger und aufregender Verteidiger, der seine Abwehr st\u00e4rken und die dringend ben\u00f6tigte Ruhe bringen k\u00f6nnte.<\/span><\/p>\n<blockquote>\n<p><span style=\"font-weight: 400;\">Er spielt derzeit in Frankreich, was bedeutet, dass er in eine franz\u00f6sischsprachige Umkleidekabine wie die von Montreal schl\u00fcpfen und ihnen etwas geben w\u00fcrde, das sie dringend brauchen. Es w\u00e4re ein gro\u00dfartiger Schritt sowohl f\u00fcr ihn als auch f\u00fcr Montreal.<\/span><\/p>\n<\/blockquote>\n<h2><b>Norbert Balogh nach Colorado Rapids<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Derzeit in Palermo kommt Balogh nicht ausreichend auf den Platz und hat damit seinen Platz in der ungarischen Nationalmannschaft verloren. Mit nur 21 Jahren hat er gen\u00fcgend Zeit, seine Karriere wieder in Gang zu bringen, m\u00f6chte aber nicht zu viele verlorene Jahre. <\/span><\/p>\n<blockquote>\n<p><span style=\"font-weight: 400;\">Der St\u00fcrmer hat gezeigt, dass er t\u00f6dlich sein kann, und das ist es, was Colorado braucht. <\/span><\/p>\n<\/blockquote>\n<p><span style=\"font-weight: 400;\">Sie haben letzte Saison nur 31 Tore in 34 Spielen erzielt, was eine schreckliche R\u00fcckkehr ist Balogh w\u00e4re kein garantierter Erfolg, er w\u00e4re wie Slots in einem Casino spielen, etwas Spa\u00df, mit einer gro\u00dfen Chance zu gewinnen und belohnt zu werden, aber nicht garantiert Da er jedoch wahrscheinlich auf Leihbasis verf\u00fcgbar w\u00e4re, w\u00e4re er eine Option mit geringem Risiko, \u00e4hnlich wie das Spielen von Slots mit Freispielen oder einem Bonus ohne Einzahlung. Weitere Details finden Sie unter&nbsp;<a href=\"https:\/\/topnzcasinos.co.nz\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/topnzcasinos.co.nz&amp;source=gmail&amp;ust=1635081733011000&amp;usg=AFQjCNGiZhDyCzG5kulG7Q5KGbWHOZfASw\">https:\/\/topnzcasinos.co.nz<\/a>&nbsp;, die besten Slots und Boni ohne Einzahlung!<\/span><\/p>\n<h2><b>\u00c1d\u00e1m Bogd\u00e1n zum LAFC<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">LAFC wird dieses Jahr sein MLS-Deb\u00fct geben und daf\u00fcr braucht es jemanden, der f\u00fcr Ruhe und Stabilit\u00e4t sorgt. F\u00fcr ein neues Team kann es sehr hart sein, also kann es einen echten Unterschied machen, jemanden mit Erfahrung und Pr\u00e4senz zu haben. \u00c1d\u00e1m Bogd\u00e1n spielt seit einigen Jahren auf h\u00f6chstem Niveau und ist in der Hackordnung bei Liverpool gefallen, er ist Torh\u00fcter dritter, vielleicht sogar vierter Wahl und braucht einen Wechsel. Eine Leihe an LAFC w\u00e4re perfekt f\u00fcr ihn.<\/span><\/p>\n<p><em>Foto:&nbsp;<a href=\"https:\/\/www.facebook.com\/MLS\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.facebook.com\/MLS\/<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der ungarische Fu\u00dfball durchlebt ein wenig einen schlechten Abschnitt Als das Land, das die Welt Pusk\u00e1s, Kocsis, Lantos und mehr brachte, war Ungarn einst ein Ort, der die Fu\u00dfballwelt beherrschte. \u00c4hnlich wie die niederl\u00e4ndische Mannschaft von 1970 bleibt ihre WM-Mannschaft von 1954 eine der beliebtesten Mannschaften, die das Turnier nicht gewonnen hat Sie spielten mit [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":741987,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1219],"tags":[1218,1157],"class_list":["post-741986","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport","tag-fusball","tag-vereinigte-staaten"],"blocksy_meta":[],"acf":[],"author_username":"alk","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"Drei Spieler aus Ungarn \u00fcben ihr Handwerk in der MLS aus und alle drei spielen in der Nationalmannschaft, was darauf hindeutet, dass sie in die MLS wechseln.","focus_keyword":"MLS","canonical_url":"","robots":"","primary_category":"1219","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/741986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=741986"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/741986\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/741987"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=741986"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=741986"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=741986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}