{"id":744301,"date":"2017-10-21T09:00:42","date_gmt":"2017-10-21T07:00:42","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/zoltan-szelesi-wurde-zum-amtierenden-nationaltrainer-in-ungarn-ernannt\/"},"modified":"2017-10-21T09:00:42","modified_gmt":"2017-10-21T07:00:42","slug":"zoltan-szelesi-wurde-zum-amtierenden-nationaltrainer-in-ungarn-ernannt","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/zoltan-szelesi-wurde-zum-amtierenden-nationaltrainer-in-ungarn-ernannt\/","title":{"rendered":"Zolt\u00e1n Sz\u00e9lesi wurde zum amtierenden Nationaltrainer in Ungarn ernannt"},"content":{"rendered":"<p><strong>Der Ungarische Fu\u00dfballverband (MLSZ) hat Zolt\u00e1n Sz\u00e9lesi zum amtierenden Trainer f\u00fcr die letzten beiden Spiele ernannt, die die nationale Elf dieses Jahr bestreiten soll.<\/strong><\/p>\n<p>In den vergangenen zwei Jahren war Szelesi, 35, Assistent seines Vorg\u00e4ngers Bernd Storck, der am 17. Oktober seinen Posten nach der gescheiterten Qualifikation der Mannschaft f\u00fcr die Weltmeisterschaft 2018 niederlegteWie wir am Mittwoch schrieben, ist Ungarns Cheftrainer seit Sommer 2015, <a href=\"https:\/\/dailynewshungary.com\/de\/bernd-storck-verlasst-ungarn-post-im-gegenseitigen-einvernehmen\/\" target=\"_blank\" rel=\"noopener noreferrer\">Storck hat seinen Posten mit sofortiger Wirkung verlassen<\/a> Nach einer Achterbahnfahrt zwei Jahre als Trainer der Herren-Nationalmannschaft Sein Assistent Andreas M\u00f6ller geht mit ihm, aber seine anderen Landsleute im Nationalmannschaftsaufbau bleiben auf ihren Positionen.<\/p>\n<p>Als Spieler verbrachte Szelesi seine Profikarriere bei ungarischen, deutschen, franz\u00f6sischen, niederl\u00e4ndischen und griechischen Vereinen. Er bestritt 28 L\u00e4nderspiele.<\/p>\n<p><iframe loading=\"lazy\" title=\"Zolt\u00e1n Sz\u00e9lesi HIGHLIGHTS\" width=\"1333\" height=\"1000\" src=\"https:\/\/www.youtube.com\/embed\/pbgDOy7z1No?start=87&amp;feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen=\"\"><\/iframe><\/p>\n<p><a href=\"https:\/\/dailynewshungary.com\/de\/ungarn-spielt-im-november-gegen-luxemburg-und-costa-rica\/\" target=\"_blank\" rel=\"noopener noreferrer\">Die nationale Elf wird sich stellen<\/a> Luxemburg in einem Ausw\u00e4rtsspiel am 10. November und Costa Rica am 14. November zu Hause.<\/p>\n<p><em>Foto: mlsz.hu<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Ungarische Fu\u00dfballverband (MLSZ) hat Zolt\u00e1n Sz\u00e9lesi zum amtierenden Trainer f\u00fcr die letzten beiden Spiele ernannt, die die nationale Elf dieses Jahr bestreiten soll. In den vergangenen zwei Jahren war Szelesi, 35, Assistent seines Vorg\u00e4ngers Bernd Storck, der am 17. Oktober seinen Posten nach der gescheiterten Qualifikation der Mannschaft f\u00fcr die Weltmeisterschaft 2018 niederlegteWie wir [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":744302,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1219],"tags":[1218],"class_list":["post-744301","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport","tag-fusball"],"blocksy_meta":[],"acf":[],"author_username":"alk","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"Der ungarische Fu\u00dfballverband hat Zolt\u00e1n Sz\u00e9lesi zum amtierenden Trainer f\u00fcr die letzten beiden Spiele ernannt, die die nationale Elf dieses Jahr bestreiten soll.","focus_keyword":"Sz\u00e9lesi","canonical_url":"","robots":"","primary_category":"1219","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"62","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/744301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=744301"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/744301\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/744302"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=744301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=744301"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=744301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}