{"id":744305,"date":"2017-10-20T23:30:57","date_gmt":"2017-10-20T21:30:57","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/ungarns-justizminister-trifft-polnischen-amtskollegen-in-warschau\/"},"modified":"2017-10-20T23:30:57","modified_gmt":"2017-10-20T21:30:57","slug":"ungarns-justizminister-trifft-polnischen-amtskollegen-in-warschau","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/ungarns-justizminister-trifft-polnischen-amtskollegen-in-warschau\/","title":{"rendered":"Ungarns Justizminister trifft polnischen Amtskollegen in Warschau"},"content":{"rendered":"<p><strong>L\u00e1szl\u00f3 Tr\u00f3cs\u00e1nyi, Ungarns Justizminister, traf sich mit seinem <a href=\"https:\/\/dailynewshungary.com\/de\/der-grose-britische-zuguberfall-wie-eine-15-kopfige-bande-1963-26-millionen-pfund-stahl\/\" target=\"_blank\" rel=\"noopener\">Polnisch<\/a> Amtskollege Zbigniew Ziobro zu Gespr\u00e4chen am Freitag in Warschau.<\/strong><\/p>\n<p>Die Parteien bei den Gespr\u00e4chen seien sich einig, dass Europa Doppelmoral vermeiden m\u00fcsse, sagte Tr\u00f3cs\u00e1nyi nach den Gespr\u00e4chen telefonisch gegen\u00fcber MTI. Sie diskutierten auch \u00fcber Mechanismen einer Rechtsstaatlichkeit als ein f\u00fcr beide L\u00e4nder relevantes Thema, f\u00fcgte er hinzu.<\/p>\n<p>Die <a href=\"https:\/\/dailynewshungary.com\/de\/der-grose-britische-zuguberfall-wie-eine-15-kopfige-bande-1963-26-millionen-pfund-stahl\/\" target=\"_blank\" rel=\"noopener\">Europ\u00e4ische Union<\/a> Praktiken vermeiden sollten, bei denen mitteleurop\u00e4ische L\u00e4nder anders bewertet werden als westliche Staaten, sagte TrocsanyiEr bestand darauf, dass \u201ceurop\u00e4ische Werte geteilt werden; es gibt keine (unterschiedlichen) mitteleurop\u00e4ischen und westeurop\u00e4ischen Werte\u201d.<\/p>\n<blockquote>\n<p><span style=\"color: #0000ff;\">Tr\u00f3cs\u00e1nyi und Zbioro waren sich einig, dass das Vertrauen der \u00d6ffentlichkeit in das Justizsystem von gro\u00dfer Bedeutung ist.<\/span><\/p>\n<\/blockquote>\n<p>\u201eDie Menschen erwarten \u00fcberall ein schnelles und effizientes Justizsystem, sagte Tr\u00f3cs\u00e1nyi.<\/p>\n<p>Tr\u00f3cs\u00e1nyi verwies auf die Debatten mit der Europ\u00e4ischen Kommission und anderen internationalen Organisationen, als Ungarns Grundgesetz 2011 in Kraft trat. Als Herausforderungen der \u00c4ra nannte er auch \u201ePh\u00e4nomene, die durch die Globalisierung hervorgerufen wurden\u201cund internationale Organisationen, die sich \u201ewie ein neuer Zweig der Macht verhalten\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u00e1szl\u00f3 Tr\u00f3cs\u00e1nyi, Ungarns Justizminister, traf sich mit seinem Polnisch Amtskollege Zbigniew Ziobro zu Gespr\u00e4chen am Freitag in Warschau. Die Parteien bei den Gespr\u00e4chen seien sich einig, dass Europa Doppelmoral vermeiden m\u00fcsse, sagte Tr\u00f3cs\u00e1nyi nach den Gespr\u00e4chen telefonisch gegen\u00fcber MTI. Sie diskutierten auch \u00fcber Mechanismen einer Rechtsstaatlichkeit als ein f\u00fcr beide L\u00e4nder relevantes Thema, f\u00fcgte er [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":744306,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1081],"tags":[1160,1082,1197],"class_list":["post-744305","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politik","tag-besuch","tag-europaische-union","tag-polen"],"blocksy_meta":[],"acf":[],"author_username":"alk","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"L\u00e1szlo Tr\u00f3cs\u00e1nyi, Ungarns Justizminister, traf am Freitag seinen polnischen Amtskollegen Zbigniew Ziobro zu Gespr\u00e4chen in Warschau, Polen.","focus_keyword":"Warschau","canonical_url":"","robots":"","primary_category":"1081","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"58","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/744305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=744305"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/744305\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/744306"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=744305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=744305"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=744305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}