{"id":745813,"date":"2017-08-28T08:30:54","date_gmt":"2017-08-28T06:30:54","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/an-diesem-wochenende-runway-run-am-flughafen-budapest\/"},"modified":"2017-08-28T08:30:54","modified_gmt":"2017-08-28T06:30:54","slug":"an-diesem-wochenende-runway-run-am-flughafen-budapest","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/an-diesem-wochenende-runway-run-am-flughafen-budapest\/","title":{"rendered":"An diesem Wochenende: Runway Run am Flughafen Budapest"},"content":{"rendered":"<p><strong>Dies ist das f\u00fcnfte Jahr, in dem der Flughafen Budapest sein \u00e4u\u00dferst erfolgreiches Wohlt\u00e4tigkeitslaufrennen Runway Run organisiert, eine in ganz Europa einzigartige Veranstaltung.<\/strong><\/p>\n<p>Am 2. September 2017 wurde die <a href=\"https:\/\/dailynewshungary.com\/de\/der-grose-britische-zuguberfall-wie-eine-15-kopfige-bande-1963-26-millionen-pfund-stahl\/\" target=\"_blank\" rel=\"noopener noreferrer\">Flughafen<\/a> Betreiber wird Start &#8211; und Landebahn f\u00fcr fast tausend L\u00e4ufer schlie\u00dfen (oder \u00f6ffnen) Die exklusive Veranstaltung ist in erster Linie f\u00fcr ein Publikum aus der Welt der Luftfahrt und des Handels gedacht, aber Teilnehmer der Suhanj! Stiftung, bekannte Sportler und Pers\u00f6nlichkeiten des \u00f6ffentlichen Lebens, Mitglieder der Medien werden ebenfalls teilnehmen.<\/p>\n<p>In diesem Jahr werden Einnahmen aus den Startgeldern zur Unterst\u00fctzung der SUHANJ! Stiftung verwendet.<\/p>\n<p><strong>Datum:<\/strong> 2. September 2017, um 11 Uhr (Samstag)<br \/>\n<strong>Veranstaltungsort:<\/strong> Landebahn Budapest Flughafen 13R-31L<br \/>\n<strong>Entfernungen:<\/strong> 5 km und 10 km<\/p>\n<p><strong>Wettbewerbskategorien:<\/strong><br \/>\no 5 km Einzel<br \/>\no 10 km Einzel<br \/>\no Kinder laufen 6 bis 15 Jahre (1 km)<\/p>\n<p><strong>Startgeld:<\/strong><\/p>\n<p>Die Registrierung als L\u00e4ufer endete am 18. August 2017. Ich habe die Registrierung verpasst, seien Sie nicht traurig, denn n\u00e4chstes Jahr wird der Runway Run mit Sicherheit organisiert  <\/p>\n<p>https:\/\/www.youtube.com\/watch?v=GbehU5N9xeU<\/p>\n<p><em>Weitere Informationen: <a href=\"mailto:bu**********@********ok.hu\" data-original-string=\"onP0+dkT\/CpOfAQgUQRlhw==dd1apk+DLcQSH68id0a1NmopdmzQ5LmH2GrIaZUej02wQM=\" title=\"This contact has been encoded by Anti-Spam by CleanTalk. Click to decode. To finish the decoding make sure that JavaScript is enabled in your browser.\" target=\"_blank\" rel=\"noopener noreferrer\"><span \n                data-original-string='Qba9UmMPaPlSF9kZPocN8w==dd1imr\/g8oPWGLZsRe3rRTu\/DCkGQPvH1z1WFgZDr5a+d4='\n                class='apbct-email-encoder'\n                title='This contact has been encoded by Anti-Spam by CleanTalk. Click to decode. To finish the decoding make sure that JavaScript is enabled in your browser.'>bu<span class=\"apbct-blur\">**********<\/span>@<span class=\"apbct-blur\">********<\/span>ok.hu<\/span><\/a><\/em><\/p>\n<p><em>** Bei Kindern wird der Eintritt f\u00fcr 1 Escort gew\u00e4hrt, sobald die erforderlichen personenbezogenen Daten angegeben wurden, \u00fcber die Registrierungsseite Bitte geben Sie ESCORT in das Feld Firmenname ein F\u00fcr Escorts wird kein gesondertes Startgeld erhoben.<\/em><\/p>\n<p><em>Foto: facebook.com\/pg\/budapestairport<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dies ist das f\u00fcnfte Jahr, in dem der Flughafen Budapest sein \u00e4u\u00dferst erfolgreiches Wohlt\u00e4tigkeitslaufrennen Runway Run organisiert, eine in ganz Europa einzigartige Veranstaltung. Am 2. September 2017 wurde die Flughafen Betreiber wird Start &#8211; und Landebahn f\u00fcr fast tausend L\u00e4ufer schlie\u00dfen (oder \u00f6ffnen) Die exklusive Veranstaltung ist in erster Linie f\u00fcr ein Publikum aus der [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":745814,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1219],"tags":[1115,1446,1469],"class_list":["post-745813","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport","tag-flughafen","tag-outdoor-sport","tag-veranstaltung"],"blocksy_meta":[],"acf":[],"author_username":"alk","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"Dies ist das f\u00fcnfte Jahr, in dem der Flughafen Budapest sein \u00e4u\u00dferst erfolgreiches Wohlt\u00e4tigkeitslaufrennen Runway Run organisiert.","focus_keyword":"Landebahn Run","canonical_url":"","robots":"","primary_category":"1219","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/745813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=745813"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/745813\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/745814"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=745813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=745813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=745813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}