{"id":745999,"date":"2017-08-21T09:30:07","date_gmt":"2017-08-21T07:30:07","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/20-august-partys-markieren-den-nationalfeiertag-st-stephen-aktualisierung\/"},"modified":"2017-08-21T09:30:07","modified_gmt":"2017-08-21T07:30:07","slug":"20-august-partys-markieren-den-nationalfeiertag-st-stephen-aktualisierung","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/20-august-partys-markieren-den-nationalfeiertag-st-stephen-aktualisierung\/","title":{"rendered":"20. August \u2013 Partys markieren den Nationalfeiertag St. Stephen \u2013 AKTUALISIERUNG"},"content":{"rendered":"<p><strong>Jobbik-Chef G\u00e1bor Vona startete bei der Veranstaltung der Partei am 20. August in Budapest eine Unterschriftenaktion f\u00fcr eine europ\u00e4ische Lohnunion. Fraktionsvorsitzender der regierenden Fidesz-Partei, Lajos K\u00f3sa, markiert <a href=\"https:\/\/dailynewshungary.com\/de\/was-feiern-die-ungarn-am-20-august\/\" target=\"_blank\" rel=\"noopener\">Ungarns Nationalfeiertag am Sonntag<\/a>\u201esagte das Erbe des heiligen Stephanus und verpflichtet die Ungarn, den Weg zu gehen, der in tausend Jahren seiner Staatlichkeit vorgezeichnet wurde.<\/strong><\/p>\n<p>Bei einer Veranstaltung in Debrecen in S\u00fcdungarn nannte K\u00f3sa Ungarn \u201cstark und unabh\u00e4ngig; eine christliche Nation und eine Gemeinschaft von Ungarn, die immer aufgeschlossen, aber gleichzeitig darauf bedacht sind, ihre Kultur, ihren Charakter, ihr Erbe und ihre Freiheit zu bewahren\u201d.<\/p>\n<p>L\u00e1szlo Botka, die Opposition <a href=\"https:\/\/dailynewshungary.com\/de\/der-grose-britische-zuguberfall-wie-eine-15-kopfige-bande-1963-26-millionen-pfund-stahl\/\" target=\"_blank\" rel=\"noopener\">Sozialistische Partei<\/a>\u2018s Ministerpr\u00e4sidentenkandidat, sagte: \u201cWir m\u00fcssen nach Europa zur\u00fcckkehren\u201d.<\/p>\n<figure id=\"attachment_137269\" aria-describedby=\"caption-attachment-137269\" style=\"width: 1024px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-137269 size-large\" src=\"https:\/\/dailynewshungary.com\/wp-content\/uploads\/2017\/08\/botka-augusztus-20-1024x677.jpg\" alt=\"Botka Augusztus X\" width=\"1024\" height=\"677\" srcset=\"https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2017\/08\/botka-augusztus-20-1024x677.jpg 1024w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2017\/08\/botka-augusztus-20-300x198.jpg 300w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2017\/08\/botka-augusztus-20-768x507.jpg 768w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2017\/08\/botka-augusztus-20-220x145.jpg 220w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2017\/08\/botka-augusztus-20-600x396.jpg 600w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2017\/08\/botka-augusztus-20-200x132.jpg 200w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2017\/08\/botka-augusztus-20-1080x714.jpg 1080w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2017\/08\/botka-augusztus-20.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"><figcaption id=\"caption-attachment-137269\" class=\"wp-caption-text\">L\u00e1szl\u00f3 Botka \u2013 Foto: MTI<\/figcaption><\/figure>\n<p>\u201cWir k\u00f6nnen nur dann eine gl\u00fcckliche und koh\u00e4rente Nation des Karpatenbeckens sein, wenn wir innerhalb der Grenzen und dar\u00fcber hinaus gr\u00f6\u00dfere Verantwortung \u00fcbernehmen\u201d, sagte Botka in Szeged, der s\u00fcdungarischen Stadt, deren B\u00fcrgermeister er istEr sagte, Patriot zu sein bedeutet, \u201cunser historisches und kulturelles Erbe f\u00fcr k\u00fcnftige Generationen zu sch\u00fctzen und unsere gespaltene Gesellschaft wieder zu vereinen\u201d<\/p>\n<p><a href=\"https:\/\/dailynewshungary.com\/de\/dialog-co-leiter-oppositionsparteien-bekampfen-sich-anstatt-zu-kooperieren\/\" target=\"_blank\" rel=\"noopener\">Wie wir gestern geschrieben haben<\/a>, bei der Demonstration zur Unterst\u00fctzung einer freien Presse und eines Regierungswechsels sagte Gergely Kar\u00e1csony, Co-Vorsitzender von Dialogue, der Menge, dass nach den Parlamentswahlen 2018 der von St. Stephen gegr\u00fcndete Staat, der in den vergangenen 100 Jahren mehrfach zerst\u00f6rt worden war, wieder aufgebaut werden m\u00fcsse.<\/p>\n<h4>Jobbik: Rammbock in Bewegung, letzte Chance f\u00fcr die EU!<\/h4>\n<p>Laut Jobbik-Pressestelle hat G\u00e1bor Vona am 20. August offiziell die Initiative der Lohngewerkschaft ins Leben gerufen: Im Rahmen des im Budapester Stadtpark abgehaltenen Familientags von Jobbik beteuerte der Pr\u00e4sident der gr\u00f6\u00dften Oppositionspartei, es sei das vitale Interesse der EU, das Lohngef\u00e4lle auf unserem Kontinent zu spalten, und wies auch darauf hin, dass die ostmitteleurop\u00e4ischen Regierungen eine gro\u00dfe Verantwortung h\u00e4tten, diese historische Chance nicht zu verpassen Mit der Unterzeichnung der Lohngewerkschaftsinitiative von Jobbik hat Herr Vona das Projekt am 20. August offiziell auf der Familienveranstaltung der Partei ins Leben gerufen, davor hat der Ministerpr\u00e4sidentkandidat der st\u00e4rksten Oppositionspartei die in acht EU-Mitgliedstaaten laufende Kampagne zur \u00dcbernahme von \u201cgleichen L\u00f6hnen f\u00fcr gleiche Arbeit\u201d als Grundrecht eingef\u00fchrt.<\/p>\n<p>An die Kritiker der Lohngewerkschaftsinitiative wandte sich der Politiker, dass einige von ihnen sich vielleicht nicht die M\u00fche gemacht h\u00e4tten, das Dokument tats\u00e4chlich zu lesen, also \u201chaben sie keine Ahnung, worum es geht\u201d Er f\u00fcgte hinzu, dass das Konzept der Lohnunion keine Erh\u00f6hung der L\u00f6hne \u00fcber Nacht beinhaltet \u201cDas ist ein europ\u00e4isches Reformprojekt! weil in der Europ\u00e4ischen Union etwas nicht stimmt\u201d, erkl\u00e4rte Herr Vona und verwies auf das unerf\u00fcllte Versprechen an die neu beigetretenen L\u00e4nder, dass ihre L\u00f6hne denen der westlichen Staaten n\u00e4her kommen w\u00fcrden. \u201eEr sprach davon, dass die EU nur erweitert werden w\u00fcrde, um neue M\u00e4rkte und billige Arbeitskr\u00e4fte im Osten zu gewinnen, nannte er es einen Systemfehler.<\/p>\n<p>Das Konzept der Lohnunion hat sich jedoch bereits als machbar erwiesen, wie das historische Beispiel Ostdeutschland zeigt: Die ehemalige DDR ist heute die 14. am weitesten entwickelte Region in der Europ\u00e4ischen Union \u201cWenn Ostdeutschland es schaffen k\u00f6nnte, sollte es auch die gesamte Europ\u00e4ische Union schaffen\u201d Herr Vona beteuerte, es sei nur eine Frage wahrer Absichten gewesen, das ostdeutsche Beispiel weiter zu erl\u00e4utern, sagte er, die Integration der DDR habe Deutschland nicht schw\u00e4cher gemachtIm Gegenteil, die Deutschen seien noch st\u00e4rker geworden Wie er es ausdr\u00fcckte: \u201cDie Europ\u00e4ische Union wird entweder die Lohnunion \u00fcbernehmen, oder es wird \u00fcberhaupt keine Europ\u00e4ische Union geben\u201d<\/p>\n<p>Betonend, dass die B\u00fcrgerinitiative die h\u00f6chste Ebene der Volksaktion in der Europ\u00e4ischen Union sei, und wenn es eine noch h\u00f6here g\u00e4be, h\u00e4tten sie sie ergriffen, stellte er die Frage: \u201cAber warum muss ich, Jobbik, die Opposition das tun?\u201d, so seine Antwort, der Grund, dass die ungarischen Regierungen der vergangenen 27 Jahre unsere Wirtschaft auf billige Arbeitskr\u00e4fte gr\u00fcndeten \u201cLassen Sie uns mit der Idee spielen, was passiert w\u00e4re, wenn Viktor Orb\u00e1n auf das Konzept der Europ\u00e4ischen Lohnunion gekommen w\u00e4re! w\u00fcrde Jobbik es unterst\u00fctzen? ja!\u201d, so wollte er betonen, dass die Verringerung des Lohngef\u00e4lles eine \u00fcberparteiliche Initiative sei, mit der Frage: \u201cHek k\u00f6nnte die anst\u00e4ndige Idee des ungarischen Erwerbs nicht unterst\u00fctzen!<\/p>\n<p>Als er \u00fcber den \u00fcberparteilichen Charakter des Vorschlags sprach, sagte er, er k\u00e4mpfe nicht nur f\u00fcr Jobbiks Anh\u00e4nger um europ\u00e4ische L\u00f6hne. \u201eDas Banner der Lohngewerkschaft wurde von Jobbik gehisst, aber wir begr\u00fc\u00dfen alle, die dieses Banner hochhalten m\u00f6chten.\u201cbehie\u00df der Premierministerkandidat\u201d.<\/p>\n<p>Nach Ansicht von Herrn Vona haben wir in Bezug auf die Schaffung eines neuen Europas unsere eigenen Hausaufgaben zu erledigen Diese Hausaufgabe besteht darin, ein Ungarn zu schaffen, das in der Lage ist, eine solche wirtschaftliche Chance zu nutzen, da Fidesz in den vergangenen sieben Jahren nur erreicht hat, dass der Mindestlohn langsam das Existenzminimum zu erreichen scheint Er \u00e4u\u00dferte seine Meinung, dass wir die Schweiz Mitteleuropas sein k\u00f6nnten, wenn das Verm\u00f6gen von 62 Tausend Milliarden HUF, das derzeit \u00fcber korrupte Offshore-Kan\u00e4le leckt, den L\u00f6hnen zugewiesen w\u00fcrde Er betonte, dass es keine umfassende Wirtschaftspolitik sei, dem Strohmann des Premierministers L ofrinc M\u00e9sz\u00e1ros alles zu geben Stattdessen sollten ungarische kleine und mittlere Unternehmen dabei unterst\u00fctzt werden, in den internationalen Markt eintreten zu k\u00f6nnen.<\/p>\n<p>Herr Vona betonte auch, dass die Zahl der Unterschriften f\u00fcr die Lohngewerkschaftsinitiative eine Botschaft an Br\u00fcssel sei \u201cDas ist wie ein Rammbock: Je mehr von uns sie schieben, desto leichter ist es, die Tore Br\u00fcssels zu durchbrechen\u201d, zog der Pr\u00e4sident eine Analogie, um die historische Chance aufzuzeigenEr wies auf eine Frage hin, dass Rentner auch mit der Lohngewerkschaft besser dran w\u00e4renErkl\u00e4rte, warum es im Interesse der Rentner liegt, ihre Unterst\u00fctzungsbekundungen f\u00fcr die Sache der Lohngewerkschaft abzugeben, sagte er, dass h\u00f6here L\u00f6hne auch h\u00f6here Renten generieren w\u00fcrden Er wies auch darauf hin, dass Arbeit an sich nicht ausreiche: \u201cWenn man f\u00fcr seine Arbeit einen angemessenen Lohn hat, dann ist das alles da\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Bei den Bem\u00fchungen um die Lohnunion setzt Jobbik auf B\u00fcrger, die ihre Unterst\u00fctzungsbekundungen abgeben, sowie auf diejenigen, die aktiv zur Kampagne beitragen, indem sie die Nachricht verbreiten: \u201eWir brauchen in dieser Angelegenheit das gesamte ungarische Volk, denn es ist die letzte Chance f\u00fcr die Europ\u00e4ische Union.\u201cDas Schicksal der EU wird in den n\u00e4chsten Jahren entschieden werden\u201d, bekr\u00e4ftigte er und f\u00fcgte hinzu, dass wir nicht zulassen k\u00f6nnen, dass Entscheidungen \u00fcber unseren K\u00f6pfen getroffen werden. \u201eWir m\u00fcssen diesen Pr\u00fcgelbock gemeinsam aufbringen, damit die Europ\u00e4ische Union wirklich dem Volk geh\u00f6ren kann!\u201d Herr Vona erkl\u00e4rte, dass ihr Ziel darin bestehe, allen das Gedeihen in ihrem eigenen Heimatland zu erm\u00f6glichen. \u201eWir k\u00f6nnen die Auswirkungen Ungarns weiter verhindern\u201c\u201eDer Politiker wird sich darauf berufen, dass\u201d<\/p>\n<p style=\"text-align: center;\">[button link=\u201dhttps:\/\/ec.europa.eu\/citizens-initiative\/33\/public\/index.do?lang=en\u201d type=\u201dbig\u201d color=\u201dteal\u201d newwindow=\u201dyes\u201d] WAGE UNION \u2013 Europ\u00e4ische B\u00fcrgerinitiative finden Sie hier![\/button]<\/p>\n<p><em>Ausgew\u00e4hlte Bild: MTI<\/em><\/p>\n<p>ce: ZsK<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jobbik-Chef G\u00e1bor Vona startete bei der Veranstaltung der Partei am 20. August in Budapest eine Unterschriftenaktion f\u00fcr eine europ\u00e4ische Lohnunion. Fraktionsvorsitzender der regierenden Fidesz-Partei, Lajos K\u00f3sa, markiert Ungarns Nationalfeiertag am Sonntag\u201esagte das Erbe des heiligen Stephanus und verpflichtet die Ungarn, den Weg zu gehen, der in tausend Jahren seiner Staatlichkeit vorgezeichnet wurde. Bei einer Veranstaltung [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":746000,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1081],"tags":[1091,1144,1632,1598,1695],"class_list":["post-745999","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politik","tag-fidesz","tag-gedenken","tag-jobbik","tag-nationalfeiertag","tag-sozialisten"],"blocksy_meta":[],"acf":[],"author_username":"Szandi","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"Laut Lajos K\u00f3sa verpflichtet das Erbe des Heiligen Stephan die Ungarn, den Weg zu gehen, der in tausend Jahren seiner Staatlichkeit vorgezeichnet wurde.","focus_keyword":"Nationalfeiertag","canonical_url":"","robots":"","primary_category":"1081","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"58","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/745999","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=745999"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/745999\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/746000"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=745999"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=745999"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=745999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}