{"id":753388,"date":"2016-11-17T15:00:45","date_gmt":"2016-11-17T14:00:45","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/entscheidungsparteien-und-oppositionskandidaten-erzielen-einigung-uber-kandidaten-fur-das-oberste-gericht-aktualisierung\/"},"modified":"2016-11-17T15:00:45","modified_gmt":"2016-11-17T14:00:45","slug":"entscheidungsparteien-und-oppositionskandidaten-erzielen-einigung-uber-kandidaten-fur-das-oberste-gericht-aktualisierung","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/entscheidungsparteien-und-oppositionskandidaten-erzielen-einigung-uber-kandidaten-fur-das-oberste-gericht-aktualisierung\/","title":{"rendered":"Entscheidungsparteien und Oppositionskandidaten erzielen Einigung \u00fcber Kandidaten f\u00fcr das oberste Gericht \u2013 AKTUALISIERUNG"},"content":{"rendered":"<p><strong>Budapest, 17. November (MTI) \u2013 Das regierende B\u00fcndnis Fidesz-KDNP und die gr\u00fcne Opposition LMP haben am Donnerstag eine Einigung \u00fcber die Kandidaten erzielt, um die vier freien Stellen im Verfassungsgericht zu besetzen, sagte der Fraktionsvorsitzende von Fidesz, Lajos K\u00f3sa, Verfassungsrichter Tam\u00e1s Sulyok wurde vom Parlamentspr\u00e4sidenten L\u00e1szl\u00f3 K\u00f6v\u00e9r f\u00fcr den Posten des Pr\u00e4sidenten des Verfassungsgerichts nominiert.<\/strong><\/p>\n<p>Die drei Fraktionen einigten sich darauf, den K\u00faria-Richter Ildik\u00f3 Marosi, Attila Horv\u00e1th, Rechtshistoriker, Bal\u00e1zs Schanda, Verfassungsrechtler, und Marcel Szab\u00f3, stellvertretender Ombudsmann f\u00fcr k\u00fcnftige Generationen, Gergely Guly\u00e1s, stellvertretender Leiter des parlamentarischen Ausschusses, der f\u00fcr die Nominierung von Verfassungsgerichten zust\u00e4ndig ist, zu ernennen Richter, sagte auf einer Pressekonferenz.<\/p>\n<p>Das Parlament wird voraussichtlich am kommenden Dienstag \u00fcber die Nominierten abstimmen.<\/p>\n<p>Kosa sagte, die drei Parteien h\u00e4tten sich auch darauf geeinigt, wen sie f\u00fcr die Leitung des Verfassungsgerichts nominieren w\u00fcrden.<\/p>\n<h4>Verfassungsrichter Tam\u00e1s Sulyok wurde zum obersten Gerichtsvorsitzenden ernannt<\/h4>\n<p>Die 15 Mitglieder des Gerichts werden vom Parlament, mit Zweidrittelunterst\u00fctzung aller Gesetzgeber, f\u00fcr zw\u00f6lf Jahre gew\u00e4hlt, der Leiter des Gerichts wird ebenfalls vom Parlament gew\u00e4hlt, und zwar aus dem Kreis der Richter.<\/p>\n<p>Die Zahl der Verfassungsgerichtsrichter sank im vergangenen Jahr auf 11, der Posten des Pr\u00e4sidenten ist derzeit unbesetzt, Sulyok wurde im September 2014 zum obersten Gerichtsmitglied gew\u00e4hlt, am 1. April 2015 wurde er stellvertretender Gerichtsvorsteher und ist seit dem 22. April dieses Jahres kommissarischer Pr\u00e4sident.<\/p>\n<p>Das Parlament wird voraussichtlich am kommenden Dienstag \u00fcber die Kandidaten f\u00fcr die Besetzung des Pr\u00e4sidentenpostens und vier freier Stellen abstimmen.<\/p>\n<h4>Reaktionen<\/h4>\n<p>&nbsp;<\/p>\n<p>Die oppositionellen Sozialisten nannten die geplante Wahl einen Schritt \u201ean einen Putsch grenzend\u201cund k\u00fcndigten an, dass sie der Abstimmung am Dienstag fernbleiben w\u00fcrden. Der stellvertretende Fraktionsvorsitzende S\u00e1ndor Bur\u00e1ny sagte, die Sozialisten bedauern, dass die LMP dieses Man\u00f6ver unterst\u00fctze.<\/p>\n<p>Die oppositionelle Jobbik-Partei kritisierte die Regierungsparteien daf\u00fcr, dass sie sie nicht konsultierten, und warf LMP vor, \u201eeinen Backstage-Pakt\u201cmit Fidesz geschlossen zu haben. Jobbik sagte, es werde zu einem sp\u00e4teren Zeitpunkt eine Position zu den Kandidaten einnehmen.<\/p>\n<p>LMP-Co-Chef \u00c1kos Hadh\u00e1zy sagte, dass es nach der Wahl mehr Gerichtsmitglieder geben w\u00fcrde, die unabh\u00e4ngig von der Regierung Entscheidungen treffen k\u00f6nnten. LMP habe nichts als Gegenleistung f\u00fcr seine Unterst\u00fctzung verlangt, sagte er. LMP stellte lediglich die Voraussetzungen daf\u00fcr, dass die Kandidaten unabh\u00e4ngig und engagiert sein sollten f\u00fcr die Umwelt und eine Frau, sagte er.<\/p>\n<p>Die oppositionelle Demokratische Koalition bezeichnete LMP als Kollaborateur f\u00fcr ihre Einigung mit den Regierungsparteien \u00fcber die Kandidaten.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Budapest, 17. November (MTI) \u2013 Das regierende B\u00fcndnis Fidesz-KDNP und die gr\u00fcne Opposition LMP haben am Donnerstag eine Einigung \u00fcber die Kandidaten erzielt, um die vier freien Stellen im Verfassungsgericht zu besetzen, sagte der Fraktionsvorsitzende von Fidesz, Lajos K\u00f3sa, Verfassungsrichter Tam\u00e1s Sulyok wurde vom Parlamentspr\u00e4sidenten L\u00e1szl\u00f3 K\u00f6v\u00e9r f\u00fcr den Posten des Pr\u00e4sidenten des Verfassungsgerichts nominiert. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":753389,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1081],"tags":[1091,1326,1746,1873,1658],"class_list":["post-753388","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politik","tag-fidesz","tag-gericht","tag-hausredner","tag-lmp","tag-parlament"],"blocksy_meta":[],"acf":[],"author_username":"alk","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"","focus_keyword":"Obergericht","canonical_url":"","robots":"","primary_category":"1081","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"56","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/753388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=753388"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/753388\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/753389"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=753388"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=753388"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=753388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}