{"id":755351,"date":"2016-09-01T16:30:48","date_gmt":"2016-09-01T14:30:48","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/ikonische-ungarische-schokolade-kehrt-nach-szerencs-zuruck\/"},"modified":"2016-09-01T16:30:48","modified_gmt":"2016-09-01T14:30:48","slug":"ikonische-ungarische-schokolade-kehrt-nach-szerencs-zuruck","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/ikonische-ungarische-schokolade-kehrt-nach-szerencs-zuruck\/","title":{"rendered":"Ikonische ungarische Schokolade kehrt nach Szerencs zur\u00fcck"},"content":{"rendered":"<p><strong>Jahrzehntelang war der Name Szerencs ein Synonym f\u00fcr die ungarische Schokoladenproduktion <a href=\"http:\/\/www.globoport.hu\/172203\/az-orszag-legedesebb-hetvegeje\/\" target=\"_blank\" rel=\"noopener noreferrer\">globoport.hu<\/a> Schreibt. es ist kein Zufall, dass hier in diesem Jahr zum neunten Mal das Nationale Schokoladenfest veranstaltet wurde Aber eine Schokoladenfabrik im Ort gibt es seit einigen Jahren nicht mehr \u2013 bis jetzt.<\/strong><\/p>\n<p>Fr\u00fcher war Szerencs ber\u00fchmt f\u00fcr seine Schokolade, was aber leider nur eine Tradition in der Vergangenheit bedeutete Der Wandel des politischen Systems bewirkte den Niedergang der Schokoladenproduktion, und im Ort blieb nur noch die Expertise, die Begeisterung, das Schokoladenfest, das Festival hat sich seitdem ausgeweitet, mit Programmen f\u00fcr die ganze Familie, Sporttage f\u00fcr die Schulen des Kreises und ein Schokoladen-Abenteuerpark unterhielten die Kids, w\u00e4hrend die Erwachsenen unter anderem die Konzerte ungarischer Bands genie\u00dfen konnten.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-82320 size-large\" src=\"https:\/\/dailynewshungary.com\/wp-content\/uploads\/2016\/08\/csokifeszt2016b-1024x576.jpg\" alt=\"Dobos Schokolade Szerencs\" width=\"1024\" height=\"576\" srcset=\"https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2016\/08\/csokifeszt2016b-1024x576.jpg 1024w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2016\/08\/csokifeszt2016b-300x169.jpg 300w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2016\/08\/csokifeszt2016b-768x432.jpg 768w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2016\/08\/csokifeszt2016b-220x124.jpg 220w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2016\/08\/csokifeszt2016b-610x343.jpg 610w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2016\/08\/csokifeszt2016b-1080x608.jpg 1080w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2016\/08\/csokifeszt2016b.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"><\/p>\n<p>Der wichtigste Aspekt von Szerencs ist jedoch immer noch die Schokolade, die nun in Form der Szerencs Confectionary Ltd. in die Stadt zur\u00fcckkehrt. Ihr erstes wirklich unkonventionelles Produkt, das noch immer ungarischen Traditionen folgt, ist die Dobos-Schokolade, die von der inspiriert wurde Geschmackskombinationen des ber\u00fchmten Dobos-Kuchens.<\/p>\n<p style=\"text-align: center;\">[button link=\u201dhttps:\/\/dailynewshungary.com\/tag\/gastronomie\/\u201d type=\u201dbig\u201d color=\u201d red\u201d newwindow=\u201d yes\u201d] Weiterlesen Artikel \u00fcber ungarisches Essen [\/button]<\/p>\n<p>Der neue Eigent\u00fcmer des Unternehmens, der Gesch\u00e4ftsmann S\u00e1ndor Balogh <a href=\"https:\/\/dailynewshungary.com\/de\/die-afrikanisch-ungarische-union-ist-10-jahre-alt-interview-mit-sandor-balogh\/\" target=\"_blank\" rel=\"noopener noreferrer\">Chef der 10 Jahre alten Afrikanischen Ungarischen Union<\/a>, und das siebenb\u00fcrgische Chocolatier Dezs. G\u00e1lffi plant, dem Unternehmen seinen fr\u00fcheren Glanz zur\u00fcckzugeben.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-82321 size-large\" src=\"https:\/\/dailynewshungary.com\/wp-content\/uploads\/2016\/08\/csokifeszt2016c-768x1024.jpg\" alt=\"Dobos Schokolade Szerencs\" width=\"768\" height=\"1024\" srcset=\"https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2016\/08\/csokifeszt2016c-768x1024.jpg 768w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2016\/08\/csokifeszt2016c-225x300.jpg 225w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2016\/08\/csokifeszt2016c-165x220.jpg 165w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2016\/08\/csokifeszt2016c-610x813.jpg 610w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2016\/08\/csokifeszt2016c-1080x1440.jpg 1080w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2016\/08\/csokifeszt2016c.jpg 1200w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\"><\/p>\n<p>Das Unternehmen m\u00f6chte mit Produkten in die internationalen M\u00e4rkte eintreten, die die traditionelle Szerencs-Produktpalette erg\u00e4nzen und gleichzeitig charakteristisch ungarisch bleiben. Daher werden diese handwerklichen Qualit\u00e4tsprodukte als Spezialit\u00e4ten in anderen Teilen der Welt erscheinen. Die Dobos-Schokolade enth\u00e4lt bereits eine Milchschokolade, eine dunkle Schokolade und eine wei\u00dfe Schokoladenversion.<\/p>\n<p><em>Fotos: globoport.hu<\/em><\/p>\n<p>Editor kopieren: bm<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jahrzehntelang war der Name Szerencs ein Synonym f\u00fcr die ungarische Schokoladenproduktion globoport.hu Schreibt. es ist kein Zufall, dass hier in diesem Jahr zum neunten Mal das Nationale Schokoladenfest veranstaltet wurde Aber eine Schokoladenfabrik im Ort gibt es seit einigen Jahren nicht mehr \u2013 bis jetzt. Fr\u00fcher war Szerencs ber\u00fchmt f\u00fcr seine Schokolade, was aber leider [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":755352,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1281],"tags":[1473,1268,1125,3960],"class_list":["post-755351","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geschaft","tag-essen","tag-gastronomie","tag-geschichte","tag-htcc"],"blocksy_meta":[],"acf":[],"author_username":"esztervass","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"","focus_keyword":"szerencs Schokolade","canonical_url":"","robots":"","primary_category":"1281","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"18","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/755351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=755351"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/755351\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/755352"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=755351"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=755351"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=755351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}