{"id":755696,"date":"2016-08-19T17:00:43","date_gmt":"2016-08-19T15:00:43","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/ausenminister-zu-besuch-in-der-turkei-um-orbans-reise-vorzubereiten\/"},"modified":"2016-08-19T17:00:43","modified_gmt":"2016-08-19T15:00:43","slug":"ausenminister-zu-besuch-in-der-turkei-um-orbans-reise-vorzubereiten","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/ausenminister-zu-besuch-in-der-turkei-um-orbans-reise-vorzubereiten\/","title":{"rendered":"Au\u00dfenminister zu Besuch in der T\u00fcrkei, um Orb\u00e1ns Reise vorzubereiten"},"content":{"rendered":"<p><strong>Budapest, 19. August (MTI) \u2013 Au\u00dfenminister P\u00e9ter Szijj\u00e1rt\u00f3 wird am kommenden Dienstag Ankara einen Besuch abstatten, um eine geplante Reise von Premierminister Viktor Orb\u00e1n in die T\u00fcrkei vorzubereiten, berichtete das Nachrichtenportal Origo und das Au\u00dfenministerium hat die Informationen best\u00e4tigt.<\/strong><\/p>\n<p>Szijj\u00e1rt\u00f3 werde der erste hochrangige europ\u00e4ische Politiker sein, der die T\u00fcrkei seit dem gescheiterten Putsch im Juli besucht, sagte Origo. Von Ankara aus werde Szijj\u00e1rt\u00f3 nach \u00c4gypten reisen und seinen Premierminister und Au\u00dfenminister treffen, f\u00fcgte das Portal hinzu.<\/p>\n<p>Neben den Vorbereitungen f\u00fcr Orb\u00e1ns Besuch wird Szijj\u00e1rt\u00f3 seinen Amtskollegen Mevlut Cavusoglu treffen, um die bilaterale Zusammenarbeit und ein Abkommen zwischen der T\u00fcrkei und der Europ\u00e4ischen Union zu besprechen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Budapest, 19. August (MTI) \u2013 Au\u00dfenminister P\u00e9ter Szijj\u00e1rt\u00f3 wird am kommenden Dienstag Ankara einen Besuch abstatten, um eine geplante Reise von Premierminister Viktor Orb\u00e1n in die T\u00fcrkei vorzubereiten, berichtete das Nachrichtenportal Origo und das Au\u00dfenministerium hat die Informationen best\u00e4tigt. Szijj\u00e1rt\u00f3 werde der erste hochrangige europ\u00e4ische Politiker sein, der die T\u00fcrkei seit dem gescheiterten Putsch im [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":755697,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1081],"tags":[1169,1200,1333],"class_list":["post-755696","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politik","tag-aussenministerium-von-ungarn","tag-turkei","tag-viktor-oder-ban"],"blocksy_meta":[],"acf":[],"author_username":"alk","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"","focus_keyword":"Truthahn hungary","canonical_url":"","robots":"","primary_category":"1081","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"4","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/755696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=755696"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/755696\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/755697"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=755696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=755696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=755696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}