{"id":756655,"date":"2016-07-13T12:40:18","date_gmt":"2016-07-13T10:40:18","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/lmp-schlagt-die-einrichtung-von-grenzschutztruppen-vor\/"},"modified":"2016-07-13T12:40:18","modified_gmt":"2016-07-13T10:40:18","slug":"lmp-schlagt-die-einrichtung-von-grenzschutztruppen-vor","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/lmp-schlagt-die-einrichtung-von-grenzschutztruppen-vor\/","title":{"rendered":"LMP schl\u00e4gt die Einrichtung von Grenzschutztruppen vor"},"content":{"rendered":"<p><strong>Budapest, 13. Juli (MTI) \u201eAsylverfahren in Ungarn sind \u201esinnlos\u201c geworden, da es jetzt fast unm\u00f6glich ist, Asyl zu erhalten, und dies zu einem Anstieg des Menschenschmuggels gef\u00fchrt hat, sagte ein Sprecher der oppositionellen LMP.<\/strong><\/p>\n<p>Dieser Trend habe auch die Belastung der ungarischen Polizei erh\u00f6ht, die bereits mit Personalmangel zu k\u00e4mpfen habe, da Beamte f\u00fcr Patrouillenaufgaben an den Grenzen entsandt worden seien, sagte Ferenc Gerstm\u00e1r auf einer Pressekonferenz.<\/p>\n<p>Als L\u00f6sung schlage LMP vor, dass die Regierung eine separate Grenzschutzeinheit einrichten sollte, sagte er und f\u00fcgte hinzu, dass die Partei die regionale Zusammenarbeit der Beh\u00f6rden dr\u00e4nge, bis diese Ma\u00dfnahme umgesetzt sei.<\/p>\n<p><em>Foto: MTI<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Budapest, 13. Juli (MTI) \u201eAsylverfahren in Ungarn sind \u201esinnlos\u201c geworden, da es jetzt fast unm\u00f6glich ist, Asyl zu erhalten, und dies zu einem Anstieg des Menschenschmuggels gef\u00fchrt hat, sagte ein Sprecher der oppositionellen LMP. Dieser Trend habe auch die Belastung der ungarischen Polizei erh\u00f6ht, die bereits mit Personalmangel zu k\u00e4mpfen habe, da Beamte f\u00fcr Patrouillenaufgaben [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":756656,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1081],"tags":[1873,1445,1236],"class_list":["post-756655","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politik","tag-lmp","tag-migration","tag-polizei"],"blocksy_meta":[],"acf":[],"author_username":"alk","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"","focus_keyword":"","canonical_url":"","robots":"","primary_category":"1081","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/756655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=756655"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/756655\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/756656"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=756655"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=756655"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=756655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}