{"id":757061,"date":"2016-06-28T12:35:27","date_gmt":"2016-06-28T10:35:27","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/hadhazy-um-fur-das-amt-des-lmp-co-vorsitzenden-zu-kandidieren\/"},"modified":"2016-06-28T12:35:27","modified_gmt":"2016-06-28T10:35:27","slug":"hadhazy-um-fur-das-amt-des-lmp-co-vorsitzenden-zu-kandidieren","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/hadhazy-um-fur-das-amt-des-lmp-co-vorsitzenden-zu-kandidieren\/","title":{"rendered":"Hadh\u00e1zy, um f\u00fcr das Amt des LMP-Co-Vorsitzenden zu kandidieren"},"content":{"rendered":"<p><strong>Budapest, 28. Juni (MTI) \u2013 Die kleine oppositionelle LMP-Partei hat offiziell die Kandidatur von \u00c1kos Hadh\u00e1zy, dem Antikorruptionssprecher der Partei, angenommen, um Andras Schiffer als Co-Vorsitzenden zu ersetzen, sagte die Tageszeitung Magyar Id.k am Dienstag.<\/strong><\/p>\n<p>Schiffer trat Ende Mai von seinem Amt zur\u00fcck und wird sein Mandat als Gesetzgeber am 31. August zur\u00fcckgeben.<\/p>\n<p>Hadh\u00e1zy sagte, er habe zugestimmt, f\u00fcr das Amt des Partei-Co-Vorsitzenden zu kandidieren, da er von mehreren Parteimitgliedern nominiert worden sei. Seine Kandidatur wurde offiziell, nachdem er sein Programm auf einem internen Forum der LMP ver\u00f6ffentlicht hatte.<\/p>\n<p>Die Nominierungen enden am 5. Juli und die Parteiwahlen sind f\u00fcr den 16. und 17. Juli angesetzt.<\/p>\n<p>M\u00f6gliche weitere Kandidaten sind Antal Cs\u00e1rdi, Vertreter der LMP im Budapester Rat, L\u00e1szl\u00f3 L\u00f3r\u00e1nt Keresztes, Mitglied des Parteipr\u00e4sidiums, und P\u00e9ter Ungar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Budapest, 28. Juni (MTI) \u2013 Die kleine oppositionelle LMP-Partei hat offiziell die Kandidatur von \u00c1kos Hadh\u00e1zy, dem Antikorruptionssprecher der Partei, angenommen, um Andras Schiffer als Co-Vorsitzenden zu ersetzen, sagte die Tageszeitung Magyar Id.k am Dienstag. Schiffer trat Ende Mai von seinem Amt zur\u00fcck und wird sein Mandat als Gesetzgeber am 31. August zur\u00fcckgeben. Hadh\u00e1zy sagte, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":757062,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1081],"tags":[1873],"class_list":["post-757061","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politik","tag-lmp"],"blocksy_meta":[],"acf":[],"author_username":"alk","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"","focus_keyword":"","canonical_url":"","robots":"","primary_category":"1081","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/757061","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=757061"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/757061\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/757062"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=757061"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=757061"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=757061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}