{"id":757631,"date":"2016-06-07T15:18:59","date_gmt":"2016-06-07T13:18:59","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/ungarns-frauen-erleiden-in-der-turkei-eine-niederlage\/"},"modified":"2016-06-07T15:18:59","modified_gmt":"2016-06-07T13:18:59","slug":"ungarns-frauen-erleiden-in-der-turkei-eine-niederlage","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/ungarns-frauen-erleiden-in-der-turkei-eine-niederlage\/","title":{"rendered":"Ungarns Frauen erleiden in der T\u00fcrkei eine Niederlage"},"content":{"rendered":"<p><strong>Edina Mark\u00f3s Team hat die T\u00fcrkei im vergangenen Herbst vielleicht bei der Groupama Ar\u00e9na geschlagen, aber sie musste jeden Zentimeter des Weges f\u00fcr die drei Punkte arbeiten. Da es der T\u00fcrkei bereits gelungen war, Russland zu Hause unentschieden zu halten, wurde das Spiel in Antalya als potenzielle Bananenschale f\u00fcr Ungarn angesehen, und es dauerte nicht lange, bis dies geschah. Die T\u00fcrkei ging in der vierten Minute in F\u00fchrung, Ece T\u00fcrko\u011flu erzielte aus der Ferne ein Tor und das Tor ersch\u00fctterte sichtbar eine ungarische Mannschaft, die Schwierigkeiten hatte, ihren Rhythmus zu finden. Die Hausherren verdoppelten ihren Vorsprung in der 27. Minute, Evelin Mosd\u00f3czi setzte sich durch ihr eigenes Netz, und es h\u00e4tte f\u00fcr Mark nicht lange schlechter werden k\u00f6nnen, nachdem die T\u00fcrkei getroffen hatte.<\/strong><\/p>\n<p>Ungarn begann, sein Haus in Ordnung zu bringen, als die Halbzeit zu Ende ging, und verringerte den R\u00fcckstand in der 40. Minute, als Zsanett Jakabfi einen Pass von Fanny V\u00e1g\u00f3 im Strafraum erhielt, bevor er kurz vor dem Pfosten traf. Ungarn dominierte das Spiel in der zweiten Halbzeit, konnte seine \u00dcberlegenheit jedoch nicht in Tore umwandeln, da die Holzarbeiten so knapp waren wie m\u00f6glich. Bei einem sp\u00e4ten Aufschwung schuf Ungarn eine Reihe von Torchancen, doch das Ende blieb weiterhin glanzlos, da die T\u00fcrkei das Spiel mit 2-1 gewann.<\/p>\n<p>\u201cWir sind schlecht ins Spiel gestartet; es war, als ob wir glaubten, wir w\u00e4ren eine gute Mannschaft und m\u00fcssten einfach auftauchen, um die T\u00fcrkei zu schlagen\u201d, sagte Edina Mark\u00f3 im Anschluss an das Spiel \u201cWir waren mental nicht vorbereitet und daf\u00fcr \u00fcbernehme ich die volle VerantwortungWir waren lethargisch; wir konnten unseren Rhythmus nicht finden und zahlten den PreisWir h\u00e4tten uns vielleicht sp\u00e4ter verbessert und begonnen, das Spiel zu diktieren, aber wir waren arm vor dem TorWir waren nicht treffsicher genug, und unsere Entscheidungsfindung war hinf\u00e4llig; deshalb haben wir es nicht geschafft, den Ausgleich zu erzielenWir sind am Ende der Saison und die Spieler sind m\u00fcde; diejenigen, die uns wieder ins Spiel h\u00e4tten schleppen k\u00f6nnen, sind leer gelaufen\u201d, f\u00fcgte sie hinzu.<\/p>\n<p><strong>T\u00fcrkei 2-1 Ungarn (2-1) <\/strong><\/p>\n<p><em>Ungarn: R\u00e9ka Sz cs \u2013 Evelin Mosd\u00f3czi, Szabina T\u00e1losi, Vikt\u00f3ria Szab\u00f3, Gabriella T\u00f3th (Zsanett Kaj\u00e1n 70), Henrietta Csisz\u00e1r (Zs\u00f3fia R\u00e1cz 46), Fanny V\u00e1g\u00f3 (Petra Kocs\u00e1n 78), Zsanett Jakabfi, D\u00f3ra Zeller<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Edina Mark\u00f3s Team hat die T\u00fcrkei im vergangenen Herbst vielleicht bei der Groupama Ar\u00e9na geschlagen, aber sie musste jeden Zentimeter des Weges f\u00fcr die drei Punkte arbeiten. Da es der T\u00fcrkei bereits gelungen war, Russland zu Hause unentschieden zu halten, wurde das Spiel in Antalya als potenzielle Bananenschale f\u00fcr Ungarn angesehen, und es dauerte nicht [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":757632,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1219],"tags":[1218,1200],"class_list":["post-757631","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport","tag-fusball","tag-turkei"],"blocksy_meta":[],"acf":[],"author_username":"alk","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"","focus_keyword":"","canonical_url":"","robots":"","primary_category":"1219","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/757631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=757631"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/757631\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/757632"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=757631"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=757631"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=757631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}