{"id":764480,"date":"2015-10-09T12:19:51","date_gmt":"2015-10-09T10:19:51","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/ungarn-august-handelsbilanzuberschus-eur-459-m\/"},"modified":"2015-10-09T12:19:51","modified_gmt":"2015-10-09T10:19:51","slug":"ungarn-august-handelsbilanzuberschus-eur-459-m","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/ungarn-august-handelsbilanzuberschus-eur-459-m\/","title":{"rendered":"Ungarn August Handelsbilanz\u00fcberschu\u00df EUR 459 m\u00a0"},"content":{"rendered":"<p><strong>Budapest, 9. Oktober (MTI) \u201eUngarn verzeichnete im August einen Handels\u00fcberschuss von 459,2 Millionen Euro, basierend auf vorl\u00e4ufigen Daten, ein Anstieg von 25 Millionen gegen\u00fcber dem gleichen Monat ein Jahr zuvor, teilte das Statistische Zentralamt (KSH) am Freitag mit.<\/strong><\/p>\n<p>Die Exporte kletterten im Zeitraum um 6,2 Prozent auf 6,519 Milliarden Euro, auch die Importe stiegen um 6,2 Prozent, auf 6,060 Milliarden.<\/p>\n<p>Im Januar-August betrug der Handels\u00fcberschuss 5,311 Milliarden Euro und stieg damit um 1,214 Milliarden gegen\u00fcber dem Vorjahreszeitraum. Die Exporte wuchsen um 7,4 Prozent auf 59,386 Milliarden Euro und die Importe stiegen um 5,6 Prozent auf 54,076 Milliarden.<\/p>\n<p>Ganze 76 Prozent der Importe Ungarns kamen im August aus anderen L\u00e4ndern der Europ\u00e4ischen Union und 79 Prozent der Exporte gingen in EU-Mitgliedstaaten.<\/p>\n<p>Ein Beamter des Wirtschaftsministeriums sagte in einem Kommentar zu den Daten, dass die Handelsbilanz durch eine ausgewogenere Industrieproduktion unterst\u00fctzt worden sei, wodurch sich dem traditionell leistungsstarken Fahrzeugherstellungssektor st\u00e4rkere Pharma- und Lebensmittelindustriesektoren anschlossen. Zoltan Istvan Marczinko, stellvertretender Staatssekret\u00e4r, sagte dem Nachrichtensender M1 des \u00f6ffentlich-rechtlichen Fernsehens, dass es keine Anzeichen f\u00fcr eine Verlangsamung der ungarischen Industrie gebe und dass Investitionen, neue Unternehmen und neue Fabriken noch in diesem Jahr ins Spiel k\u00e4men.<\/p>\n<p>Der Analyst der Takarekbank, Gergely Suppan, sagte gegen\u00fcber MTI, dass die August-Daten nicht nur eine Verbesserung der Terms of Trade aufgrund sinkender \u00d6lpreise, sondern auch eine Beschleunigung des Exportwachstums zeigen. Ein schnelleres Exportwachstum sei teilweise auf einen Aufw\u00e4rtstrend in Westeuropa und teilweise auf inl\u00e4ndische Kapazit\u00e4tssteigerungen in der Automobilindustrie und anderen Sektoren zur\u00fcckzuf\u00fchren, f\u00fcgte er hinzu.<\/p>\n<p>Die Analysten der CIB Bank sagten, der Handels\u00fcberschuss im August sei niedriger als erwartet ausgefallen, aber immer noch betr\u00e4chtlich, und f\u00fcgten hinzu, dass der monatliche \u00dcberschuss im August 2014 auf einem \u00e4hnlichen Niveau lag.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Budapest, 9. Oktober (MTI) \u201eUngarn verzeichnete im August einen Handels\u00fcberschuss von 459,2 Millionen Euro, basierend auf vorl\u00e4ufigen Daten, ein Anstieg von 25 Millionen gegen\u00fcber dem gleichen Monat ein Jahr zuvor, teilte das Statistische Zentralamt (KSH) am Freitag mit. Die Exporte kletterten im Zeitraum um 6,2 Prozent auf 6,519 Milliarden Euro, auch die Importe stiegen um [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":764481,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1281],"tags":[1104],"class_list":["post-764480","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geschaft","tag-wirtschaft"],"blocksy_meta":[],"acf":[],"author_username":"alk","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"","focus_keyword":"","canonical_url":"","robots":"","primary_category":"1281","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/764480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=764480"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/764480\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/764481"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=764480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=764480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=764480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}