{"id":764797,"date":"2015-09-29T16:30:39","date_gmt":"2015-09-29T14:30:39","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/paks-upgrade-plane-im-einklang-mit-internationalen-standards-sagt-regierungskommissar\/"},"modified":"2015-09-29T16:30:39","modified_gmt":"2015-09-29T14:30:39","slug":"paks-upgrade-plane-im-einklang-mit-internationalen-standards-sagt-regierungskommissar","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/paks-upgrade-plane-im-einklang-mit-internationalen-standards-sagt-regierungskommissar\/","title":{"rendered":"Paks-Upgrade-Pl\u00e4ne im Einklang mit internationalen Standards, sagt Regierungskommissar"},"content":{"rendered":"<p><strong>Wien, 29. September (MTI) \u2013 Die Modernisierungspl\u00e4ne f\u00fcr das Kernkraftwerk Paks entsprechen ungarischen, europ\u00e4ischen und internationalen Standards und umfassen eine Reihe von Sicherheitssystemen, sagte Attila Aszodi, Regierungskommissar f\u00fcr das Projekt, in der Dienstagausgabe des \u00d6sterreichische Tageszeitung Die Presse.<\/strong><\/p>\n<p>Die Umweltvertr\u00e4glichkeitspr\u00fcfung des Projekts ber\u00fccksichtigte mehrere unwahrscheinliche, aber potenziell schwerwiegende Auswirkungen, die die Pflanze haben k\u00f6nnte, sagte Aszodi und f\u00fcgte hinzu, dass die Studie zur thermischen Verschmutzung der Donau ergeben habe, dass die Pflanze den Lebensraum des Flusses nicht gef\u00e4hrden werde.<\/p>\n<p>Auf eine Frage zur Sorge der \u00f6sterreichischen Regierung, dass in der N\u00e4he dieses Landes ein Atomkraftwerk russischen Typs gebaut werde, sagte der Kommissar, dass solche Aussagen \u201cf\u00fcr die \u00f6sterreichische Innenpolitik\u201d gemeint seien.<\/p>\n<p>Aszodi sagte, dass \u00f6sterreichische Beamte bei offiziellen Treffen nie solche Bedenken hinsichtlich der Modernisierung ge\u00e4u\u00dfert h\u00e4tten. Er sagte, es sei unbegr\u00fcndet zu behaupten, dass bei der Umweltvertr\u00e4glichkeitspr\u00fcfung die M\u00f6glichkeit nicht ber\u00fccksichtigt worden sei, dass die Anlage radioaktives Material in das \u00f6sterreichische Hoheitsgebiet emittiert.<\/p>\n<p>Auf die Frage, warum Ungarn vom Ziel der EU abweicht, seine Abh\u00e4ngigkeit von russischer Energie zu verringern, stellte Aszodi fest, dass auch \u00f6sterreichische und deutsche Unternehmen mit Russland zusammenarbeiten und dass Russlands staatlicher Atomenergiekonzern Rosatom einen Anteil von 34 Prozent an dem neuen Atomkraftwerk hat, das in Finnland gebaut werden soll.<\/p>\n<p>Aszodi sagte, Ungarn ben\u00f6tige Atomkraft zur Stromerzeugung, da es im Gegensatz zu \u00d6sterreich keinen Zugang zu einer ausreichenden Menge Wasserkraft habe, und wies darauf hin, dass Ungarn immer noch einen gro\u00dfen Teil seines Stroms importieren m\u00fcsse.<\/p>\n<p>Aszodi sagte, die Anlage werde im Einklang mit den Marktpraktiken und ohne illegale staatliche Beihilfen betrieben. Er sagte, die Europ\u00e4ische Kommission habe dem Deal zwischen Ungarn und Russland \u00fcber das Projekt zugestimmt. Russland werde Subunternehmer in den Bau einbeziehen. Die Ausschreibung werde bald angerufen, wobei Unternehmen wie Alstom, Siemens und Rolls-Royce alle Interesse bekundeten, sagte er.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wien, 29. September (MTI) \u2013 Die Modernisierungspl\u00e4ne f\u00fcr das Kernkraftwerk Paks entsprechen ungarischen, europ\u00e4ischen und internationalen Standards und umfassen eine Reihe von Sicherheitssystemen, sagte Attila Aszodi, Regierungskommissar f\u00fcr das Projekt, in der Dienstagausgabe des \u00d6sterreichische Tageszeitung Die Presse. Die Umweltvertr\u00e4glichkeitspr\u00fcfung des Projekts ber\u00fccksichtigte mehrere unwahrscheinliche, aber potenziell schwerwiegende Auswirkungen, die die Pflanze haben k\u00f6nnte, sagte [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":764798,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1281],"tags":[1312,1129,1474,1209],"class_list":["post-764797","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geschaft","tag-energie","tag-osterreich","tag-pak-projekt","tag-russland"],"blocksy_meta":[],"acf":[],"author_username":"alk","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"","focus_keyword":"","canonical_url":"","robots":"","primary_category":"1281","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/764797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=764797"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/764797\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/764798"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=764797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=764797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=764797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}