{"id":766237,"date":"2015-08-12T06:04:50","date_gmt":"2015-08-12T04:04:50","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/opposition-schlagt-gegen-cbank-wegen-neuen-villenkaufs-ein\/"},"modified":"2015-08-12T06:04:50","modified_gmt":"2015-08-12T04:04:50","slug":"opposition-schlagt-gegen-cbank-wegen-neuen-villenkaufs-ein","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/opposition-schlagt-gegen-cbank-wegen-neuen-villenkaufs-ein\/","title":{"rendered":"Opposition schl\u00e4gt gegen cbank wegen neuen Villenkaufs ein"},"content":{"rendered":"<p><strong>Budapest (MTI) \u2013 Oppositionsparteien kritisierten am Dienstag die Immobilienk\u00e4ufe der Zentralbank, nachdem Presseberichte neue Details einer im Februar gekauften Luxusvilla enth\u00fcllten.<\/strong><\/p>\n<p>Die Tageszeitung Magyar Nemzet berichtete am Dienstag, dass die Pallas Athene-Stiftung der Ungarischen Nationalbank (NBH) ein 2.165 Quadratmeter gro\u00dfes Grundst\u00fcck auf einem H\u00fcgel im gr\u00fcnen 12. Bezirk Budapests f\u00fcr 1,3 Milliarden Forint (4,17 Mio. EUR) von einem auf den Jungferninseln registrierten Unternehmen gekauft habe Die Zentralbank lehnte die Bitte der Zeitung um Stellungnahme mit der Begr\u00fcndung ab, dass ihre Stiftungen unabh\u00e4ngig voneinander operierten.<\/p>\n<p>Pallas Athene sagte, das Geb\u00e4ude werde ein Forschungs- und Ausbildungszentrum beherbergen und der Kaufpreis liege laut einer unabh\u00e4ngigen Bewertung unter dem Marktpreis. Die Stiftung habe au\u00dferdem eine 795 Millionen Forint teure Villa im Budaer Schloss gekauft, wo sie ihren Hauptsitz errichten wolle, hie\u00df es in einer an das Papier gesendeten Erkl\u00e4rung.<\/p>\n<p>Istvan Tukacs, ein Abgeordneter der sozialistischen Opposition, sagte, der Gouverneur der Zentralbank Gyorgy Matolcsy solle sofort zur\u00fccktreten, um \u201cweiteren sparsamen Ausgaben\u201d ein Ende zu setzen.<\/p>\n<p>Der stellvertretende Vorsitzende des radikalen Nationalisten Jobbik, Janos Volner, sagte, die Partei halte den Kauf von Luxusvillen aus Steuergeldern f\u00fcr inakzeptabel.<\/p>\n<p>Erzsebet Schmuck, eine Abgeordnete der oppositionellen LMP, sagte, die Regierung sei weit davon entfernt, sicherzustellen, dass Steuergelder nicht in Offshore-Unternehmen landen. Genau aus diesem Grund h\u00e4tten die Regierungsparteien die pr\u00e4ventiven Vorschl\u00e4ge der LMP zu diesem Thema dreimal abgelehnt.<\/p>\n<p>Die linke Opposition Democratic Coalition (DK) forderte von der Zentralbank, offenzulegen, wer hinter der Offshore-Gesellschaft steckt, die von so lukrativen Steuergeldern f\u00fcr Kaufausgaben profitiert hat. W\u00e4hrend Schulen und Krankenh\u00e4usern die Mittel fehlen, um Rechnungen zu bezahlen oder eine Klimaanlage zu installieren, gibt Matolcsy immer noch Milliarden aus, ohne zu z\u00e4hlen, sagte die Partei in einer Erkl\u00e4rung.<\/p>\n<p>Egyutt-Vizechef Levente Papa forderte Matolcsy auf, die unvorsichtigen Ausgaben einzustellen, und forderte, dass der Aufsichtsratschef der NBH den Kauf umgehend untersuchen solle.<\/p>\n<p>Die Ungarische Liberale Partei sagte, \u201cMatolcsy und Unternehmen begingen Seriendiebstahl auf Kosten der Steuerzahler\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Budapest (MTI) \u2013 Oppositionsparteien kritisierten am Dienstag die Immobilienk\u00e4ufe der Zentralbank, nachdem Presseberichte neue Details einer im Februar gekauften Luxusvilla enth\u00fcllten. Die Tageszeitung Magyar Nemzet berichtete am Dienstag, dass die Pallas Athene-Stiftung der Ungarischen Nationalbank (NBH) ein 2.165 Quadratmeter gro\u00dfes Grundst\u00fcck auf einem H\u00fcgel im gr\u00fcnen 12. Bezirk Budapests f\u00fcr 1,3 Milliarden Forint (4,17 Mio. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":766238,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1281],"tags":[1256,1104],"class_list":["post-766237","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geschaft","tag-nationalbank-von-ungarn","tag-wirtschaft"],"blocksy_meta":[],"acf":[],"author_username":"alk","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"","focus_keyword":"","canonical_url":"","robots":"","primary_category":"1281","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/766237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=766237"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/766237\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/766238"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=766237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=766237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=766237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}