{"id":766818,"date":"2015-07-13T04:25:56","date_gmt":"2015-07-13T02:25:56","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/ungarn-erhalt-beobachterstatus-in-der-pazifischen-ozeanallianz\/"},"modified":"2015-07-13T04:25:56","modified_gmt":"2015-07-13T02:25:56","slug":"ungarn-erhalt-beobachterstatus-in-der-pazifischen-ozeanallianz","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/ungarn-erhalt-beobachterstatus-in-der-pazifischen-ozeanallianz\/","title":{"rendered":"Ungarn erh\u00e4lt Beobachterstatus in der Pazifischen Ozeanallianz"},"content":{"rendered":"<p><strong>Budapest (MTI) \u201eUngarn hat Beobachterstatus bei der Pacific Ocean Alliance gewonnen, teilte das Au\u00dfenministerium am Sonntag in einer Erkl\u00e4rung mit und f\u00fcgte hinzu, dass dies das erste gro\u00dfe diplomatische Ergebnis seiner Politik der \u00d6ffnung des S\u00fcdens sei.<\/strong><\/p>\n<p>Das Ministerium habe im April seinen offiziellen Antrag gestellt, hei\u00dft es in der Erkl\u00e4rungDie Entscheidung wurde Anfang Juli von den vier Staats &#8211; und Regierungschefs der Allianz (Chile, Kolumbien, Mexiko, und Peru) getroffen.<\/p>\n<p>Ungarn werde sich an der Arbeit des B\u00fcndnisses in den Bereichen Wassermanagement, Unterst\u00fctzung kleiner und mittlerer Unternehmen, Stipendienprogramm namens Stipendium Hungaricum und Bildung beteiligen, teilte das Ministerium mit.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Budapest (MTI) \u201eUngarn hat Beobachterstatus bei der Pacific Ocean Alliance gewonnen, teilte das Au\u00dfenministerium am Sonntag in einer Erkl\u00e4rung mit und f\u00fcgte hinzu, dass dies das erste gro\u00dfe diplomatische Ergebnis seiner Politik der \u00d6ffnung des S\u00fcdens sei. Das Ministerium habe im April seinen offiziellen Antrag gestellt, hei\u00dft es in der Erkl\u00e4rungDie Entscheidung wurde Anfang Juli [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":766819,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1281],"tags":[1066],"class_list":["post-766818","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geschaft","tag-hungary"],"blocksy_meta":[],"acf":[],"author_username":"alk","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"","focus_keyword":"","canonical_url":"","robots":"","primary_category":"1281","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/766818","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=766818"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/766818\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/766819"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=766818"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=766818"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=766818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}