{"id":767100,"date":"2015-06-30T17:30:53","date_gmt":"2015-06-30T15:30:53","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/fidesz-ungarn-hat-die-zweitniedrigsten-gaspreise-in-der-eu\/"},"modified":"2015-06-30T17:30:53","modified_gmt":"2015-06-30T15:30:53","slug":"fidesz-ungarn-hat-die-zweitniedrigsten-gaspreise-in-der-eu","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/fidesz-ungarn-hat-die-zweitniedrigsten-gaspreise-in-der-eu\/","title":{"rendered":"FIDESZ: Ungarn hat die zweitniedrigsten Gaspreise in der EU"},"content":{"rendered":"<p><strong>Budapest, 30. Juni (MTI) \u2013 Dank der von der Regierung angeordneten Senkungen der Versorgungsgeb\u00fchren hat Ungarn den zweitniedrigsten Erdgaspreis in der Europ\u00e4ischen Union, basierend auf der Kaufkraftparit\u00e4t (KKP), sagte der Fidesz-Abgeordnete Szilard Nemeth auf einer Pressekonferenz in Budapest Dienstag.<\/strong><\/p>\n<p>W\u00e4hrend Ungarn im Jahr 2010 das Land war, in dem die Verbraucher in der EU am meisten f\u00fcr Gas bezahlen mussten, gibt es nur noch in Rum\u00e4nien niedrigere Gaspreise, basierend auf den KKP-Wechselkursen, sagte er.<\/p>\n<p>Nemeth sagte, die Entwicklung des Strompreises sei \u00e4hnlich, nur Bulgarien habe heute niedrigere Preise.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Budapest, 30. Juni (MTI) \u2013 Dank der von der Regierung angeordneten Senkungen der Versorgungsgeb\u00fchren hat Ungarn den zweitniedrigsten Erdgaspreis in der Europ\u00e4ischen Union, basierend auf der Kaufkraftparit\u00e4t (KKP), sagte der Fidesz-Abgeordnete Szilard Nemeth auf einer Pressekonferenz in Budapest Dienstag. W\u00e4hrend Ungarn im Jahr 2010 das Land war, in dem die Verbraucher in der EU am [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":767101,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1281],"tags":[1312,1091],"class_list":["post-767100","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geschaft","tag-energie","tag-fidesz"],"blocksy_meta":[],"acf":[],"author_username":"alk","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"","focus_keyword":"","canonical_url":"","robots":"","primary_category":"1281","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/767100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=767100"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/767100\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/767101"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=767100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=767100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=767100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}